{"id":13583,"date":"2024-10-11T11:03:23","date_gmt":"2024-10-11T16:03:23","guid":{"rendered":"https:\/\/prensapaisa.com\/?p=13583"},"modified":"2024-10-11T11:03:25","modified_gmt":"2024-10-11T16:03:25","slug":"joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno","status":"publish","type":"post","link":"https:\/\/prensapaisa.com\/index.php\/2024\/10\/11\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\/","title":{"rendered":"Joven se fue para una cita con una mujer y lo asesinaron en el Urab\u00e1 antioque\u00f1o"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/prensapaisa.com\/?fbclid=IwZXh0bgNhZW0CMTAAAR2DcgxmIxPmIo7w18YNVqtTaxPBuoTjcPPOBp1dUGSWolzRi6caPGwIzjw_aem_SIQzLVlG0CISr2oeDY0qLg\" rel=\"noreferrer noopener\" target=\"_blank\">Prensapaisa.com<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Familiares y amigos le hacen luto a Jhon Jarry, conocido con amor como &#8220;El Bocarri&#8221;, quien fue asesinado a tiros en el sector Uno de Villa Mar\u00eda, municipio de Turbo, Antioquia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a><\/a>Seg\u00fan versiones preliminares, el hombre, quien viv\u00eda en el barrio Las Flores fue citado por una chica y hab\u00eda pertenecido al grupo Los Pamperos del barrio El Bosque, fue emboscado por sus agresores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El chico, cuando fue a una supuesta cita, Le indicaron fue atacado con arma de fuego.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las autoridades investigan, paso a paso, los hechos y tratan de verificar las causas del crimen y rastrean a los pistoleros mediante c\u00e1maras de seguridad.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"953\" src=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/10\/461996940_568660025728989_3525498105554796243_n-1024x953.jpg\" alt=\"\" class=\"wp-image-13584\" srcset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/10\/461996940_568660025728989_3525498105554796243_n-1024x953.jpg 1024w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/10\/461996940_568660025728989_3525498105554796243_n-300x279.jpg 300w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/10\/461996940_568660025728989_3525498105554796243_n-768x714.jpg 768w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/10\/461996940_568660025728989_3525498105554796243_n-1170x1088.jpg 1170w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/10\/461996940_568660025728989_3525498105554796243_n-585x544.jpg 585w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/10\/461996940_568660025728989_3525498105554796243_n.jpg 1290w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Prensapaisa.com Familiares y amigos le hacen luto a Jhon Jarry, conocido con amor como &#8220;El Bocarri&#8221;, quien fue asesinado a tiros en el sector Uno de Villa Mar\u00eda, municipio de&hellip;<\/p>\n","protected":false},"author":1,"featured_media":13584,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43,1,47,46],"tags":[],"class_list":["post-13583","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fallecidos","category-noticias","category-orden-publico","category-redes-sociales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Joven se fue para una cita con una mujer y lo asesinaron en el Urab\u00e1 antioque\u00f1o - PRENSA PAISA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prensapaisa.com\/index.php\/2024\/10\/11\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Joven se fue para una cita con una mujer y lo asesinaron en el Urab\u00e1 antioque\u00f1o - PRENSA PAISA\" \/>\n<meta property=\"og:description\" content=\"Prensapaisa.com Familiares y amigos le hacen luto a Jhon Jarry, conocido con amor como &#8220;El Bocarri&#8221;, quien fue asesinado a tiros en el sector Uno de Villa Mar\u00eda, municipio de&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prensapaisa.com\/index.php\/2024\/10\/11\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\/\" \/>\n<meta property=\"og:site_name\" content=\"PRENSA PAISA\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-11T16:03:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-11T16:03:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/10\/461996940_568660025728989_3525498105554796243_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1290\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"noticias@prensapaisa.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"noticias@prensapaisa.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/10\\\/11\\\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/10\\\/11\\\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\\\/\"},\"author\":{\"name\":\"noticias@prensapaisa.com\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#\\\/schema\\\/person\\\/c5899b8b285dbcd70faec88a7c1579f6\"},\"headline\":\"Joven se fue para una cita con una mujer y lo asesinaron en el Urab\u00e1 antioque\u00f1o\",\"datePublished\":\"2024-10-11T16:03:23+00:00\",\"dateModified\":\"2024-10-11T16:03:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/10\\\/11\\\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\\\/\"},\"wordCount\":129,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/10\\\/11\\\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prensapaisa.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/461996940_568660025728989_3525498105554796243_n.jpg\",\"articleSection\":[\"Fallecidos\",\"Noticias\",\"Orden Publico\",\"Redes Sociales\"],\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/10\\\/11\\\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/10\\\/11\\\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\\\/\",\"url\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/10\\\/11\\\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\\\/\",\"name\":\"Joven se fue para una cita con una mujer y lo asesinaron en el Urab\u00e1 antioque\u00f1o - PRENSA PAISA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/10\\\/11\\\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/10\\\/11\\\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prensapaisa.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/461996940_568660025728989_3525498105554796243_n.jpg\",\"datePublished\":\"2024-10-11T16:03:23+00:00\",\"dateModified\":\"2024-10-11T16:03:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/10\\\/11\\\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/10\\\/11\\\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/10\\\/11\\\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/prensapaisa.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/461996940_568660025728989_3525498105554796243_n.jpg\",\"contentUrl\":\"https:\\\/\\\/prensapaisa.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/461996940_568660025728989_3525498105554796243_n.jpg\",\"width\":1290,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/10\\\/11\\\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/prensapaisa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Joven se fue para una cita con una mujer y lo asesinaron en el Urab\u00e1 antioque\u00f1o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#website\",\"url\":\"https:\\\/\\\/prensapaisa.com\\\/\",\"name\":\"PRENSA PAISA\",\"description\":\"Prensa Paisa la Original | Noticias de Medell\u00edn, Antioquia\",\"publisher\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prensapaisa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#organization\",\"name\":\"PRENSA PAISA\",\"url\":\"https:\\\/\\\/prensapaisa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/prensapaisa.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/cropped-cropped-prensa.png\",\"contentUrl\":\"https:\\\/\\\/prensapaisa.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/cropped-cropped-prensa.png\",\"width\":784,\"height\":524,\"caption\":\"PRENSA PAISA\"},\"image\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#\\\/schema\\\/person\\\/c5899b8b285dbcd70faec88a7c1579f6\",\"name\":\"noticias@prensapaisa.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca2b49c1df14b84557c567431f045ea69c8ea5da2da50309fd4de9b811da0433?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca2b49c1df14b84557c567431f045ea69c8ea5da2da50309fd4de9b811da0433?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca2b49c1df14b84557c567431f045ea69c8ea5da2da50309fd4de9b811da0433?s=96&d=mm&r=g\",\"caption\":\"noticias@prensapaisa.com\"},\"sameAs\":[\"http:\\\/\\\/prensapaisa.com\"],\"url\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/author\\\/prensapaisagmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Joven se fue para una cita con una mujer y lo asesinaron en el Urab\u00e1 antioque\u00f1o - PRENSA PAISA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prensapaisa.com\/index.php\/2024\/10\/11\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\/","og_locale":"es_ES","og_type":"article","og_title":"Joven se fue para una cita con una mujer y lo asesinaron en el Urab\u00e1 antioque\u00f1o - PRENSA PAISA","og_description":"Prensapaisa.com Familiares y amigos le hacen luto a Jhon Jarry, conocido con amor como &#8220;El Bocarri&#8221;, quien fue asesinado a tiros en el sector Uno de Villa Mar\u00eda, municipio de&hellip;","og_url":"https:\/\/prensapaisa.com\/index.php\/2024\/10\/11\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\/","og_site_name":"PRENSA PAISA","article_published_time":"2024-10-11T16:03:23+00:00","article_modified_time":"2024-10-11T16:03:25+00:00","og_image":[{"width":1290,"height":1200,"url":"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/10\/461996940_568660025728989_3525498105554796243_n.jpg","type":"image\/jpeg"}],"author":"noticias@prensapaisa.com","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"noticias@prensapaisa.com","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prensapaisa.com\/index.php\/2024\/10\/11\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\/#article","isPartOf":{"@id":"https:\/\/prensapaisa.com\/index.php\/2024\/10\/11\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\/"},"author":{"name":"noticias@prensapaisa.com","@id":"https:\/\/prensapaisa.com\/#\/schema\/person\/c5899b8b285dbcd70faec88a7c1579f6"},"headline":"Joven se fue para una cita con una mujer y lo asesinaron en el Urab\u00e1 antioque\u00f1o","datePublished":"2024-10-11T16:03:23+00:00","dateModified":"2024-10-11T16:03:25+00:00","mainEntityOfPage":{"@id":"https:\/\/prensapaisa.com\/index.php\/2024\/10\/11\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\/"},"wordCount":129,"commentCount":0,"publisher":{"@id":"https:\/\/prensapaisa.com\/#organization"},"image":{"@id":"https:\/\/prensapaisa.com\/index.php\/2024\/10\/11\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\/#primaryimage"},"thumbnailUrl":"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/10\/461996940_568660025728989_3525498105554796243_n.jpg","articleSection":["Fallecidos","Noticias","Orden Publico","Redes Sociales"],"inLanguage":"es-CO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prensapaisa.com\/index.php\/2024\/10\/11\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prensapaisa.com\/index.php\/2024\/10\/11\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\/","url":"https:\/\/prensapaisa.com\/index.php\/2024\/10\/11\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\/","name":"Joven se fue para una cita con una mujer y lo asesinaron en el Urab\u00e1 antioque\u00f1o - PRENSA PAISA","isPartOf":{"@id":"https:\/\/prensapaisa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prensapaisa.com\/index.php\/2024\/10\/11\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\/#primaryimage"},"image":{"@id":"https:\/\/prensapaisa.com\/index.php\/2024\/10\/11\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\/#primaryimage"},"thumbnailUrl":"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/10\/461996940_568660025728989_3525498105554796243_n.jpg","datePublished":"2024-10-11T16:03:23+00:00","dateModified":"2024-10-11T16:03:25+00:00","breadcrumb":{"@id":"https:\/\/prensapaisa.com\/index.php\/2024\/10\/11\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prensapaisa.com\/index.php\/2024\/10\/11\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/prensapaisa.com\/index.php\/2024\/10\/11\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\/#primaryimage","url":"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/10\/461996940_568660025728989_3525498105554796243_n.jpg","contentUrl":"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/10\/461996940_568660025728989_3525498105554796243_n.jpg","width":1290,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/prensapaisa.com\/index.php\/2024\/10\/11\/joven-se-fue-para-una-cita-con-una-mujer-y-lo-asesinaron-en-el-uraba-antioqueno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/prensapaisa.com\/"},{"@type":"ListItem","position":2,"name":"Joven se fue para una cita con una mujer y lo asesinaron en el Urab\u00e1 antioque\u00f1o"}]},{"@type":"WebSite","@id":"https:\/\/prensapaisa.com\/#website","url":"https:\/\/prensapaisa.com\/","name":"PRENSA PAISA","description":"Prensa Paisa la Original | Noticias de Medell\u00edn, Antioquia","publisher":{"@id":"https:\/\/prensapaisa.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prensapaisa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/prensapaisa.com\/#organization","name":"PRENSA PAISA","url":"https:\/\/prensapaisa.com\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/prensapaisa.com\/#\/schema\/logo\/image\/","url":"https:\/\/prensapaisa.com\/wp-content\/uploads\/2022\/05\/cropped-cropped-prensa.png","contentUrl":"https:\/\/prensapaisa.com\/wp-content\/uploads\/2022\/05\/cropped-cropped-prensa.png","width":784,"height":524,"caption":"PRENSA PAISA"},"image":{"@id":"https:\/\/prensapaisa.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/prensapaisa.com\/#\/schema\/person\/c5899b8b285dbcd70faec88a7c1579f6","name":"noticias@prensapaisa.com","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/secure.gravatar.com\/avatar\/ca2b49c1df14b84557c567431f045ea69c8ea5da2da50309fd4de9b811da0433?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ca2b49c1df14b84557c567431f045ea69c8ea5da2da50309fd4de9b811da0433?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca2b49c1df14b84557c567431f045ea69c8ea5da2da50309fd4de9b811da0433?s=96&d=mm&r=g","caption":"noticias@prensapaisa.com"},"sameAs":["http:\/\/prensapaisa.com"],"url":"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/posts\/13583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/comments?post=13583"}],"version-history":[{"count":1,"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/posts\/13583\/revisions"}],"predecessor-version":[{"id":13585,"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/posts\/13583\/revisions\/13585"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/media\/13584"}],"wp:attachment":[{"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/media?parent=13583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/categories?post=13583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/tags?post=13583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}