{"id":11969,"date":"2024-01-29T23:42:52","date_gmt":"2024-01-30T04:42:52","guid":{"rendered":"https:\/\/prensapaisa.com\/?p=11969"},"modified":"2024-01-29T23:44:00","modified_gmt":"2024-01-30T04:44:00","slug":"princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero","status":"publish","type":"post","link":"https:\/\/prensapaisa.com\/index.php\/2024\/01\/29\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\/","title":{"rendered":"Princesa Paisa se fue a decorar una casa y dej\u00f3 hospitalizado a un extranjero"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Un hombre agreg\u00f3 a una \u201cprincesa paisa\u201d por redes sociales mediante una aplicaci\u00f3n de C\u00fapido y la invit\u00f3 a su casa para que se conocieran y le organizara la sala para el cumplea\u00f1os de su hija. Cuando se conocieron, la mujer fue un amor, pues se tomaron varias copas de licor en una exclusiva y famosa zona de Medell\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El <a><\/a>hombre estaba muy \u201ccontentico\u201d porque hab\u00eda conquistado a linda dama, en Medell\u00edn, se tom\u00f3 varios energizantes, compr\u00f3 los preservativos y se la llev\u00f3 hasta su castillo con una sonrisa de oreja a oreja.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al llegar al lugar, m\u00e1s esperado por ambas partes, subieron las escaleras, siguieron la fiesta, bailaron y bebieron hasta que la mujer le aplic\u00f3 a la copa de su pretendiente una peque\u00f1a dosis de escopolamina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La v\u00edctima solo recuerda que la mujer toc\u00f3 una baldosa con un tac\u00f3n, se abri\u00f3 una puerta y de un momento a otro les cambi\u00f3 su mirada, pues ten\u00edan las cejas pintadas como las princesas malas de los cuentos de los Hermanos Grimm.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al ver que el mexicano cerr\u00f3 los ojos, como para dormir dos d\u00edas seguidos, comenz\u00f3 a desfalcar sus tarjetas. Se le llev\u00f3 joyas, un dron, objetos de valor y m\u00e1s de 30 millones de pesos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las chica, con cara de \u00e1ngel, pidi\u00f3 un carro y sali\u00f3, con un bolso en su espalda y una bolsa, donde ten\u00eda los objetos de valor, cadenas de oro y dinero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La v\u00edctimas no s\u00f3lo tuvo p\u00e9rdidas millonarias, tambi\u00e9n qued\u00f3 grave de salud, fue hospitalizado por un mes y qued\u00f3 medicado de por vida debido al efecto que le caus\u00f3 la sobredosis de droga.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta no es la primera vez que estas chicas aparecen en <a href=\"https:\/\/prensapaisa.com\/?fbclid=IwAR1wVHozU8P7JZg9Qk6hAfSFs56_iCCmf2ahQB6LH0Ff0GFCPtL-J3k1VTE\" rel=\"noreferrer noopener\" target=\"_blank\">Prensapaisa.com.<\/a> En varias oportunidades los extranjeros las buscan, por cielo y tierra, para que les devuelvan sus documentos y poder salir de la ciudad para regresar a su pa\u00eds natal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si usted conoce a esta chica, por favor, informar a las autoridades o comunicarse con Prensa Paisa. \u00a1Hay recompensa!<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"376\" height=\"1024\" src=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/424554303_412706494657677_1321510613731371771_n-376x1024.jpg\" alt=\"\" class=\"wp-image-11970\" srcset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/424554303_412706494657677_1321510613731371771_n-376x1024.jpg 376w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/424554303_412706494657677_1321510613731371771_n-110x300.jpg 110w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/424554303_412706494657677_1321510613731371771_n-585x1595.jpg 585w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/424554303_412706494657677_1321510613731371771_n.jpg 640w\" sizes=\"(max-width: 376px) 100vw, 376px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"680\" height=\"1024\" src=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/424554306_412707007990959_1684940730752269667_n-680x1024.jpg\" alt=\"\" class=\"wp-image-11971\" srcset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/424554306_412707007990959_1684940730752269667_n-680x1024.jpg 680w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/424554306_412707007990959_1684940730752269667_n-199x300.jpg 199w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/424554306_412707007990959_1684940730752269667_n-768x1157.jpg 768w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/424554306_412707007990959_1684940730752269667_n-1019x1536.jpg 1019w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/424554306_412707007990959_1684940730752269667_n-1170x1763.jpg 1170w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/424554306_412707007990959_1684940730752269667_n-585x882.jpg 585w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/424554306_412707007990959_1684940730752269667_n.jpg 1290w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"146\" height=\"239\" src=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/SS.png\" alt=\"\" class=\"wp-image-11972\" style=\"width:842px;height:auto\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/423248523_412707214657605_1320975784742478711_n-1-1024x1024.jpg\" alt=\"\" class=\"wp-image-11974\" srcset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/423248523_412707214657605_1320975784742478711_n-1-1024x1024.jpg 1024w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/423248523_412707214657605_1320975784742478711_n-1-300x300.jpg 300w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/423248523_412707214657605_1320975784742478711_n-1-150x150.jpg 150w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/423248523_412707214657605_1320975784742478711_n-1-768x768.jpg 768w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/423248523_412707214657605_1320975784742478711_n-1-1536x1536.jpg 1536w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/423248523_412707214657605_1320975784742478711_n-1-1170x1170.jpg 1170w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/423248523_412707214657605_1320975784742478711_n-1-585x585.jpg 585w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/423248523_412707214657605_1320975784742478711_n-1.jpg 1599w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Un hombre agreg\u00f3 a una \u201cprincesa paisa\u201d por redes sociales mediante una aplicaci\u00f3n de C\u00fapido y la invit\u00f3 a su casa para que se conocieran y le organizara la sala&hellip;<\/p>\n","protected":false},"author":1,"featured_media":11973,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11969","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Princesa Paisa se fue a decorar una casa y dej\u00f3 hospitalizado a un extranjero - PRENSA PAISA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prensapaisa.com\/index.php\/2024\/01\/29\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Princesa Paisa se fue a decorar una casa y dej\u00f3 hospitalizado a un extranjero - PRENSA PAISA\" \/>\n<meta property=\"og:description\" content=\"Un hombre agreg\u00f3 a una \u201cprincesa paisa\u201d por redes sociales mediante una aplicaci\u00f3n de C\u00fapido y la invit\u00f3 a su casa para que se conocieran y le organizara la sala&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prensapaisa.com\/index.php\/2024\/01\/29\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\/\" \/>\n<meta property=\"og:site_name\" content=\"PRENSA PAISA\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-30T04:42:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-30T04:44:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/423248523_412707214657605_1320975784742478711_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1599\" \/>\n\t<meta property=\"og:image:height\" content=\"1599\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"noticias@prensapaisa.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"noticias@prensapaisa.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/01\\\/29\\\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/01\\\/29\\\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\\\/\"},\"author\":{\"name\":\"noticias@prensapaisa.com\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#\\\/schema\\\/person\\\/c5899b8b285dbcd70faec88a7c1579f6\"},\"headline\":\"Princesa Paisa se fue a decorar una casa y dej\u00f3 hospitalizado a un extranjero\",\"datePublished\":\"2024-01-30T04:42:52+00:00\",\"dateModified\":\"2024-01-30T04:44:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/01\\\/29\\\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\\\/\"},\"wordCount\":363,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/01\\\/29\\\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prensapaisa.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/423248523_412707214657605_1320975784742478711_n.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/01\\\/29\\\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/01\\\/29\\\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\\\/\",\"url\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/01\\\/29\\\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\\\/\",\"name\":\"Princesa Paisa se fue a decorar una casa y dej\u00f3 hospitalizado a un extranjero - PRENSA PAISA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/01\\\/29\\\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/01\\\/29\\\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prensapaisa.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/423248523_412707214657605_1320975784742478711_n.jpg\",\"datePublished\":\"2024-01-30T04:42:52+00:00\",\"dateModified\":\"2024-01-30T04:44:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/01\\\/29\\\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/01\\\/29\\\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/01\\\/29\\\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/prensapaisa.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/423248523_412707214657605_1320975784742478711_n.jpg\",\"contentUrl\":\"https:\\\/\\\/prensapaisa.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/423248523_412707214657605_1320975784742478711_n.jpg\",\"width\":1599,\"height\":1599},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/01\\\/29\\\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/prensapaisa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Princesa Paisa se fue a decorar una casa y dej\u00f3 hospitalizado a un extranjero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#website\",\"url\":\"https:\\\/\\\/prensapaisa.com\\\/\",\"name\":\"PRENSA PAISA\",\"description\":\"Prensa Paisa la Original | Noticias de Medell\u00edn, Antioquia\",\"publisher\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prensapaisa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#organization\",\"name\":\"PRENSA PAISA\",\"url\":\"https:\\\/\\\/prensapaisa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/prensapaisa.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/cropped-cropped-prensa.png\",\"contentUrl\":\"https:\\\/\\\/prensapaisa.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/cropped-cropped-prensa.png\",\"width\":784,\"height\":524,\"caption\":\"PRENSA PAISA\"},\"image\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#\\\/schema\\\/person\\\/c5899b8b285dbcd70faec88a7c1579f6\",\"name\":\"noticias@prensapaisa.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca2b49c1df14b84557c567431f045ea69c8ea5da2da50309fd4de9b811da0433?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca2b49c1df14b84557c567431f045ea69c8ea5da2da50309fd4de9b811da0433?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca2b49c1df14b84557c567431f045ea69c8ea5da2da50309fd4de9b811da0433?s=96&d=mm&r=g\",\"caption\":\"noticias@prensapaisa.com\"},\"sameAs\":[\"http:\\\/\\\/prensapaisa.com\"],\"url\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/author\\\/prensapaisagmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Princesa Paisa se fue a decorar una casa y dej\u00f3 hospitalizado a un extranjero - PRENSA PAISA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prensapaisa.com\/index.php\/2024\/01\/29\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\/","og_locale":"es_ES","og_type":"article","og_title":"Princesa Paisa se fue a decorar una casa y dej\u00f3 hospitalizado a un extranjero - PRENSA PAISA","og_description":"Un hombre agreg\u00f3 a una \u201cprincesa paisa\u201d por redes sociales mediante una aplicaci\u00f3n de C\u00fapido y la invit\u00f3 a su casa para que se conocieran y le organizara la sala&hellip;","og_url":"https:\/\/prensapaisa.com\/index.php\/2024\/01\/29\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\/","og_site_name":"PRENSA PAISA","article_published_time":"2024-01-30T04:42:52+00:00","article_modified_time":"2024-01-30T04:44:00+00:00","og_image":[{"width":1599,"height":1599,"url":"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/423248523_412707214657605_1320975784742478711_n.jpg","type":"image\/jpeg"}],"author":"noticias@prensapaisa.com","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"noticias@prensapaisa.com","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prensapaisa.com\/index.php\/2024\/01\/29\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\/#article","isPartOf":{"@id":"https:\/\/prensapaisa.com\/index.php\/2024\/01\/29\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\/"},"author":{"name":"noticias@prensapaisa.com","@id":"https:\/\/prensapaisa.com\/#\/schema\/person\/c5899b8b285dbcd70faec88a7c1579f6"},"headline":"Princesa Paisa se fue a decorar una casa y dej\u00f3 hospitalizado a un extranjero","datePublished":"2024-01-30T04:42:52+00:00","dateModified":"2024-01-30T04:44:00+00:00","mainEntityOfPage":{"@id":"https:\/\/prensapaisa.com\/index.php\/2024\/01\/29\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\/"},"wordCount":363,"commentCount":0,"publisher":{"@id":"https:\/\/prensapaisa.com\/#organization"},"image":{"@id":"https:\/\/prensapaisa.com\/index.php\/2024\/01\/29\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\/#primaryimage"},"thumbnailUrl":"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/423248523_412707214657605_1320975784742478711_n.jpg","articleSection":["Noticias"],"inLanguage":"es-CO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prensapaisa.com\/index.php\/2024\/01\/29\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prensapaisa.com\/index.php\/2024\/01\/29\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\/","url":"https:\/\/prensapaisa.com\/index.php\/2024\/01\/29\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\/","name":"Princesa Paisa se fue a decorar una casa y dej\u00f3 hospitalizado a un extranjero - PRENSA PAISA","isPartOf":{"@id":"https:\/\/prensapaisa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prensapaisa.com\/index.php\/2024\/01\/29\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\/#primaryimage"},"image":{"@id":"https:\/\/prensapaisa.com\/index.php\/2024\/01\/29\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\/#primaryimage"},"thumbnailUrl":"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/423248523_412707214657605_1320975784742478711_n.jpg","datePublished":"2024-01-30T04:42:52+00:00","dateModified":"2024-01-30T04:44:00+00:00","breadcrumb":{"@id":"https:\/\/prensapaisa.com\/index.php\/2024\/01\/29\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prensapaisa.com\/index.php\/2024\/01\/29\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/prensapaisa.com\/index.php\/2024\/01\/29\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\/#primaryimage","url":"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/423248523_412707214657605_1320975784742478711_n.jpg","contentUrl":"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/423248523_412707214657605_1320975784742478711_n.jpg","width":1599,"height":1599},{"@type":"BreadcrumbList","@id":"https:\/\/prensapaisa.com\/index.php\/2024\/01\/29\/princesa-paisa-se-fue-a-decorar-una-casa-y-dejo-hospitalizado-a-un-extranjero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/prensapaisa.com\/"},{"@type":"ListItem","position":2,"name":"Princesa Paisa se fue a decorar una casa y dej\u00f3 hospitalizado a un extranjero"}]},{"@type":"WebSite","@id":"https:\/\/prensapaisa.com\/#website","url":"https:\/\/prensapaisa.com\/","name":"PRENSA PAISA","description":"Prensa Paisa la Original | Noticias de Medell\u00edn, Antioquia","publisher":{"@id":"https:\/\/prensapaisa.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prensapaisa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/prensapaisa.com\/#organization","name":"PRENSA PAISA","url":"https:\/\/prensapaisa.com\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/prensapaisa.com\/#\/schema\/logo\/image\/","url":"https:\/\/prensapaisa.com\/wp-content\/uploads\/2022\/05\/cropped-cropped-prensa.png","contentUrl":"https:\/\/prensapaisa.com\/wp-content\/uploads\/2022\/05\/cropped-cropped-prensa.png","width":784,"height":524,"caption":"PRENSA PAISA"},"image":{"@id":"https:\/\/prensapaisa.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/prensapaisa.com\/#\/schema\/person\/c5899b8b285dbcd70faec88a7c1579f6","name":"noticias@prensapaisa.com","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/secure.gravatar.com\/avatar\/ca2b49c1df14b84557c567431f045ea69c8ea5da2da50309fd4de9b811da0433?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ca2b49c1df14b84557c567431f045ea69c8ea5da2da50309fd4de9b811da0433?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca2b49c1df14b84557c567431f045ea69c8ea5da2da50309fd4de9b811da0433?s=96&d=mm&r=g","caption":"noticias@prensapaisa.com"},"sameAs":["http:\/\/prensapaisa.com"],"url":"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/posts\/11969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/comments?post=11969"}],"version-history":[{"count":1,"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/posts\/11969\/revisions"}],"predecessor-version":[{"id":11975,"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/posts\/11969\/revisions\/11975"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/media\/11973"}],"wp:attachment":[{"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/media?parent=11969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/categories?post=11969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/tags?post=11969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}