{"id":11794,"date":"2024-01-02T19:13:35","date_gmt":"2024-01-03T00:13:35","guid":{"rendered":"https:\/\/prensapaisa.com\/?p=11794"},"modified":"2024-01-02T19:23:02","modified_gmt":"2024-01-03T00:23:02","slug":"mujer-fue-asesinada-por-su-amado-en-la-comuna-1","status":"publish","type":"post","link":"https:\/\/prensapaisa.com\/index.php\/2024\/01\/02\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\/","title":{"rendered":"Mujer fue asesinada por su amado en la Comuna 1"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Familiares y amigos le hacen luto a. Ana Rosa Rodr\u00edguez, de 29 a\u00f1os, quien fue asesinada por su pareja durante amel amanecer del primero de enero en el barrio Santo Domingo de Medell\u00edn.<\/p>\n\n\n\n<p><a><\/a>Varias vecinas contaron que estaban en una celebraci\u00f3n familiar para recibir el A\u00f1o y la pareja discuti\u00f3 varias veces. Luego de unos minutos, el hombre le caus\u00f3 varias lesiones con un cuchillo y escap\u00f3 en una motocicleta.<\/p>\n\n\n\n<p>La mujer, oriunda de Venezuela, trabajaba en un restaurante y era madre de un ni\u00f1o de 9 a\u00f1os.<\/p>\n\n\n\n<p>La v\u00edctima fue trasladada hasta la Unidad Intermedia de Santa Cruz, pero se qued\u00f3 sin signos vitales.<\/p>\n\n\n\n<p>Las autoridades investigan, paso a paso, los hechos y tratan de verificar las versiones encontradas.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"615\" height=\"1024\" data-id=\"11798\" src=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/415933718_396656132929380_561548188423468276_n-615x1024.jpg\" alt=\"\" class=\"wp-image-11798\" srcset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/415933718_396656132929380_561548188423468276_n-615x1024.jpg 615w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/415933718_396656132929380_561548188423468276_n-180x300.jpg 180w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/415933718_396656132929380_561548188423468276_n-768x1279.jpg 768w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/415933718_396656132929380_561548188423468276_n-923x1536.jpg 923w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/415933718_396656132929380_561548188423468276_n-1170x1948.jpg 1170w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/415933718_396656132929380_561548188423468276_n-585x974.jpg 585w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/415933718_396656132929380_561548188423468276_n.jpg 1230w\" sizes=\"(max-width: 615px) 100vw, 615px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"767\" src=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/415947375_396656226262704_4849167334759751186_n-1-1024x767.jpg\" alt=\"\" class=\"wp-image-11799\" srcset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/415947375_396656226262704_4849167334759751186_n-1-1024x767.jpg 1024w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/415947375_396656226262704_4849167334759751186_n-1-300x225.jpg 300w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/415947375_396656226262704_4849167334759751186_n-1-768x575.jpg 768w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/415947375_396656226262704_4849167334759751186_n-1-1170x876.jpg 1170w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/415947375_396656226262704_4849167334759751186_n-1-585x438.jpg 585w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/415947375_396656226262704_4849167334759751186_n-1.jpg 1290w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"461\" height=\"1024\" src=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/415796145_396656656262661_1301620183069553830_n-1-461x1024.jpg\" alt=\"\" class=\"wp-image-11800\" srcset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/415796145_396656656262661_1301620183069553830_n-1-461x1024.jpg 461w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/415796145_396656656262661_1301620183069553830_n-1-135x300.jpg 135w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/415796145_396656656262661_1301620183069553830_n-1-768x1706.jpg 768w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/415796145_396656656262661_1301620183069553830_n-1-692x1536.jpg 692w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/415796145_396656656262661_1301620183069553830_n-1-922x2048.jpg 922w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/415796145_396656656262661_1301620183069553830_n-1-585x1299.jpg 585w, https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/415796145_396656656262661_1301620183069553830_n-1.jpg 1032w\" sizes=\"(max-width: 461px) 100vw, 461px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Familiares y amigos le hacen luto a. Ana Rosa Rodr\u00edguez, de 29 a\u00f1os, quien fue asesinada por su pareja durante amel amanecer del primero de enero en el barrio Santo&hellip;<\/p>\n","protected":false},"author":1,"featured_media":11802,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11794","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mujer fue asesinada por su amado en la Comuna 1 - PRENSA PAISA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prensapaisa.com\/index.php\/2024\/01\/02\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mujer fue asesinada por su amado en la Comuna 1 - PRENSA PAISA\" \/>\n<meta property=\"og:description\" content=\"Familiares y amigos le hacen luto a. Ana Rosa Rodr\u00edguez, de 29 a\u00f1os, quien fue asesinada por su pareja durante amel amanecer del primero de enero en el barrio Santo&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prensapaisa.com\/index.php\/2024\/01\/02\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\/\" \/>\n<meta property=\"og:site_name\" content=\"PRENSA PAISA\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-03T00:13:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-03T00:23:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/415796145_396656656262661_1301620183069553830_n-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1032\" \/>\n\t<meta property=\"og:image:height\" content=\"2292\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"noticias@prensapaisa.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"noticias@prensapaisa.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/01\\\/02\\\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/01\\\/02\\\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\\\/\"},\"author\":{\"name\":\"noticias@prensapaisa.com\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#\\\/schema\\\/person\\\/c5899b8b285dbcd70faec88a7c1579f6\"},\"headline\":\"Mujer fue asesinada por su amado en la Comuna 1\",\"datePublished\":\"2024-01-03T00:13:35+00:00\",\"dateModified\":\"2024-01-03T00:23:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/01\\\/02\\\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\\\/\"},\"wordCount\":135,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/01\\\/02\\\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prensapaisa.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/415796145_396656656262661_1301620183069553830_n-2.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/01\\\/02\\\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/01\\\/02\\\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\\\/\",\"url\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/01\\\/02\\\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\\\/\",\"name\":\"Mujer fue asesinada por su amado en la Comuna 1 - PRENSA PAISA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/01\\\/02\\\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/01\\\/02\\\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prensapaisa.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/415796145_396656656262661_1301620183069553830_n-2.jpg\",\"datePublished\":\"2024-01-03T00:13:35+00:00\",\"dateModified\":\"2024-01-03T00:23:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/01\\\/02\\\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/01\\\/02\\\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/01\\\/02\\\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/prensapaisa.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/415796145_396656656262661_1301620183069553830_n-2.jpg\",\"contentUrl\":\"https:\\\/\\\/prensapaisa.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/415796145_396656656262661_1301620183069553830_n-2.jpg\",\"width\":1032,\"height\":2292},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/2024\\\/01\\\/02\\\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/prensapaisa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mujer fue asesinada por su amado en la Comuna 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#website\",\"url\":\"https:\\\/\\\/prensapaisa.com\\\/\",\"name\":\"PRENSA PAISA\",\"description\":\"Prensa Paisa la Original | Noticias de Medell\u00edn, Antioquia\",\"publisher\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prensapaisa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#organization\",\"name\":\"PRENSA PAISA\",\"url\":\"https:\\\/\\\/prensapaisa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/prensapaisa.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/cropped-cropped-prensa.png\",\"contentUrl\":\"https:\\\/\\\/prensapaisa.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/cropped-cropped-prensa.png\",\"width\":784,\"height\":524,\"caption\":\"PRENSA PAISA\"},\"image\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#\\\/schema\\\/person\\\/c5899b8b285dbcd70faec88a7c1579f6\",\"name\":\"noticias@prensapaisa.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca2b49c1df14b84557c567431f045ea69c8ea5da2da50309fd4de9b811da0433?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca2b49c1df14b84557c567431f045ea69c8ea5da2da50309fd4de9b811da0433?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca2b49c1df14b84557c567431f045ea69c8ea5da2da50309fd4de9b811da0433?s=96&d=mm&r=g\",\"caption\":\"noticias@prensapaisa.com\"},\"sameAs\":[\"http:\\\/\\\/prensapaisa.com\"],\"url\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/author\\\/prensapaisagmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mujer fue asesinada por su amado en la Comuna 1 - PRENSA PAISA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prensapaisa.com\/index.php\/2024\/01\/02\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\/","og_locale":"es_ES","og_type":"article","og_title":"Mujer fue asesinada por su amado en la Comuna 1 - PRENSA PAISA","og_description":"Familiares y amigos le hacen luto a. Ana Rosa Rodr\u00edguez, de 29 a\u00f1os, quien fue asesinada por su pareja durante amel amanecer del primero de enero en el barrio Santo&hellip;","og_url":"https:\/\/prensapaisa.com\/index.php\/2024\/01\/02\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\/","og_site_name":"PRENSA PAISA","article_published_time":"2024-01-03T00:13:35+00:00","article_modified_time":"2024-01-03T00:23:02+00:00","og_image":[{"width":1032,"height":2292,"url":"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/415796145_396656656262661_1301620183069553830_n-2.jpg","type":"image\/jpeg"}],"author":"noticias@prensapaisa.com","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"noticias@prensapaisa.com","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prensapaisa.com\/index.php\/2024\/01\/02\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\/#article","isPartOf":{"@id":"https:\/\/prensapaisa.com\/index.php\/2024\/01\/02\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\/"},"author":{"name":"noticias@prensapaisa.com","@id":"https:\/\/prensapaisa.com\/#\/schema\/person\/c5899b8b285dbcd70faec88a7c1579f6"},"headline":"Mujer fue asesinada por su amado en la Comuna 1","datePublished":"2024-01-03T00:13:35+00:00","dateModified":"2024-01-03T00:23:02+00:00","mainEntityOfPage":{"@id":"https:\/\/prensapaisa.com\/index.php\/2024\/01\/02\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\/"},"wordCount":135,"commentCount":0,"publisher":{"@id":"https:\/\/prensapaisa.com\/#organization"},"image":{"@id":"https:\/\/prensapaisa.com\/index.php\/2024\/01\/02\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\/#primaryimage"},"thumbnailUrl":"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/415796145_396656656262661_1301620183069553830_n-2.jpg","articleSection":["Noticias"],"inLanguage":"es-CO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prensapaisa.com\/index.php\/2024\/01\/02\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prensapaisa.com\/index.php\/2024\/01\/02\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\/","url":"https:\/\/prensapaisa.com\/index.php\/2024\/01\/02\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\/","name":"Mujer fue asesinada por su amado en la Comuna 1 - PRENSA PAISA","isPartOf":{"@id":"https:\/\/prensapaisa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prensapaisa.com\/index.php\/2024\/01\/02\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\/#primaryimage"},"image":{"@id":"https:\/\/prensapaisa.com\/index.php\/2024\/01\/02\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\/#primaryimage"},"thumbnailUrl":"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/415796145_396656656262661_1301620183069553830_n-2.jpg","datePublished":"2024-01-03T00:13:35+00:00","dateModified":"2024-01-03T00:23:02+00:00","breadcrumb":{"@id":"https:\/\/prensapaisa.com\/index.php\/2024\/01\/02\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prensapaisa.com\/index.php\/2024\/01\/02\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/prensapaisa.com\/index.php\/2024\/01\/02\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\/#primaryimage","url":"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/415796145_396656656262661_1301620183069553830_n-2.jpg","contentUrl":"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/01\/415796145_396656656262661_1301620183069553830_n-2.jpg","width":1032,"height":2292},{"@type":"BreadcrumbList","@id":"https:\/\/prensapaisa.com\/index.php\/2024\/01\/02\/mujer-fue-asesinada-por-su-amado-en-la-comuna-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/prensapaisa.com\/"},{"@type":"ListItem","position":2,"name":"Mujer fue asesinada por su amado en la Comuna 1"}]},{"@type":"WebSite","@id":"https:\/\/prensapaisa.com\/#website","url":"https:\/\/prensapaisa.com\/","name":"PRENSA PAISA","description":"Prensa Paisa la Original | Noticias de Medell\u00edn, Antioquia","publisher":{"@id":"https:\/\/prensapaisa.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prensapaisa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/prensapaisa.com\/#organization","name":"PRENSA PAISA","url":"https:\/\/prensapaisa.com\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/prensapaisa.com\/#\/schema\/logo\/image\/","url":"https:\/\/prensapaisa.com\/wp-content\/uploads\/2022\/05\/cropped-cropped-prensa.png","contentUrl":"https:\/\/prensapaisa.com\/wp-content\/uploads\/2022\/05\/cropped-cropped-prensa.png","width":784,"height":524,"caption":"PRENSA PAISA"},"image":{"@id":"https:\/\/prensapaisa.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/prensapaisa.com\/#\/schema\/person\/c5899b8b285dbcd70faec88a7c1579f6","name":"noticias@prensapaisa.com","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/secure.gravatar.com\/avatar\/ca2b49c1df14b84557c567431f045ea69c8ea5da2da50309fd4de9b811da0433?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ca2b49c1df14b84557c567431f045ea69c8ea5da2da50309fd4de9b811da0433?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca2b49c1df14b84557c567431f045ea69c8ea5da2da50309fd4de9b811da0433?s=96&d=mm&r=g","caption":"noticias@prensapaisa.com"},"sameAs":["http:\/\/prensapaisa.com"],"url":"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/posts\/11794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/comments?post=11794"}],"version-history":[{"count":2,"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/posts\/11794\/revisions"}],"predecessor-version":[{"id":11801,"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/posts\/11794\/revisions\/11801"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/media\/11802"}],"wp:attachment":[{"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/media?parent=11794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/categories?post=11794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/tags?post=11794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}