{"id":3330,"date":"2021-09-30T04:25:56","date_gmt":"2021-09-30T04:25:56","guid":{"rendered":"https:\/\/soledaddemo.pencidesign.net\/?page_id=1203"},"modified":"2022-06-04T14:52:00","modified_gmt":"2022-06-04T19:52:00","slug":"home-with-one-sidebar","status":"publish","type":"page","link":"https:\/\/prensapaisa.com\/index.php\/home-with-one-sidebar\/","title":{"rendered":"Home With One Sidebar"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3330\" class=\"elementor elementor-3330\">\n\t\t\t\t\t\t<section class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-eef12f7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eef12f7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct  elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-53cfe97\" data-id=\"53cfe97\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c7095b9 elementor-widget elementor-widget-penci-news-ticker\" data-id=\"c7095b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"penci-news-ticker.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\r\n\t\t\t\t<div class=\"penci-enews-ticker penci-topbar-trending penci-enews-ticker-923\">\r\n\t\t\t\r\n\t\t\t\t\t\t\t<span class=\"headline-title nticker-style-2\">News Highlight<\/span>\r\n\t\t\t\t\t\t\t<span class=\"penci-trending-nav\">\r\n\t\t\t\t\t<a class=\"penci-slider-prev\" href=\"#\"><i class=\"penci-faicon fa fa-angle-left\" ><\/i><\/a>\r\n\t\t\t\t\t<a class=\"penci-slider-next\" href=\"#\"><i class=\"penci-faicon fa fa-angle-right\" ><\/i><\/a>\r\n\t\t\t\t<\/span>\r\n\t\t\t\t<div class=\"penci-owl-carousel penci-owl-carousel-slider penci-headline-posts\" data-auto=\"true\" data-nav=\"false\" data-autotime=\"3000\" data-speed=\"300\" data-anim=\"slideInUp\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div>\r\n\t\t\t\t\t\t\t<a class=\"penci-topbar-post-title\" href=\"https:\/\/prensapaisa.com\/index.php\/2022\/09\/01\/se-declara-calamidad-publica-en-antioquia-por-la-nueva-temporada-de-lluvias-que-inicia-en-septiembre\/\">Se declara calamidad p\u00fablica, en Antioquia, por la nueva temporada de lluvias que inicia en...<\/a>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div>\r\n\t\t\t\t\t\t\t<a class=\"penci-topbar-post-title\" href=\"https:\/\/prensapaisa.com\/index.php\/2025\/12\/13\/un-hombre-pidio-a-sus-vecinos-que-dejaran-de-quemar-polvora-y-lo-asesinaron\/\">Un hombre pidi\u00f3 a sus vecinos que dejaran de quemar p\u00f3lvora y lo asesinaron<\/a>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div>\r\n\t\t\t\t\t\t\t<a class=\"penci-topbar-post-title\" href=\"https:\/\/prensapaisa.com\/index.php\/2022\/09\/27\/se-fue-para-misa-y-no-regreso-en-el-norte-del-valle-de-aburra\/\">Se fue para misa y no regres\u00f3 en el Norte del Valle de Aburr\u00e1<\/a>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div>\r\n\t\t\t\t\t\t\t<a class=\"penci-topbar-post-title\" href=\"https:\/\/prensapaisa.com\/index.php\/2022\/03\/29\/alerta-en-el-aeropuerto-en-rionegro-antioquia\/\">Alerta en el aeropuerto en Rionegro, Antioquia<\/a>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div>\r\n\t\t\t\t\t\t\t<a class=\"penci-topbar-post-title\" href=\"https:\/\/prensapaisa.com\/index.php\/2026\/04\/04\/diluvio-en-manrique-medellin\/\">Diluvio en Manrique, Medell\u00edn<\/a>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div>\r\n\t\t\t\t\t\t\t<a class=\"penci-topbar-post-title\" href=\"https:\/\/prensapaisa.com\/index.php\/2022\/08\/31\/colombia-y-venezuela-se-unieron-nuevamente\/\">Colombia y Venezuela se unieron nuevamente<\/a>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfb8060 elementor-widget elementor-widget-penci-big-grid\" data-id=\"bfb8060\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"penci-big-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"penci-clearfix penci-biggrid-wrapper penci-bgrid-based-post penci-bgrid-style-5 pcbg-ficonpo-top-right pcbg-reiconpo-top-left penci-bgrid-content-on pencibg-imageh-zoom-in pencibg-texth-none pencibg-textani-movebottom pcbg-mask-subtitle pcbg-mask-title pcbg-mask-meta textop hide-mdesc\">\r\n\t\t\t            <div class=\"penci-clearfix penci-biggrid penci-bgstyle-5 penci-bgel\">\r\n                <div class=\"penci-biggrid-inner default\">\r\n\t\t\t\t\t<div class=\"penci-big-grid-ajax-data\"><div class=\"penci-clearfix penci-biggrid-data penci-dblock penci-fixh\"><div class=\"penci-bgitem pcbg-big-item bgitem-1\">\r\n    <div class=\"penci-bgitin\">\r\n        <div class=\"penci-bgmain\">\r\n            <div class=\"pcbg-thumb\">\r\n\t\t\t\t\t\t\t\t                <div class=\"pcbg-thumbin\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2022\/01\/20\/defensor-de-derechos-humanos-fue-hallado-sin-vida\/\" title=\"Defensor de derechos humanos fue hallado sin vida\"><\/a>\r\n\t\t\t\t\t                        <div class=\"penci-image-holder penci-lazy\"                             data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2022\/01\/IMG_20220119_144956_783.webp\" data_bg_hidpi=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2022\/01\/IMG_20220119_144956_783-585x585.webp\"\r\n                             data-sizes=\"(max-width: 767px) 585px, 1170px\">\r\n                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n            <\/div>\r\n            <div class=\"pcbg-content\">\r\n                <div class=\"pcbg-content-flex\">\r\n                    <a class=\"pcbg-bgoverlay active-overlay\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2022\/01\/20\/defensor-de-derechos-humanos-fue-hallado-sin-vida\/\" title=\"Defensor de derechos humanos fue hallado sin vida\"><\/a>\r\n                    <div class=\"pcbg-content-inner bgcontent-block\">\r\n                        <a href=\"https:\/\/prensapaisa.com\/index.php\/2022\/01\/20\/defensor-de-derechos-humanos-fue-hallado-sin-vida\/\" title=\"Defensor de derechos humanos fue hallado sin vida\"\r\n                           class=\"pcbg-bgoverlaytext item-hover\"><\/a>\r\n\r\n\t\t\t\t\t\t                            <div class=\"pcbg-above item-hover\">\r\n\t\t\t\t\t\t\t<span class=\"cat pcbg-sub-title\">\r\n\t\t\t\t\t\t\t\t<a class=\"penci-cat-name penci-cat-43\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/fallecidos\/\"  rel=\"category tag\">Fallecidos<\/a>\t\t\t\t\t\t\t<\/span>\r\n                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"pcbg-heading item-hover\">\r\n                                <h3 class=\"pcbg-title\">\r\n                                    <a href=\"https:\/\/prensapaisa.com\/index.php\/2022\/01\/20\/defensor-de-derechos-humanos-fue-hallado-sin-vida\/\">\r\n                                        Defensor de derechos humanos fue hallado sin vida                                    <\/a>\r\n                                <\/h3>\r\n                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"grid-post-box-meta pcbg-meta item-hover\">\r\n                                <div class=\"pcbg-meta-desc\">\r\n\t\t\t\t\t\t\t\t\t                                        <span class=\"bg-date-author author-italic author vcard\">\r\n\t\t\t\t\t\t\t\t\t\tby <a class=\"url fn n\"\r\n                                                                                                href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a>\r\n\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                        <span class=\"bg-date\"><time class=\"entry-date published\" datetime=\"2022-01-20T03:00:07-05:00\">enero 20, 2022<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <\/div>\r\n\t\t\t\t\t\t\t\t                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n<div class=\"penci-bgitem bgitem-2\">\r\n    <div class=\"penci-bgitin\">\r\n        <div class=\"penci-bgmain\">\r\n            <div class=\"pcbg-thumb\">\r\n\t\t\t\t\t\t\t\t                <div class=\"pcbg-thumbin\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2022\/01\/21\/chica-de-17-anos-murio-en-una-rina\/\" title=\"Chica de 17 a\u00f1os muri\u00f3 en una ri\u00f1a\"><\/a>\r\n\t\t\t\t\t                        <div class=\"penci-image-holder penci-lazy\"                             data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2022\/01\/1-585x779.jpg\" data_bg_hidpi=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2022\/01\/1-585x779.jpg\"\r\n                             data-sizes=\"(max-width: 767px) 585px, 585px\">\r\n                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n            <\/div>\r\n            <div class=\"pcbg-content\">\r\n                <div class=\"pcbg-content-flex\">\r\n                    <a class=\"pcbg-bgoverlay active-overlay\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2022\/01\/21\/chica-de-17-anos-murio-en-una-rina\/\" title=\"Chica de 17 a\u00f1os muri\u00f3 en una ri\u00f1a\"><\/a>\r\n                    <div class=\"pcbg-content-inner bgcontent-block\">\r\n                        <a href=\"https:\/\/prensapaisa.com\/index.php\/2022\/01\/21\/chica-de-17-anos-murio-en-una-rina\/\" title=\"Chica de 17 a\u00f1os muri\u00f3 en una ri\u00f1a\"\r\n                           class=\"pcbg-bgoverlaytext item-hover\"><\/a>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"pcbg-heading item-hover\">\r\n                                <h3 class=\"pcbg-title\">\r\n                                    <a href=\"https:\/\/prensapaisa.com\/index.php\/2022\/01\/21\/chica-de-17-anos-murio-en-una-rina\/\">\r\n                                        Chica de 17 a\u00f1os muri\u00f3 en una ri\u00f1a                                    <\/a>\r\n                                <\/h3>\r\n                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"grid-post-box-meta pcbg-meta item-hover\">\r\n                                <div class=\"pcbg-meta-desc\">\r\n\t\t\t\t\t\t\t\t\t                                        <span class=\"bg-date-author author-italic author vcard\">\r\n\t\t\t\t\t\t\t\t\t\tby <a class=\"url fn n\"\r\n                                                                                                href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a>\r\n\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                        <span class=\"bg-date\"><time class=\"entry-date published\" datetime=\"2022-01-21T00:20:22-05:00\">enero 21, 2022<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <\/div>\r\n\t\t\t\t\t\t\t\t                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n<div class=\"penci-bgitem bgitem-0\">\r\n    <div class=\"penci-bgitin\">\r\n        <div class=\"penci-bgmain\">\r\n            <div class=\"pcbg-thumb\">\r\n\t\t\t\t\t\t\t\t                <div class=\"pcbg-thumbin\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2022\/02\/02\/no-hay-cura-para-algunos-motociclistas-en-remedios-antioquia-2\/\" title=\"No hay &#8220;cura&#8221; para algunos motociclistas en Remedios, Antioquia\"><\/a>\r\n\t\t\t\t\t                        <div class=\"penci-image-holder penci-lazy\"                             data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2022\/06\/3-1.jpg\" data_bg_hidpi=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2022\/06\/3-1.jpg\"\r\n                             data-sizes=\"(max-width: 767px) 585px, 585px\">\r\n                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n            <\/div>\r\n            <div class=\"pcbg-content\">\r\n                <div class=\"pcbg-content-flex\">\r\n                    <a class=\"pcbg-bgoverlay active-overlay\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2022\/02\/02\/no-hay-cura-para-algunos-motociclistas-en-remedios-antioquia-2\/\" title=\"No hay &#8220;cura&#8221; para algunos motociclistas en Remedios, Antioquia\"><\/a>\r\n                    <div class=\"pcbg-content-inner bgcontent-block\">\r\n                        <a href=\"https:\/\/prensapaisa.com\/index.php\/2022\/02\/02\/no-hay-cura-para-algunos-motociclistas-en-remedios-antioquia-2\/\" title=\"No hay &#8220;cura&#8221; para algunos motociclistas en Remedios, Antioquia\"\r\n                           class=\"pcbg-bgoverlaytext item-hover\"><\/a>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"pcbg-heading item-hover\">\r\n                                <h3 class=\"pcbg-title\">\r\n                                    <a href=\"https:\/\/prensapaisa.com\/index.php\/2022\/02\/02\/no-hay-cura-para-algunos-motociclistas-en-remedios-antioquia-2\/\">\r\n                                        No hay &#8220;cura&#8221; para algunos motociclistas en Remedios, Antioquia                                    <\/a>\r\n                                <\/h3>\r\n                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"grid-post-box-meta pcbg-meta item-hover\">\r\n                                <div class=\"pcbg-meta-desc\">\r\n\t\t\t\t\t\t\t\t\t                                        <span class=\"bg-date-author author-italic author vcard\">\r\n\t\t\t\t\t\t\t\t\t\tby <a class=\"url fn n\"\r\n                                                                                                href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a>\r\n\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                        <span class=\"bg-date\"><time class=\"entry-date published\" datetime=\"2022-02-02T09:23:00-05:00\">febrero 2, 2022<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <\/div>\r\n\t\t\t\t\t\t\t\t                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n<\/div><\/div>                <\/div>\r\n\t\t\t\t            <\/div>\r\n        <\/div>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-720d638 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"720d638\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct  elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2991c9d\" data-id=\"2991c9d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6dff450 elementor-widget elementor-widget-html\" data-id=\"6dff450\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div style='text-align: center;'><a style='display: inline-block; max-width: 728px;' href='https:\/\/1.envato.market\/YYJ4P' target='_blank'><img src='https:\/\/soledaddemo.pencidesign.net\/wp-content\/uploads\/2021\/08\/banner-home.jpg' width='728' height='90' alt='banner'><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4d3d12 elementor-widget elementor-widget-penci-big-grid\" data-id=\"d4d3d12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"penci-big-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"penci-clearfix penci-biggrid-wrapper penci-grid-col-6 penci-grid-mcol-2 penci-bgrid-based-custom penci-bgrid-style-1 pcbg-ficonpo-top-right pcbg-reiconpo-top-left penci-bgrid-content-below pencibg-imageh-zoom-in pencibg-texth-none pencibg-textani-movetop textop\">\r\n\t\t\t            <div class=\"penci-clearfix penci-biggrid penci-bgstyle-1 penci-bgel\">\r\n                <div class=\"penci-biggrid-inner default\">\r\n\t\t\t\t\t<div class=\"penci-clearfix penci-biggrid-data penci-dflex\"><div class=\"penci-bgitem elementor-repeater-item-17beedc\">\r\n    <div class=\"penci-bgitin\">\r\n        <div class=\"penci-bgmain\">\r\n            <div class=\"pcbg-thumb\">\r\n                <div class=\"pcbg-thumbin\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n\t\t\t\t\t   href=\"https:\/\/soledaddemo.pencidesign.net\/category\/fashion\/\"                       title=\"Fashion\"><\/a>\r\n\t\t\t\t\t                        <div class=\"penci-image-holder penci-lazy\" data-bgset=\"https:\/\/soledaddemo.pencidesign.net\/wp-content\/uploads\/2021\/08\/fashion.jpg\">\r\n                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n            <\/div>\r\n            <div class=\"pcbg-content\">\r\n                <div class=\"pcbg-content-flex pcbg-overlap-hover\">\r\n\t\t\t\t\t                        <a class=\"pcbg-cbgoverlap\"\r\n                           href=\"https:\/\/soledaddemo.pencidesign.net\/category\/fashion\/\"                           title=\"Fashion\"><\/a>\r\n\t\t\t\t\t                    <a class=\"pcbg-bgoverlay\"\r\n\t\t\t\t\t   href=\"https:\/\/soledaddemo.pencidesign.net\/category\/fashion\/\"                       title=\"Fashion\"><\/a>\r\n                    <div class=\"pcbg-content-inner bgcontent-block\">\r\n                        <a href=\"https:\/\/soledaddemo.pencidesign.net\/category\/fashion\/\"                           title=\"Fashion\"\r\n                           class=\"pcbg-bgoverlaytext item-hover\"><\/a>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"pcbg-heading item-hover\">\r\n                                <h3 class=\"pcbg-title\"><a\r\n\t\t\t\t\t\t\t\t\t\thref=\"https:\/\/soledaddemo.pencidesign.net\/category\/fashion\/\">Fashion<\/a><\/h3>\r\n                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n<div class=\"penci-bgitem elementor-repeater-item-1667a51\">\r\n    <div class=\"penci-bgitin\">\r\n        <div class=\"penci-bgmain\">\r\n            <div class=\"pcbg-thumb\">\r\n                <div class=\"pcbg-thumbin\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n\t\t\t\t\t   href=\"https:\/\/soledaddemo.pencidesign.net\/category\/food\/\"                       title=\"Food\"><\/a>\r\n\t\t\t\t\t                        <div class=\"penci-image-holder penci-lazy\" data-bgset=\"https:\/\/soledaddemo.pencidesign.net\/wp-content\/uploads\/2021\/08\/food.jpg\">\r\n                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n            <\/div>\r\n            <div class=\"pcbg-content\">\r\n                <div class=\"pcbg-content-flex pcbg-overlap-hover\">\r\n\t\t\t\t\t                        <a class=\"pcbg-cbgoverlap\"\r\n                           href=\"https:\/\/soledaddemo.pencidesign.net\/category\/food\/\"                           title=\"Food\"><\/a>\r\n\t\t\t\t\t                    <a class=\"pcbg-bgoverlay\"\r\n\t\t\t\t\t   href=\"https:\/\/soledaddemo.pencidesign.net\/category\/food\/\"                       title=\"Food\"><\/a>\r\n                    <div class=\"pcbg-content-inner bgcontent-block\">\r\n                        <a href=\"https:\/\/soledaddemo.pencidesign.net\/category\/food\/\"                           title=\"Food\"\r\n                           class=\"pcbg-bgoverlaytext item-hover\"><\/a>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"pcbg-heading item-hover\">\r\n                                <h3 class=\"pcbg-title\"><a\r\n\t\t\t\t\t\t\t\t\t\thref=\"https:\/\/soledaddemo.pencidesign.net\/category\/food\/\">Food<\/a><\/h3>\r\n                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n<div class=\"penci-bgitem elementor-repeater-item-953d092\">\r\n    <div class=\"penci-bgitin\">\r\n        <div class=\"penci-bgmain\">\r\n            <div class=\"pcbg-thumb\">\r\n                <div class=\"pcbg-thumbin\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n\t\t\t\t\t   href=\"https:\/\/soledaddemo.pencidesign.net\/category\/technology\/\"                       title=\"Technology\"><\/a>\r\n\t\t\t\t\t                        <div class=\"penci-image-holder penci-lazy\" data-bgset=\"https:\/\/soledaddemo.pencidesign.net\/wp-content\/uploads\/2021\/08\/tech.jpg\">\r\n                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n            <\/div>\r\n            <div class=\"pcbg-content\">\r\n                <div class=\"pcbg-content-flex pcbg-overlap-hover\">\r\n\t\t\t\t\t                        <a class=\"pcbg-cbgoverlap\"\r\n                           href=\"https:\/\/soledaddemo.pencidesign.net\/category\/technology\/\"                           title=\"Technology\"><\/a>\r\n\t\t\t\t\t                    <a class=\"pcbg-bgoverlay\"\r\n\t\t\t\t\t   href=\"https:\/\/soledaddemo.pencidesign.net\/category\/technology\/\"                       title=\"Technology\"><\/a>\r\n                    <div class=\"pcbg-content-inner bgcontent-block\">\r\n                        <a href=\"https:\/\/soledaddemo.pencidesign.net\/category\/technology\/\"                           title=\"Technology\"\r\n                           class=\"pcbg-bgoverlaytext item-hover\"><\/a>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"pcbg-heading item-hover\">\r\n                                <h3 class=\"pcbg-title\"><a\r\n\t\t\t\t\t\t\t\t\t\thref=\"https:\/\/soledaddemo.pencidesign.net\/category\/technology\/\">Technology<\/a><\/h3>\r\n                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n<div class=\"penci-bgitem elementor-repeater-item-80f0ea0\">\r\n    <div class=\"penci-bgitin\">\r\n        <div class=\"penci-bgmain\">\r\n            <div class=\"pcbg-thumb\">\r\n                <div class=\"pcbg-thumbin\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n\t\t\t\t\t   href=\"https:\/\/soledaddemo.pencidesign.net\/category\/life-style\/style\/\"                       title=\"Style\"><\/a>\r\n\t\t\t\t\t                        <div class=\"penci-image-holder penci-lazy\" data-bgset=\"https:\/\/soledaddemo.pencidesign.net\/wp-content\/uploads\/2021\/08\/style.jpg\">\r\n                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n            <\/div>\r\n            <div class=\"pcbg-content\">\r\n                <div class=\"pcbg-content-flex pcbg-overlap-hover\">\r\n\t\t\t\t\t                        <a class=\"pcbg-cbgoverlap\"\r\n                           href=\"https:\/\/soledaddemo.pencidesign.net\/category\/life-style\/style\/\"                           title=\"Style\"><\/a>\r\n\t\t\t\t\t                    <a class=\"pcbg-bgoverlay\"\r\n\t\t\t\t\t   href=\"https:\/\/soledaddemo.pencidesign.net\/category\/life-style\/style\/\"                       title=\"Style\"><\/a>\r\n                    <div class=\"pcbg-content-inner bgcontent-block\">\r\n                        <a href=\"https:\/\/soledaddemo.pencidesign.net\/category\/life-style\/style\/\"                           title=\"Style\"\r\n                           class=\"pcbg-bgoverlaytext item-hover\"><\/a>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"pcbg-heading item-hover\">\r\n                                <h3 class=\"pcbg-title\"><a\r\n\t\t\t\t\t\t\t\t\t\thref=\"https:\/\/soledaddemo.pencidesign.net\/category\/life-style\/style\/\">Style<\/a><\/h3>\r\n                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n<div class=\"penci-bgitem elementor-repeater-item-1a68081\">\r\n    <div class=\"penci-bgitin\">\r\n        <div class=\"penci-bgmain\">\r\n            <div class=\"pcbg-thumb\">\r\n                <div class=\"pcbg-thumbin\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n\t\t\t\t\t   href=\"https:\/\/soledaddemo.pencidesign.net\/category\/life-style\/healthy-living\/\"                       title=\"Living\"><\/a>\r\n\t\t\t\t\t                        <div class=\"penci-image-holder penci-lazy\" data-bgset=\"https:\/\/soledaddemo.pencidesign.net\/wp-content\/uploads\/2021\/08\/living.jpg\">\r\n                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n            <\/div>\r\n            <div class=\"pcbg-content\">\r\n                <div class=\"pcbg-content-flex pcbg-overlap-hover\">\r\n\t\t\t\t\t                        <a class=\"pcbg-cbgoverlap\"\r\n                           href=\"https:\/\/soledaddemo.pencidesign.net\/category\/life-style\/healthy-living\/\"                           title=\"Living\"><\/a>\r\n\t\t\t\t\t                    <a class=\"pcbg-bgoverlay\"\r\n\t\t\t\t\t   href=\"https:\/\/soledaddemo.pencidesign.net\/category\/life-style\/healthy-living\/\"                       title=\"Living\"><\/a>\r\n                    <div class=\"pcbg-content-inner bgcontent-block\">\r\n                        <a href=\"https:\/\/soledaddemo.pencidesign.net\/category\/life-style\/healthy-living\/\"                           title=\"Living\"\r\n                           class=\"pcbg-bgoverlaytext item-hover\"><\/a>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"pcbg-heading item-hover\">\r\n                                <h3 class=\"pcbg-title\"><a\r\n\t\t\t\t\t\t\t\t\t\thref=\"https:\/\/soledaddemo.pencidesign.net\/category\/life-style\/healthy-living\/\">Living<\/a><\/h3>\r\n                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n<div class=\"penci-bgitem elementor-repeater-item-cf4b5ca\">\r\n    <div class=\"penci-bgitin\">\r\n        <div class=\"penci-bgmain\">\r\n            <div class=\"pcbg-thumb\">\r\n                <div class=\"pcbg-thumbin\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n\t\t\t\t\t                          title=\"Culture\"><\/a>\r\n\t\t\t\t\t                        <div class=\"penci-image-holder penci-lazy\" data-bgset=\"https:\/\/soledaddemo.pencidesign.net\/wp-content\/uploads\/2021\/08\/culture.jpg\">\r\n                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n            <\/div>\r\n            <div class=\"pcbg-content\">\r\n                <div class=\"pcbg-content-flex\">\r\n\t\t\t\t\t                    <a class=\"pcbg-bgoverlay\"\r\n\t\t\t\t\t                          title=\"Culture\"><\/a>\r\n                    <div class=\"pcbg-content-inner bgcontent-block\">\r\n                        <a                            title=\"Culture\"\r\n                           class=\"pcbg-bgoverlaytext item-hover\"><\/a>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"pcbg-heading item-hover\">\r\n                                <h3 class=\"pcbg-title\"><a\r\n\t\t\t\t\t\t\t\t\t\t>Culture<\/a><\/h3>\r\n                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n<\/div>                <\/div>\r\n\t\t\t\t            <\/div>\r\n        <\/div>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"penci-section penci-enSticky penci-structure-22 elementor-section elementor-top-section elementor-element elementor-element-4528b81 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4528b81\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"penci-ercol-33 penci-ercol-order-1 penci-sticky-sb penci-sidebarSC elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8e0b4d1\" data-id=\"8e0b4d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca5ff6f elementor-widget elementor-widget-penci-sidebar\" data-id=\"ca5ff6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"penci-sidebar.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n        <div id=\"sidebar\"\r\n             class=\"penci-sidebar-content penci-sidebar-content-vc style-1 pcalign-center  pciconp-right pcicon-right\">\r\n            <div class=\"theiaStickySidebar\">\r\n\t\t\t\t<aside id=\"block-3\" class=\"widget widget_block\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\"><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><\/div>\n<\/aside><aside id=\"block-11\" class=\"widget widget_block widget_text\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/aside><aside id=\"penci_social_widget-1\" class=\"widget penci_social_widget\"><h3 class=\"widget-title penci-border-arrow\"><span class=\"inner-arrow\">S\u00edguenos en Nuestras Redes Sociales <\/span><\/h3>\r\n            <div class=\"widget-social pc_aligncenter show-text remove-border-radius penci-social-colored\">\r\n\t\t\t\t                        <a href=\"https:\/\/www.facebook.com\/PrensaPaisaOficial\"\r\n                           aria-label=\"Facebook\"  rel=\"noreferrer\"                           target=\"_blank\"><i class=\"penci-faicon fa fa-facebook\"  style=\"font-size: 14px\"><\/i>                            <span style=\"font-size: 13px\">Facebook<\/span><\/a>\r\n\t\t\t\t\t\t                        <a href=\"https:\/\/twitter.com\/PrensaAntioquia\"\r\n                           aria-label=\"Twitter\"  rel=\"noreferrer\"                           target=\"_blank\"><i class=\"penci-faicon fa fa-twitter\"  style=\"font-size: 14px\"><\/i>                            <span style=\"font-size: 13px\">Twitter<\/span><\/a>\r\n\t\t\t\t\t\t                        <a href=\"https:\/\/www.instagram.com\/prensapaisa\/\"\r\n                           aria-label=\"Instagram\"  rel=\"noreferrer\"                           target=\"_blank\"><i class=\"penci-faicon fa fa-instagram\"  style=\"font-size: 14px\"><\/i>                            <span style=\"font-size: 13px\">Instagram<\/span><\/a>\r\n\t\t\t\t\t\t                        <a href=\"https:\/\/www.youtube.com\/channel\/UCQjX-HcLcmi73FNWoobKBvg\"\r\n                           aria-label=\"Youtube\"  rel=\"noreferrer\"                           target=\"_blank\"><i class=\"penci-faicon fa fa-youtube-play\"  style=\"font-size: 14px\"><\/i>                            <span style=\"font-size: 13px\">Youtube<\/span><\/a>\r\n\t\t\t\t\t\t                        <a href=\"https:\/\/api.whatsapp.com\/send\/?phone=573135242677&#038;text&#038;app_absent=0\"\r\n                           aria-label=\"Whatsapp\"  rel=\"noreferrer\"                           target=\"_blank\"><i class=\"penci-faicon fa fa-whatsapp\"  style=\"font-size: 14px\"><\/i>                            <span style=\"font-size: 13px\">Whatsapp<\/span><\/a>\r\n\t\t\t\t\t\t            <\/div>\r\n\r\n\t\t\t<\/aside><aside id=\"custom_html-1\" class=\"widget_text widget widget_custom_html\"><div class=\"textwidget custom-html-widget\"><\/div><\/aside><aside id=\"penci_popular_news_widget-1\" class=\"widget penci_popular_news_widget\"><h3 class=\"widget-title penci-border-arrow\"><span class=\"inner-arrow\">Noticias Populares<\/span><\/h3>                <ul id=\"penci-popularwg-6117\"\r\n                    class=\"side-newsfeed display-order-numbers\">\r\n\r\n\t\t\t\t\t\r\n                        <li class=\"penci-feed\">\r\n\t\t\t\t\t\t\t                                <span class=\"order-border-number\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"number-post\">1<\/span>\r\n\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t                            <div class=\"side-item\">\r\n\t\t\t\t\t\t\t\t                                    <div class=\"side-image\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                            <a class=\"penci-image-holder penci-lazy small-fix-size\" rel=\"bookmark\"\r\n                                               data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2022\/06\/captura-juan-23-263x175.jpeg\"\r\n                                               href=\"https:\/\/prensapaisa.com\/index.php\/2022\/06\/16\/capturan-a-un-hombre-muy-buscado-por-las-chicas-y-por-las-autoridades-bellanitas\/\"\r\n                                               title=\"Capturan a un hombre muy buscado por las chicas y por las autoridades bellanitas\"><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t                                    <\/div>\r\n\t\t\t\t\t\t\t\t                                <div class=\"side-item-text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n                                    <h4 class=\"side-title-post\">\r\n                                        <a href=\"https:\/\/prensapaisa.com\/index.php\/2022\/06\/16\/capturan-a-un-hombre-muy-buscado-por-las-chicas-y-por-las-autoridades-bellanitas\/\" rel=\"bookmark\" title=\"Capturan a un hombre muy buscado por las chicas y por las autoridades bellanitas\">\r\n\t\t\t\t\t\t\t\t\t\t\tCapturan a un hombre muy buscado por las...                                        <\/a>\r\n                                    <\/h4>\r\n\t\t\t\t\t\t\t\t\t                                        <div class=\"grid-post-box-meta penci-side-item-meta pcsnmt-below\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                                <span class=\"side-item-meta side-wdate\"><time class=\"entry-date published\" datetime=\"2022-06-16T17:13:08-05:00\">junio 16, 2022<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                                <span class=\"side-item-meta side-wviews\">11.713 views<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t                                        <\/div>\r\n\t\t\t\t\t\t\t\t\t                                <\/div>\r\n                            <\/div>\r\n                        <\/li>\r\n\r\n\t\t\t\t\t\t\r\n                        <li class=\"penci-feed\">\r\n\t\t\t\t\t\t\t                                <span class=\"order-border-number\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"number-post\">2<\/span>\r\n\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t                            <div class=\"side-item\">\r\n\t\t\t\t\t\t\t\t                                    <div class=\"side-image\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                            <a class=\"penci-image-holder penci-lazy small-fix-size\" rel=\"bookmark\"\r\n                                               data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/04\/440776043_466092179319108_7012276559466048800_n-263x175.jpg\"\r\n                                               href=\"https:\/\/prensapaisa.com\/index.php\/2024\/04\/29\/gringo-que-deslumbraba-y-derretia-a-las-chicas-por-su-fisico-y-dinero-fue-enviado-a-prision-en-medellin\/\"\r\n                                               title=\"Gringo que deslumbraba y derret\u00eda a las chicas por su f\u00edsico y dinero fue enviado a prisi\u00f3n en Medell\u00edn\"><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t                                    <\/div>\r\n\t\t\t\t\t\t\t\t                                <div class=\"side-item-text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n                                    <h4 class=\"side-title-post\">\r\n                                        <a href=\"https:\/\/prensapaisa.com\/index.php\/2024\/04\/29\/gringo-que-deslumbraba-y-derretia-a-las-chicas-por-su-fisico-y-dinero-fue-enviado-a-prision-en-medellin\/\" rel=\"bookmark\" title=\"Gringo que deslumbraba y derret\u00eda a las chicas por su f\u00edsico y dinero fue enviado a prisi\u00f3n en Medell\u00edn\">\r\n\t\t\t\t\t\t\t\t\t\t\tGringo que deslumbraba y derret\u00eda a las chicas...                                        <\/a>\r\n                                    <\/h4>\r\n\t\t\t\t\t\t\t\t\t                                        <div class=\"grid-post-box-meta penci-side-item-meta pcsnmt-below\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                                <span class=\"side-item-meta side-wdate\"><time class=\"entry-date published\" datetime=\"2024-04-29T09:20:32-05:00\">abril 29, 2024<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                                <span class=\"side-item-meta side-wviews\">11.284 views<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t                                        <\/div>\r\n\t\t\t\t\t\t\t\t\t                                <\/div>\r\n                            <\/div>\r\n                        <\/li>\r\n\r\n\t\t\t\t\t\t\r\n                        <li class=\"penci-feed\">\r\n\t\t\t\t\t\t\t                                <span class=\"order-border-number\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"number-post\">3<\/span>\r\n\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t                            <div class=\"side-item\">\r\n\t\t\t\t\t\t\t\t                                    <div class=\"side-image\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                            <a class=\"penci-image-holder penci-lazy small-fix-size\" rel=\"bookmark\"\r\n                                               data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2025\/05\/496992099_729718606289796_6513705962496735415_n-1-263x175.jpg\"\r\n                                               href=\"https:\/\/prensapaisa.com\/index.php\/2025\/05\/20\/cayo-el-narco-invisible-del-clan-del-golfo-alias-marquitos-quien-enviaba-hasta-tres-toneladas-de-cocaina-al-mes-a-estados-unidos-le-dijo-a-la-policia-que-no-le-tenia-miedo-y-s\/\"\r\n                                               title=\"Cay\u00f3 el \u2018narco invisible\u2019 del Clan del Golfo, alias &#8220;marquitos&#8221;, quien enviaba hasta tres toneladas de coca\u00edna al mes a Estados Unidos; le dijo a la polic\u00eda que no le ten\u00eda miedo y sonri\u00f3\u2026\"><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t                                    <\/div>\r\n\t\t\t\t\t\t\t\t                                <div class=\"side-item-text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n                                    <h4 class=\"side-title-post\">\r\n                                        <a href=\"https:\/\/prensapaisa.com\/index.php\/2025\/05\/20\/cayo-el-narco-invisible-del-clan-del-golfo-alias-marquitos-quien-enviaba-hasta-tres-toneladas-de-cocaina-al-mes-a-estados-unidos-le-dijo-a-la-policia-que-no-le-tenia-miedo-y-s\/\" rel=\"bookmark\" title=\"Cay\u00f3 el \u2018narco invisible\u2019 del Clan del Golfo, alias &#8220;marquitos&#8221;, quien enviaba hasta tres toneladas de coca\u00edna al mes a Estados Unidos; le dijo a la polic\u00eda que no le ten\u00eda miedo y sonri\u00f3\u2026\">\r\n\t\t\t\t\t\t\t\t\t\t\tCay\u00f3 el \u2018narco invisible\u2019 del Clan del Golfo,...                                        <\/a>\r\n                                    <\/h4>\r\n\t\t\t\t\t\t\t\t\t                                        <div class=\"grid-post-box-meta penci-side-item-meta pcsnmt-below\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                                <span class=\"side-item-meta side-wdate\"><time class=\"entry-date published\" datetime=\"2025-05-20T19:20:23-05:00\">mayo 20, 2025<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                                <span class=\"side-item-meta side-wviews\">11.048 views<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t                                        <\/div>\r\n\t\t\t\t\t\t\t\t\t                                <\/div>\r\n                            <\/div>\r\n                        <\/li>\r\n\r\n\t\t\t\t\t\t\r\n                        <li class=\"penci-feed\">\r\n\t\t\t\t\t\t\t                                <span class=\"order-border-number\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"number-post\">4<\/span>\r\n\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t                            <div class=\"side-item\">\r\n\t\t\t\t\t\t\t\t                                    <div class=\"side-image\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                            <a class=\"penci-image-holder penci-lazy small-fix-size\" rel=\"bookmark\"\r\n                                               data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-21-at-10.20.34-AM-1-263x175.jpeg\"\r\n                                               href=\"https:\/\/prensapaisa.com\/index.php\/2023\/06\/21\/capturan-a-tres-hombres-por-quitarle-la-vida-a-un-hincha-en-medellin\/\"\r\n                                               title=\"Capturan a tres hombres por quitarle la vida a un hincha en Medell\u00edn\"><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t                                    <\/div>\r\n\t\t\t\t\t\t\t\t                                <div class=\"side-item-text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n                                    <h4 class=\"side-title-post\">\r\n                                        <a href=\"https:\/\/prensapaisa.com\/index.php\/2023\/06\/21\/capturan-a-tres-hombres-por-quitarle-la-vida-a-un-hincha-en-medellin\/\" rel=\"bookmark\" title=\"Capturan a tres hombres por quitarle la vida a un hincha en Medell\u00edn\">\r\n\t\t\t\t\t\t\t\t\t\t\tCapturan a tres hombres por quitarle la vida...                                        <\/a>\r\n                                    <\/h4>\r\n\t\t\t\t\t\t\t\t\t                                        <div class=\"grid-post-box-meta penci-side-item-meta pcsnmt-below\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                                <span class=\"side-item-meta side-wdate\"><time class=\"entry-date published\" datetime=\"2023-06-21T10:55:13-05:00\">junio 21, 2023<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                                <span class=\"side-item-meta side-wviews\">9.858 views<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t                                        <\/div>\r\n\t\t\t\t\t\t\t\t\t                                <\/div>\r\n                            <\/div>\r\n                        <\/li>\r\n\r\n\t\t\t\t\t\t\r\n                        <li class=\"penci-feed\">\r\n\t\t\t\t\t\t\t                                <span class=\"order-border-number\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"number-post\">5<\/span>\r\n\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t                            <div class=\"side-item\">\r\n\t\t\t\t\t\t\t\t                                    <div class=\"side-image\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                            <a class=\"penci-image-holder penci-lazy small-fix-size\" rel=\"bookmark\"\r\n                                               data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2024\/04\/439405940_463131829615143_3604830237313445378_n-263x175.jpg\"\r\n                                               href=\"https:\/\/prensapaisa.com\/index.php\/2024\/04\/24\/fico-ira-a-la-carcel-por-desacato-con-una-mujer-en-embarazo\/\"\r\n                                               title=\"Fico ir\u00e1 a la c\u00e1rcel por desacato con una mujer en embarazo\"><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t                                    <\/div>\r\n\t\t\t\t\t\t\t\t                                <div class=\"side-item-text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n                                    <h4 class=\"side-title-post\">\r\n                                        <a href=\"https:\/\/prensapaisa.com\/index.php\/2024\/04\/24\/fico-ira-a-la-carcel-por-desacato-con-una-mujer-en-embarazo\/\" rel=\"bookmark\" title=\"Fico ir\u00e1 a la c\u00e1rcel por desacato con una mujer en embarazo\">\r\n\t\t\t\t\t\t\t\t\t\t\tFico ir\u00e1 a la c\u00e1rcel por desacato con...                                        <\/a>\r\n                                    <\/h4>\r\n\t\t\t\t\t\t\t\t\t                                        <div class=\"grid-post-box-meta penci-side-item-meta pcsnmt-below\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                                <span class=\"side-item-meta side-wdate\"><time class=\"entry-date published\" datetime=\"2024-04-24T15:51:35-05:00\">abril 24, 2024<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                                <span class=\"side-item-meta side-wviews\">7.962 views<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t                                        <\/div>\r\n\t\t\t\t\t\t\t\t\t                                <\/div>\r\n                            <\/div>\r\n                        <\/li>\r\n\r\n\t\t\t\t\t\t\r\n                <\/ul>\r\n\r\n\t\t\t\t<style type=\"text\/css\">.widget ul#penci-popularwg-6117 li:not(.featured-news) .side-item .side-item-text h4 a{ font-size: 13px; }.widget ul#penci-popularwg-6117 li .side-item .side-item-text .side-item-meta{ font-size: 12px; }.widget ul#penci-popularwg-6117 li .penci-image-holder.small-fix-size{ width: 100px; }<\/style><\/aside><aside id=\"categories-2\" class=\"widget widget_categories\"><h3 class=\"widget-title penci-border-arrow\"><span class=\"inner-arrow\">Categorias<\/span><\/h3>\n\t\t\t<ul>\n\t\t\t\t\t<li class=\"cat-item cat-item-45\"><a href=\"https:\/\/prensapaisa.com\/index.php\/category\/movilidad\/accidentes\/\">Accidentes <span class=\"category-item-count\">(430)<\/span><\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-49\"><a href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/capturas\/\">Capturas <span class=\"category-item-count\">(556)<\/span><\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-50\"><a href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/denuncias\/\">Denuncias <span class=\"category-item-count\">(698)<\/span><\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-57\"><a href=\"https:\/\/prensapaisa.com\/index.php\/category\/deportes\/\">Deportes <span class=\"category-item-count\">(10)<\/span><\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-51\"><a href=\"https:\/\/prensapaisa.com\/index.php\/category\/desaparecidos\/\">Desaparecidos <span class=\"category-item-count\">(282)<\/span><\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-43\"><a href=\"https:\/\/prensapaisa.com\/index.php\/category\/fallecidos\/\">Fallecidos <span class=\"category-item-count\">(760)<\/span><\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-48\"><a href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/hurtos\/\">Hurtos <span class=\"category-item-count\">(451)<\/span><\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-44\"><a href=\"https:\/\/prensapaisa.com\/index.php\/category\/movilidad\/\">Movilidad <span class=\"category-item-count\">(345)<\/span><\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-16\"><a href=\"https:\/\/prensapaisa.com\/index.php\/category\/municipios\/\">Municipios <span class=\"category-item-count\">(1.024)<\/span><\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-1\"><a href=\"https:\/\/prensapaisa.com\/index.php\/category\/noticias\/\">Noticias <span class=\"category-item-count\">(1.772)<\/span><\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-47\"><a href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/\">Orden Publico <span class=\"category-item-count\">(798)<\/span><\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-52\"><a href=\"https:\/\/prensapaisa.com\/index.php\/category\/pico-y-placa\/\">Pico y Placa <span class=\"category-item-count\">(17)<\/span><\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-46\"><a href=\"https:\/\/prensapaisa.com\/index.php\/category\/redes-sociales\/\">Redes Sociales <span class=\"category-item-count\">(1.040)<\/span><\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-26\"><a href=\"https:\/\/prensapaisa.com\/index.php\/category\/travel\/\">Travel <span class=\"category-item-count\">(4)<\/span><\/a>\n<\/li>\n\t\t\t<\/ul>\n\n\t\t\t<\/aside><aside id=\"mc4wp_form_widget-1\" class=\"widget widget_mc4wp_form_widget\"><h3 class=\"widget-title penci-border-arrow\"><span class=\"inner-arrow\">Suscribirse al bolet\u00edn informativo<\/span><\/h3><script>(function() {\n\twindow.mc4wp = window.mc4wp || {\n\t\tlisteners: [],\n\t\tforms: {\n\t\t\ton: function(evt, cb) {\n\t\t\t\twindow.mc4wp.listeners.push(\n\t\t\t\t\t{\n\t\t\t\t\t\tevent   : evt,\n\t\t\t\t\t\tcallback: cb\n\t\t\t\t\t}\n\t\t\t\t);\n\t\t\t}\n\t\t}\n\t}\n})();\n<\/script><!-- Mailchimp for WordPress v4.13.1 - https:\/\/wordpress.org\/plugins\/mailchimp-for-wp\/ --><form id=\"mc4wp-form-1\" class=\"mc4wp-form mc4wp-form-3318\" method=\"post\" data-id=\"3318\" data-name=\"Mailchimp Form\" ><div class=\"mc4wp-form-fields\"><p class=\"mdes\">Subscribe our newsletter for latest news, service & promo. Let's stay updated!<\/p>\r\n<p class=\"mname\"><input type=\"text\" name=\"NAME\" placeholder=\"Name...\" \/><\/p>\r\n<p class=\"memail\"><input type=\"email\" id=\"mc4wp_email\" name=\"EMAIL\" placeholder=\"Email...\" required \/><\/p>\r\n<p class=\"msubmit\"><input type=\"submit\" value=\"Subscribe\" \/><\/p><\/div><label style=\"display: none !important;\">Deja este campo vac\u00edo si eres humano: <input type=\"text\" name=\"_mc4wp_honeypot\" value=\"\" tabindex=\"-1\" autocomplete=\"off\" \/><\/label><input type=\"hidden\" name=\"_mc4wp_timestamp\" value=\"1784132326\" \/><input type=\"hidden\" name=\"_mc4wp_form_id\" value=\"3318\" \/><input type=\"hidden\" name=\"_mc4wp_form_element_id\" value=\"mc4wp-form-1\" \/><div class=\"mc4wp-response\"><\/div><\/form><!-- \/ Mailchimp for WordPress Plugin --><\/aside>            <\/div>\r\n        <\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"penci-ercol-66 penci-ercol-order-2 penci-sticky-ct  elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-5952124\" data-id=\"5952124\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66b51cf elementor-widget elementor-widget-penci-featured-cat\" data-id=\"66b51cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"penci-featured-cat.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div id=\"pencifeatured_cat_68227\" class=\"penci-featured-cat-sc\">\r\n\t\t\t\t                    <section class=\"home-featured-cat mag-cat-style-13\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t                            <div class=\"penci-border-arrow penci-homepage-title penci-magazine-title style-13 pcalign-left pciconp-right pcicon-right\">\r\n                                <h3 class=\"inner-arrow\">\r\n                                    <span>\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/soledaddemo.pencidesign.net\/category\/life-style\/\">Lastest in Travel<\/a>                                    <\/span>\r\n                                <\/h3>\r\n\t\t\t\t\t\t\t\t                            <\/div>\r\n\t\t\t\t\t\t                        <div class=\"home-featured-cat-wrapper\">\r\n                            <div class=\"home-featured-cat-content pwf-id-default style-13\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                            <ul class=\"penci-grid penci-grid-maglayout penci-fea-cat-style-13\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"grid-style\">\r\n    <article id=\"post-16876\" class=\"item hentry\">\r\n\t\t            <div class=\"thumbnail\">\r\n\t\t\t\t\r\n\t\t\t\t                    <a class=\"penci-image-holder penci-lazy\"\r\n                       data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/742254221_1057317513437214_5211492233948717152_n-585x390.jpg\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/sintio-un-extrano-olor-abrio-el-capo-y-su-carro-termino-envuelto-en-llamas-en-las-palmas-medellin-sin-embargo-varios-conductores-se-bajaron-y-le-facilitaron-el-extintor\/\"\r\n                       title=\"Sinti\u00f3 un extra\u00f1o olor, abri\u00f3 el cap\u00f3 y su carro termin\u00f3 envuelto en llamas en Las Palmas, Medell\u00edn; sin embargo, varios conductores se bajaron y le facilitaron el extintor\">\r\n                    <\/a>\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t            <\/div>\r\n\t\t\r\n        <div class=\"grid-header-box\">\r\n            <h2 class=\"grid-title entry-title\"><a\r\n                        href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/sintio-un-extrano-olor-abrio-el-capo-y-su-carro-termino-envuelto-en-llamas-en-las-palmas-medellin-sin-embargo-varios-conductores-se-bajaron-y-le-facilitaron-el-extintor\/\">Sinti\u00f3 un extra\u00f1o olor, abri\u00f3 el cap\u00f3 y su carro termin\u00f3 envuelto en llamas en Las Palmas, Medell\u00edn; sin embargo, varios conductores se bajaron y le facilitaron el extintor<\/a>\r\n            <\/h2>\r\n\t\t\t                <div class=\"grid-post-box-meta\">\r\n\t\t\t\t\t                        <span class=\"featc-author author-italic author vcard\">by <a\r\n                                    class=\"url fn n\"\r\n                                    href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\r\n\t\t\t\t\t\t\t\t\t\t                        <span class=\"featc-date\"><time class=\"entry-date published\" datetime=\"2026-07-10T10:45:40-05:00\">julio 10, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">by <a class=\"url fn n\" href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2026-07-10T10:45:40-05:00\">julio 10, 2026<\/time>\t\t<\/div>\n\t\t        <\/div>\r\n\r\n    <\/article>\r\n<\/li>\r\n<li class=\"grid-style\">\r\n    <article id=\"post-16866\" class=\"item hentry\">\r\n\t\t            <div class=\"thumbnail\">\r\n\t\t\t\t\r\n\t\t\t\t                    <a class=\"penci-image-holder penci-lazy\"\r\n                       data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/742129508_1072133355381651_3020601880222902570_n-585x390.jpg\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/juez-ordena-a-congresista-yulieth-sanchez-rectificar-senalamientos-contra-dona-gloria-lider-politica-de-bello-antioquia\/\"\r\n                       title=\"Juez ordena a congresista Yulieth S\u00e1nchez rectificar se\u00f1alamientos contra do\u00f1a Gloria, l\u00edder pol\u00edtica de Bello, Antioquia\">\r\n                    <\/a>\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t            <\/div>\r\n\t\t\r\n        <div class=\"grid-header-box\">\r\n            <h2 class=\"grid-title entry-title\"><a\r\n                        href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/juez-ordena-a-congresista-yulieth-sanchez-rectificar-senalamientos-contra-dona-gloria-lider-politica-de-bello-antioquia\/\">Juez ordena a congresista Yulieth S\u00e1nchez rectificar se\u00f1alamientos contra do\u00f1a Gloria, l\u00edder pol\u00edtica de Bello, Antioquia<\/a>\r\n            <\/h2>\r\n\t\t\t                <div class=\"grid-post-box-meta\">\r\n\t\t\t\t\t                        <span class=\"featc-author author-italic author vcard\">by <a\r\n                                    class=\"url fn n\"\r\n                                    href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\r\n\t\t\t\t\t\t\t\t\t\t                        <span class=\"featc-date\"><time class=\"entry-date published\" datetime=\"2026-07-10T10:28:03-05:00\">julio 10, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">by <a class=\"url fn n\" href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2026-07-10T10:28:03-05:00\">julio 10, 2026<\/time>\t\t<\/div>\n\t\t        <\/div>\r\n\r\n    <\/article>\r\n<\/li>\r\n<li class=\"grid-style\">\r\n    <article id=\"post-16861\" class=\"item hentry\">\r\n\t\t            <div class=\"thumbnail\">\r\n\t\t\t\t\r\n\t\t\t\t                    <a class=\"penci-image-holder penci-lazy\"\r\n                       data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/741196587_1071902635404723_3685621252934489457_n-585x390.jpg\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-vecina-alerto-al-123-y-desato-el-operativo-que-termino-con-varios-jovenes-capturados-por-secuestro-en-robledo-medellin\/\"\r\n                       title=\"Una vecina alert\u00f3 al 123 y desat\u00f3 el operativo que termin\u00f3 con varios j\u00f3venes capturados por secuestro en Robledo, Medell\u00edn\">\r\n                    <\/a>\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t            <\/div>\r\n\t\t\r\n        <div class=\"grid-header-box\">\r\n            <h2 class=\"grid-title entry-title\"><a\r\n                        href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-vecina-alerto-al-123-y-desato-el-operativo-que-termino-con-varios-jovenes-capturados-por-secuestro-en-robledo-medellin\/\">Una vecina alert\u00f3 al 123 y desat\u00f3 el operativo que termin\u00f3 con varios j\u00f3venes capturados por secuestro en Robledo, Medell\u00edn<\/a>\r\n            <\/h2>\r\n\t\t\t                <div class=\"grid-post-box-meta\">\r\n\t\t\t\t\t                        <span class=\"featc-author author-italic author vcard\">by <a\r\n                                    class=\"url fn n\"\r\n                                    href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\r\n\t\t\t\t\t\t\t\t\t\t                        <span class=\"featc-date\"><time class=\"entry-date published\" datetime=\"2026-07-09T11:13:37-05:00\">julio 9, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">by <a class=\"url fn n\" href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2026-07-09T11:13:37-05:00\">julio 9, 2026<\/time>\t\t<\/div>\n\t\t        <\/div>\r\n\r\n    <\/article>\r\n<\/li>\r\n<li class=\"grid-style\">\r\n    <article id=\"post-16858\" class=\"item hentry\">\r\n\t\t            <div class=\"thumbnail\">\r\n\t\t\t\t\r\n\t\t\t\t                    <a class=\"penci-image-holder penci-lazy\"\r\n                       data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/740628751_1012735958165830_7922623203508311772_n-585x390.jpg\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/cayeron-los-cazadores-de-cadenas-de-oro-capturan-a-dos-presuntos-atracadores-vinculados-a-cinco-violentos-robos-en-medellin\/\"\r\n                       title=\"\u00a1Cayeron los cazadores de cadenas de oro! Capturan a dos presuntos atracadores vinculados a cinco violentos robos en Medell\u00edn\">\r\n                    <\/a>\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t            <\/div>\r\n\t\t\r\n        <div class=\"grid-header-box\">\r\n            <h2 class=\"grid-title entry-title\"><a\r\n                        href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/cayeron-los-cazadores-de-cadenas-de-oro-capturan-a-dos-presuntos-atracadores-vinculados-a-cinco-violentos-robos-en-medellin\/\">\u00a1Cayeron los cazadores de cadenas de oro! Capturan a dos presuntos atracadores vinculados a cinco violentos robos en Medell\u00edn<\/a>\r\n            <\/h2>\r\n\t\t\t                <div class=\"grid-post-box-meta\">\r\n\t\t\t\t\t                        <span class=\"featc-author author-italic author vcard\">by <a\r\n                                    class=\"url fn n\"\r\n                                    href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\r\n\t\t\t\t\t\t\t\t\t\t                        <span class=\"featc-date\"><time class=\"entry-date published\" datetime=\"2026-07-09T10:38:44-05:00\">julio 9, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">by <a class=\"url fn n\" href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2026-07-09T10:38:44-05:00\">julio 9, 2026<\/time>\t\t<\/div>\n\t\t        <\/div>\r\n\r\n    <\/article>\r\n<\/li>\r\n<li class=\"grid-style\">\r\n    <article id=\"post-16851\" class=\"item hentry\">\r\n\t\t            <div class=\"thumbnail\">\r\n\t\t\t\t\r\n\t\t\t\t                    <a class=\"penci-image-holder penci-lazy\"\r\n                       data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/740601678_975972272103281_2887798897915239700_n-1-585x390.jpg\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/el-viaje-sin-regreso-la-misteriosa-ruta-que-termino-con-varios-hombres-asesinados-en-distintos-municipios-de-antioquia\/\"\r\n                       title=\"El viaje sin regreso: la misteriosa ruta que termin\u00f3 con varios hombres asesinados en distintos municipios de Antioquia\">\r\n                    <\/a>\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t            <\/div>\r\n\t\t\r\n        <div class=\"grid-header-box\">\r\n            <h2 class=\"grid-title entry-title\"><a\r\n                        href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/el-viaje-sin-regreso-la-misteriosa-ruta-que-termino-con-varios-hombres-asesinados-en-distintos-municipios-de-antioquia\/\">El viaje sin regreso: la misteriosa ruta que termin\u00f3 con varios hombres asesinados en distintos municipios de Antioquia<\/a>\r\n            <\/h2>\r\n\t\t\t                <div class=\"grid-post-box-meta\">\r\n\t\t\t\t\t                        <span class=\"featc-author author-italic author vcard\">by <a\r\n                                    class=\"url fn n\"\r\n                                    href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\r\n\t\t\t\t\t\t\t\t\t\t                        <span class=\"featc-date\"><time class=\"entry-date published\" datetime=\"2026-07-09T10:37:35-05:00\">julio 9, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">by <a class=\"url fn n\" href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2026-07-09T10:37:35-05:00\">julio 9, 2026<\/time>\t\t<\/div>\n\t\t        <\/div>\r\n\r\n    <\/article>\r\n<\/li>\r\n<li class=\"grid-style\">\r\n    <article id=\"post-16840\" class=\"item hentry\">\r\n\t\t            <div class=\"thumbnail\">\r\n\t\t\t\t\r\n\t\t\t\t                    <a class=\"penci-image-holder penci-lazy\"\r\n                       data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/740881013_1011513078407653_5440553282796469660_n-585x390.jpg\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-mujer-salio-a-caminar-con-su-suegra-y-fueron-embestidas-por-una-camioneta-la-familia-de-la-joven-que-murio-atropellada-en-la-via-niquia-girardota-busca-al-conductor-que-huyo\/\"\r\n                       title=\"Una mujer sali\u00f3 a caminar con su suegra y fueron embestidas por una camioneta; la Familia de la joven que muri\u00f3 atropellada en la v\u00eda Niqu\u00eda-Girardota busca al conductor que huy\u00f3\u2026\">\r\n                    <\/a>\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t            <\/div>\r\n\t\t\r\n        <div class=\"grid-header-box\">\r\n            <h2 class=\"grid-title entry-title\"><a\r\n                        href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-mujer-salio-a-caminar-con-su-suegra-y-fueron-embestidas-por-una-camioneta-la-familia-de-la-joven-que-murio-atropellada-en-la-via-niquia-girardota-busca-al-conductor-que-huyo\/\">Una mujer sali\u00f3 a caminar con su suegra y fueron embestidas por una camioneta; la Familia de la joven que muri\u00f3 atropellada en la v\u00eda Niqu\u00eda-Girardota busca al conductor que huy\u00f3\u2026<\/a>\r\n            <\/h2>\r\n\t\t\t                <div class=\"grid-post-box-meta\">\r\n\t\t\t\t\t                        <span class=\"featc-author author-italic author vcard\">by <a\r\n                                    class=\"url fn n\"\r\n                                    href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\r\n\t\t\t\t\t\t\t\t\t\t                        <span class=\"featc-date\"><time class=\"entry-date published\" datetime=\"2026-07-09T10:21:31-05:00\">julio 9, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">by <a class=\"url fn n\" href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2026-07-09T10:21:31-05:00\">julio 9, 2026<\/time>\t\t<\/div>\n\t\t        <\/div>\r\n\r\n    <\/article>\r\n<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t                                            <\/ul>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                            <\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\r\n                        <\/div>\r\n\r\n\t\t\t\t\t\t                <\/section>\r\n\t\t\t\r\n            <\/div><!-- penci-featured-cat-sc -->\r\n\t\t\t            <style>\r\n                                #pencifeatured_cat_68227\t\t\t\t.first-post .magcat-detail .mag-header:after,\r\n                #pencifeatured_cat_68227 .list-post .header-list-style:after,\r\n                #pencifeatured_cat_68227 .home-featured-cat-content.style-7 .grid-header-box:after {\r\n\t\t\t\t\tcontent: none;\r\n\t\t\t\t}\r\n                #pencifeatured_cat_68227\t\t\t\t.grid-header-box,\r\n                #pencifeatured_cat_68227 .list-post .header-list-style,\r\n                #pencifeatured_cat_68227 .first-post .magcat-detail .mag-header {\r\n\t\t\t\t\tpadding-bottom: 0;\r\n\t\t\t\t}\r\n                            <\/style>\r\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a36262 elementor-widget elementor-widget-html\" data-id=\"2a36262\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div style='text-align: center;'><a style='display: inline-block; max-width: 728px;' href='https:\/\/1.envato.market\/YYJ4P' target='_blank'><img src='https:\/\/soledaddemo.pencidesign.net\/wp-content\/uploads\/2021\/08\/banner-home.jpg' width='728' height='90' alt='banner'><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a547a5 elementor-widget elementor-widget-penci-latest-posts\" data-id=\"3a547a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"penci-latest-posts.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t                <div id=\"pencilatest_posts_11313\" class=\"penci-latest-posts-sc penci-latest-posts-list penci-latest-posts-el penci-el-mixed-s1 penci-std-continue-center penci-std-excerpt-center penci-grid-excerpt-left\">\r\n\t\t\t\t\t\t\t\t\t\t\t                        <div class=\"penci-border-arrow penci-homepage-title penci-home-latest-posts style-13 pcalign-center pciconp-right pcicon-right\">\r\n                            <h3 class=\"inner-arrow\">\r\n                                <span>\r\n\t\t\t\t\t\t\t\tlatest in fashion                                <\/span>\r\n                            <\/h3>\r\n\t\t\t\t\t\t\t                        <\/div>\r\n\t\t\t\t\t                    <div class=\"penci-wrapper-posts-ajax\">\r\n\r\n                        <div class=\"penci-wrapper-posts-content pwid-default\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <ul class=\"penci-wrapper-data penci-grid penci-shortcode-render\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t    <li class=\"list-post penci-item-listp\">\r\n        <article id=\"post-16876\" class=\"item hentry\">\r\n\t\t\t                <div class=\"thumbnail\">\r\n\t\t\t\t\t\r\n\t\t\t\t\t                        <a class=\"penci-image-holder penci-lazy\"                           data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/742254221_1057317513437214_5211492233948717152_n-585x390.jpg\"\r\n                           href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/sintio-un-extrano-olor-abrio-el-capo-y-su-carro-termino-envuelto-en-llamas-en-las-palmas-medellin-sin-embargo-varios-conductores-se-bajaron-y-le-facilitaron-el-extintor\/\"\r\n                           title=\"Sinti\u00f3 un extra\u00f1o olor, abri\u00f3 el cap\u00f3 y su carro termin\u00f3 envuelto en llamas en Las Palmas, Medell\u00edn; sin embargo, varios conductores se bajaron y le facilitaron el extintor\">\r\n                        <\/a>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <\/div>\r\n\t\t\t\r\n            <div class=\"content-list-right content-list-center\">\r\n                <div class=\"header-list-style\">\r\n\t\t\t\t\t\r\n                    <h2 class=\"penci-entry-title entry-title grid-title\"><a\r\n                                href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/sintio-un-extrano-olor-abrio-el-capo-y-su-carro-termino-envuelto-en-llamas-en-las-palmas-medellin-sin-embargo-varios-conductores-se-bajaron-y-le-facilitaron-el-extintor\/\">Sinti\u00f3 un extra\u00f1o olor, abri\u00f3 el cap\u00f3 y su carro termin\u00f3 envuelto en llamas en Las Palmas, Medell\u00edn; sin embargo, varios conductores se bajaron y le facilitaron el extintor<\/a>\r\n                    <\/h2>\r\n\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">by <a class=\"url fn n\" href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2026-07-10T10:45:40-05:00\">julio 10, 2026<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                        <div class=\"grid-post-box-meta\">\r\n\t\t\t\t\t\t\t                                <span class=\"otherl-date-author author-italic author vcard\">by <a\r\n                                            class=\"url fn n\"\r\n                                            href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2026-07-10T10:45:40-05:00\">julio 10, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n\r\n\t\t\t\t                    <div class=\"item-content entry-content\">\r\n\t\t\t\t\t\t<p>Prensapaisa.com La ma\u00f1ana de este viernes comenz\u00f3 con largas filas de veh\u00edculos sobre la avenida Las Palmas, una de las principales v\u00edas de ingreso a Medell\u00edn. Sin embargo, esta vez &#8230;<\/p>\n                    <\/div>\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t            <\/div>\r\n\r\n        <\/article>\r\n    <\/li>\r\n    <li class=\"list-post penci-item-listp\">\r\n        <article id=\"post-16866\" class=\"item hentry\">\r\n\t\t\t                <div class=\"thumbnail\">\r\n\t\t\t\t\t\r\n\t\t\t\t\t                        <a class=\"penci-image-holder penci-lazy\"                           data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/742129508_1072133355381651_3020601880222902570_n-585x390.jpg\"\r\n                           href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/juez-ordena-a-congresista-yulieth-sanchez-rectificar-senalamientos-contra-dona-gloria-lider-politica-de-bello-antioquia\/\"\r\n                           title=\"Juez ordena a congresista Yulieth S\u00e1nchez rectificar se\u00f1alamientos contra do\u00f1a Gloria, l\u00edder pol\u00edtica de Bello, Antioquia\">\r\n                        <\/a>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <\/div>\r\n\t\t\t\r\n            <div class=\"content-list-right content-list-center\">\r\n                <div class=\"header-list-style\">\r\n\t\t\t\t\t\r\n                    <h2 class=\"penci-entry-title entry-title grid-title\"><a\r\n                                href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/juez-ordena-a-congresista-yulieth-sanchez-rectificar-senalamientos-contra-dona-gloria-lider-politica-de-bello-antioquia\/\">Juez ordena a congresista Yulieth S\u00e1nchez rectificar se\u00f1alamientos contra do\u00f1a Gloria, l\u00edder pol\u00edtica de Bello, Antioquia<\/a>\r\n                    <\/h2>\r\n\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">by <a class=\"url fn n\" href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2026-07-10T10:28:03-05:00\">julio 10, 2026<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                        <div class=\"grid-post-box-meta\">\r\n\t\t\t\t\t\t\t                                <span class=\"otherl-date-author author-italic author vcard\">by <a\r\n                                            class=\"url fn n\"\r\n                                            href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2026-07-10T10:28:03-05:00\">julio 10, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n\r\n\t\t\t\t                    <div class=\"item-content entry-content\">\r\n\t\t\t\t\t\t<p>Prensapaisa.com Una controversia pol\u00edtica que comenz\u00f3 durante los escrutinios de las elecciones legislativas termin\u00f3 en los estrados judiciales. Un juez orden\u00f3 a la representante a la C\u00e1mara Yulieth S\u00e1nchez rectificar &#8230;<\/p>\n                    <\/div>\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t            <\/div>\r\n\r\n        <\/article>\r\n    <\/li>\r\n    <li class=\"list-post penci-item-listp\">\r\n        <article id=\"post-16861\" class=\"item hentry\">\r\n\t\t\t                <div class=\"thumbnail\">\r\n\t\t\t\t\t\r\n\t\t\t\t\t                        <a class=\"penci-image-holder penci-lazy\"                           data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/741196587_1071902635404723_3685621252934489457_n-585x390.jpg\"\r\n                           href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-vecina-alerto-al-123-y-desato-el-operativo-que-termino-con-varios-jovenes-capturados-por-secuestro-en-robledo-medellin\/\"\r\n                           title=\"Una vecina alert\u00f3 al 123 y desat\u00f3 el operativo que termin\u00f3 con varios j\u00f3venes capturados por secuestro en Robledo, Medell\u00edn\">\r\n                        <\/a>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <\/div>\r\n\t\t\t\r\n            <div class=\"content-list-right content-list-center\">\r\n                <div class=\"header-list-style\">\r\n\t\t\t\t\t\r\n                    <h2 class=\"penci-entry-title entry-title grid-title\"><a\r\n                                href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-vecina-alerto-al-123-y-desato-el-operativo-que-termino-con-varios-jovenes-capturados-por-secuestro-en-robledo-medellin\/\">Una vecina alert\u00f3 al 123 y desat\u00f3 el operativo que termin\u00f3 con varios j\u00f3venes capturados por secuestro en Robledo, Medell\u00edn<\/a>\r\n                    <\/h2>\r\n\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">by <a class=\"url fn n\" href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2026-07-09T11:13:37-05:00\">julio 9, 2026<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                        <div class=\"grid-post-box-meta\">\r\n\t\t\t\t\t\t\t                                <span class=\"otherl-date-author author-italic author vcard\">by <a\r\n                                            class=\"url fn n\"\r\n                                            href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2026-07-09T11:13:37-05:00\">julio 9, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n\r\n\t\t\t\t                    <div class=\"item-content entry-content\">\r\n\t\t\t\t\t\t<p>Prensapaisa.com En Robledo, Comuna 7, los techos suelen servir para tender ropa, conversar con los vecinos o contemplar el atardecer sobre las monta\u00f1as de Medell\u00edn. Pero ese d\u00eda dejaron de &#8230;<\/p>\n                    <\/div>\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t            <\/div>\r\n\r\n        <\/article>\r\n    <\/li>\r\n    <li class=\"list-post penci-item-listp\">\r\n        <article id=\"post-16858\" class=\"item hentry\">\r\n\t\t\t                <div class=\"thumbnail\">\r\n\t\t\t\t\t\r\n\t\t\t\t\t                        <a class=\"penci-image-holder penci-lazy\"                           data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/740628751_1012735958165830_7922623203508311772_n-585x390.jpg\"\r\n                           href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/cayeron-los-cazadores-de-cadenas-de-oro-capturan-a-dos-presuntos-atracadores-vinculados-a-cinco-violentos-robos-en-medellin\/\"\r\n                           title=\"\u00a1Cayeron los cazadores de cadenas de oro! Capturan a dos presuntos atracadores vinculados a cinco violentos robos en Medell\u00edn\">\r\n                        <\/a>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <\/div>\r\n\t\t\t\r\n            <div class=\"content-list-right content-list-center\">\r\n                <div class=\"header-list-style\">\r\n\t\t\t\t\t\r\n                    <h2 class=\"penci-entry-title entry-title grid-title\"><a\r\n                                href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/cayeron-los-cazadores-de-cadenas-de-oro-capturan-a-dos-presuntos-atracadores-vinculados-a-cinco-violentos-robos-en-medellin\/\">\u00a1Cayeron los cazadores de cadenas de oro! Capturan a dos presuntos atracadores vinculados a cinco violentos robos en Medell\u00edn<\/a>\r\n                    <\/h2>\r\n\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">by <a class=\"url fn n\" href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2026-07-09T10:38:44-05:00\">julio 9, 2026<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                        <div class=\"grid-post-box-meta\">\r\n\t\t\t\t\t\t\t                                <span class=\"otherl-date-author author-italic author vcard\">by <a\r\n                                            class=\"url fn n\"\r\n                                            href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2026-07-09T10:38:44-05:00\">julio 9, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n\r\n\t\t\t\t                    <div class=\"item-content entry-content\">\r\n\t\t\t\t\t\t<p>Prensapaisa.com Antes de salir a atacar, al parecer estudiaban a sus v\u00edctimas. Bastaba ver una cadena de oro, un reloj costoso o una persona desprevenida para poner en marcha el &#8230;<\/p>\n                    <\/div>\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t            <\/div>\r\n\r\n        <\/article>\r\n    <\/li>\r\n    <li class=\"list-post penci-item-listp\">\r\n        <article id=\"post-16851\" class=\"item hentry\">\r\n\t\t\t                <div class=\"thumbnail\">\r\n\t\t\t\t\t\r\n\t\t\t\t\t                        <a class=\"penci-image-holder penci-lazy\"                           data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/740601678_975972272103281_2887798897915239700_n-1-585x390.jpg\"\r\n                           href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/el-viaje-sin-regreso-la-misteriosa-ruta-que-termino-con-varios-hombres-asesinados-en-distintos-municipios-de-antioquia\/\"\r\n                           title=\"El viaje sin regreso: la misteriosa ruta que termin\u00f3 con varios hombres asesinados en distintos municipios de Antioquia\">\r\n                        <\/a>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <\/div>\r\n\t\t\t\r\n            <div class=\"content-list-right content-list-center\">\r\n                <div class=\"header-list-style\">\r\n\t\t\t\t\t\r\n                    <h2 class=\"penci-entry-title entry-title grid-title\"><a\r\n                                href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/el-viaje-sin-regreso-la-misteriosa-ruta-que-termino-con-varios-hombres-asesinados-en-distintos-municipios-de-antioquia\/\">El viaje sin regreso: la misteriosa ruta que termin\u00f3 con varios hombres asesinados en distintos municipios de Antioquia<\/a>\r\n                    <\/h2>\r\n\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">by <a class=\"url fn n\" href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2026-07-09T10:37:35-05:00\">julio 9, 2026<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                        <div class=\"grid-post-box-meta\">\r\n\t\t\t\t\t\t\t                                <span class=\"otherl-date-author author-italic author vcard\">by <a\r\n                                            class=\"url fn n\"\r\n                                            href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2026-07-09T10:37:35-05:00\">julio 9, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n\r\n\t\t\t\t                    <div class=\"item-content entry-content\">\r\n\t\t\t\t\t\t<p>Prensapaisa.com Hay historias que comienzan como cualquier otra salida entre conocidos y terminan convirti\u00e9ndose en un rompecabezas para las autoridades. Esta es una de ellas. Las v\u00edctimas salieron de Itag\u00fc\u00ed &#8230;<\/p>\n                    <\/div>\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t            <\/div>\r\n\r\n        <\/article>\r\n    <\/li>\r\n    <li class=\"list-post penci-item-listp\">\r\n        <article id=\"post-16840\" class=\"item hentry\">\r\n\t\t\t                <div class=\"thumbnail\">\r\n\t\t\t\t\t\r\n\t\t\t\t\t                        <a class=\"penci-image-holder penci-lazy\"                           data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/740881013_1011513078407653_5440553282796469660_n-585x390.jpg\"\r\n                           href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-mujer-salio-a-caminar-con-su-suegra-y-fueron-embestidas-por-una-camioneta-la-familia-de-la-joven-que-murio-atropellada-en-la-via-niquia-girardota-busca-al-conductor-que-huyo\/\"\r\n                           title=\"Una mujer sali\u00f3 a caminar con su suegra y fueron embestidas por una camioneta; la Familia de la joven que muri\u00f3 atropellada en la v\u00eda Niqu\u00eda-Girardota busca al conductor que huy\u00f3\u2026\">\r\n                        <\/a>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <\/div>\r\n\t\t\t\r\n            <div class=\"content-list-right content-list-center\">\r\n                <div class=\"header-list-style\">\r\n\t\t\t\t\t\r\n                    <h2 class=\"penci-entry-title entry-title grid-title\"><a\r\n                                href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-mujer-salio-a-caminar-con-su-suegra-y-fueron-embestidas-por-una-camioneta-la-familia-de-la-joven-que-murio-atropellada-en-la-via-niquia-girardota-busca-al-conductor-que-huyo\/\">Una mujer sali\u00f3 a caminar con su suegra y fueron embestidas por una camioneta; la Familia de la joven que muri\u00f3 atropellada en la v\u00eda Niqu\u00eda-Girardota busca al conductor que huy\u00f3\u2026<\/a>\r\n                    <\/h2>\r\n\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">by <a class=\"url fn n\" href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2026-07-09T10:21:31-05:00\">julio 9, 2026<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                        <div class=\"grid-post-box-meta\">\r\n\t\t\t\t\t\t\t                                <span class=\"otherl-date-author author-italic author vcard\">by <a\r\n                                            class=\"url fn n\"\r\n                                            href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2026-07-09T10:21:31-05:00\">julio 9, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n\r\n\t\t\t\t                    <div class=\"item-content entry-content\">\r\n\t\t\t\t\t\t<p>Prensapaisa.com La muerte de Geraldin Vanegas tiene hoy a una familia sumida en el dolor y pidiendo ayuda para esclarecer lo ocurrido. La joven falleci\u00f3 luego de ser atropellada en &#8230;<\/p>\n                    <\/div>\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t            <\/div>\r\n\r\n        <\/article>\r\n    <\/li>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t\t\t                        <\/div>\r\n\r\n\t\t\t\t\t\t                    <\/div>\r\n                <\/div>\r\n\t\t\t            <style>\r\n                                                                                                                                #pencilatest_posts_11313\t\t\t\t.list-post .header-list-style:after,\r\n                #pencilatest_posts_11313 .grid-header-box:after,\r\n                #pencilatest_posts_11313 .penci-overlay-over .overlay-header-box:after,\r\n                #pencilatest_posts_11313 .home-featured-cat-content .first-post .magcat-detail .mag-header:after {\r\n\t\t\t\t\tcontent: none;\r\n\t\t\t\t}\r\n                #pencilatest_posts_11313\t\t\t\t.list-post .header-list-style, #pencilatest_posts_11313 .grid-header-box,\r\n                #pencilatest_posts_11313 .penci-overlay-over .overlay-header-box,\r\n                #pencilatest_posts_11313 .home-featured-cat-content .first-post .magcat-detail .mag-header {\r\n\t\t\t\t\tpadding-bottom: 0;\r\n\t\t\t\t}\r\n                                                                            <\/style>\r\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40961cc elementor-widget elementor-widget-html\" data-id=\"40961cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div style='text-align: center;'><a style='display: inline-block; max-width: 728px;' href='https:\/\/1.envato.market\/YYJ4P' target='_blank'><img src='https:\/\/soledaddemo.pencidesign.net\/wp-content\/uploads\/2021\/08\/banner-home.jpg' width='728' height='90' alt='banner'><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04b7958 elementor-widget elementor-widget-penci-big-grid\" data-id=\"04b7958\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"penci-big-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"penci-clearfix penci-biggrid-wrapper penci-grid-col-3 penci-grid-mcol-1 penci-bgrid-based-post penci-bgrid-style-1 pcbg-ficonpo-top-right pcbg-reiconpo-top-left penci-bgrid-content-below pencibg-imageh-none pencibg-texth-none pencibg-textani-movetop textop\">\r\n\t\t\t        <div class=\"penci-border-arrow penci-homepage-title penci-home-latest-posts style-13 pcalign-center pciconp-right pcicon-right block-title-icon-left\">\r\n            <h3 class=\"inner-arrow\">\r\n                <span>\r\n                    <span>healthy living<\/a>                <\/span>\r\n            <\/h3>\r\n\t\t\t        <\/div>\r\n\t\t            <div class=\"penci-clearfix penci-biggrid penci-bgstyle-1 penci-bgel\">\r\n                <div class=\"penci-biggrid-inner default\">\r\n\t\t\t\t\t<div class=\"penci-clearfix penci-biggrid-data penci-dflex\"><div class=\"penci-bgitem\">\r\n    <div class=\"penci-bgitin\">\r\n        <div class=\"penci-bgmain\">\r\n            <div class=\"pcbg-thumb\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <div class=\"pcbg-thumbin\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/sintio-un-extrano-olor-abrio-el-capo-y-su-carro-termino-envuelto-en-llamas-en-las-palmas-medellin-sin-embargo-varios-conductores-se-bajaron-y-le-facilitaron-el-extintor\/\" title=\"Sinti\u00f3 un extra\u00f1o olor, abri\u00f3 el cap\u00f3 y su carro termin\u00f3 envuelto en llamas en Las Palmas, Medell\u00edn; sin embargo, varios conductores se bajaron y le facilitaron el extintor\"><\/a>\r\n\t\t\t\t\t                        <div class=\"penci-image-holder penci-lazy\"                             data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/742254221_1057317513437214_5211492233948717152_n-585x498.jpg\" data_bg_hidpi=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/742254221_1057317513437214_5211492233948717152_n-585x498.jpg\"\r\n                             data-sizes=\"(max-width: 767px) 585px, 585px\">\r\n                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n            <\/div>\r\n            <div class=\"pcbg-content\">\r\n                <div class=\"pcbg-content-flex\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/sintio-un-extrano-olor-abrio-el-capo-y-su-carro-termino-envuelto-en-llamas-en-las-palmas-medellin-sin-embargo-varios-conductores-se-bajaron-y-le-facilitaron-el-extintor\/\" title=\"Sinti\u00f3 un extra\u00f1o olor, abri\u00f3 el cap\u00f3 y su carro termin\u00f3 envuelto en llamas en Las Palmas, Medell\u00edn; sin embargo, varios conductores se bajaron y le facilitaron el extintor\"><\/a>\r\n                    <div class=\"pcbg-content-inner bgcontent-block\">\r\n                        <a href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/sintio-un-extrano-olor-abrio-el-capo-y-su-carro-termino-envuelto-en-llamas-en-las-palmas-medellin-sin-embargo-varios-conductores-se-bajaron-y-le-facilitaron-el-extintor\/\" title=\"Sinti\u00f3 un extra\u00f1o olor, abri\u00f3 el cap\u00f3 y su carro termin\u00f3 envuelto en llamas en Las Palmas, Medell\u00edn; sin embargo, varios conductores se bajaron y le facilitaron el extintor\"\r\n                           class=\"pcbg-bgoverlaytext item-hover\"><\/a>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"pcbg-heading item-hover\">\r\n                                <h3 class=\"pcbg-title\">\r\n                                    <a href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/sintio-un-extrano-olor-abrio-el-capo-y-su-carro-termino-envuelto-en-llamas-en-las-palmas-medellin-sin-embargo-varios-conductores-se-bajaron-y-le-facilitaron-el-extintor\/\">\r\n                                        Sinti\u00f3 un extra\u00f1o olor, abri\u00f3 el cap\u00f3 y su carro termin\u00f3 envuelto en llamas en Las Palmas, Medell\u00edn; sin embargo, varios conductores se bajaron y le facilitaron el extintor                                    <\/a>\r\n                                <\/h3>\r\n                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"grid-post-box-meta pcbg-meta item-hover\">\r\n                                <div class=\"pcbg-meta-desc\">\r\n\t\t\t\t\t\t\t\t\t                                        <span class=\"bg-date-author author-italic author vcard\">\r\n\t\t\t\t\t\t\t\t\t\tby <a class=\"url fn n\"\r\n                                                                                                href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a>\r\n\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                        <span class=\"bg-date\"><time class=\"entry-date published\" datetime=\"2026-07-10T10:45:40-05:00\">julio 10, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <\/div>\r\n\t\t\t\t\t\t\t\t                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n<div class=\"penci-bgitem\">\r\n    <div class=\"penci-bgitin\">\r\n        <div class=\"penci-bgmain\">\r\n            <div class=\"pcbg-thumb\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <div class=\"pcbg-thumbin\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/juez-ordena-a-congresista-yulieth-sanchez-rectificar-senalamientos-contra-dona-gloria-lider-politica-de-bello-antioquia\/\" title=\"Juez ordena a congresista Yulieth S\u00e1nchez rectificar se\u00f1alamientos contra do\u00f1a Gloria, l\u00edder pol\u00edtica de Bello, Antioquia\"><\/a>\r\n\t\t\t\t\t                        <div class=\"penci-image-holder penci-lazy\"                             data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/742129508_1072133355381651_3020601880222902570_n-585x731.jpg\" data_bg_hidpi=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/742129508_1072133355381651_3020601880222902570_n-585x731.jpg\"\r\n                             data-sizes=\"(max-width: 767px) 585px, 585px\">\r\n                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n            <\/div>\r\n            <div class=\"pcbg-content\">\r\n                <div class=\"pcbg-content-flex\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/juez-ordena-a-congresista-yulieth-sanchez-rectificar-senalamientos-contra-dona-gloria-lider-politica-de-bello-antioquia\/\" title=\"Juez ordena a congresista Yulieth S\u00e1nchez rectificar se\u00f1alamientos contra do\u00f1a Gloria, l\u00edder pol\u00edtica de Bello, Antioquia\"><\/a>\r\n                    <div class=\"pcbg-content-inner bgcontent-block\">\r\n                        <a href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/juez-ordena-a-congresista-yulieth-sanchez-rectificar-senalamientos-contra-dona-gloria-lider-politica-de-bello-antioquia\/\" title=\"Juez ordena a congresista Yulieth S\u00e1nchez rectificar se\u00f1alamientos contra do\u00f1a Gloria, l\u00edder pol\u00edtica de Bello, Antioquia\"\r\n                           class=\"pcbg-bgoverlaytext item-hover\"><\/a>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"pcbg-heading item-hover\">\r\n                                <h3 class=\"pcbg-title\">\r\n                                    <a href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/juez-ordena-a-congresista-yulieth-sanchez-rectificar-senalamientos-contra-dona-gloria-lider-politica-de-bello-antioquia\/\">\r\n                                        Juez ordena a congresista Yulieth S\u00e1nchez rectificar se\u00f1alamientos contra do\u00f1a Gloria, l\u00edder pol\u00edtica de Bello, Antioquia                                    <\/a>\r\n                                <\/h3>\r\n                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"grid-post-box-meta pcbg-meta item-hover\">\r\n                                <div class=\"pcbg-meta-desc\">\r\n\t\t\t\t\t\t\t\t\t                                        <span class=\"bg-date-author author-italic author vcard\">\r\n\t\t\t\t\t\t\t\t\t\tby <a class=\"url fn n\"\r\n                                                                                                href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a>\r\n\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                        <span class=\"bg-date\"><time class=\"entry-date published\" datetime=\"2026-07-10T10:28:03-05:00\">julio 10, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <\/div>\r\n\t\t\t\t\t\t\t\t                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n<div class=\"penci-bgitem\">\r\n    <div class=\"penci-bgitin\">\r\n        <div class=\"penci-bgmain\">\r\n            <div class=\"pcbg-thumb\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <div class=\"pcbg-thumbin\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-vecina-alerto-al-123-y-desato-el-operativo-que-termino-con-varios-jovenes-capturados-por-secuestro-en-robledo-medellin\/\" title=\"Una vecina alert\u00f3 al 123 y desat\u00f3 el operativo que termin\u00f3 con varios j\u00f3venes capturados por secuestro en Robledo, Medell\u00edn\"><\/a>\r\n\t\t\t\t\t                        <div class=\"penci-image-holder penci-lazy\"                             data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/741196587_1071902635404723_3685621252934489457_n-585x390.jpg\" data_bg_hidpi=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/741196587_1071902635404723_3685621252934489457_n-585x390.jpg\"\r\n                             data-sizes=\"(max-width: 767px) 585px, 585px\">\r\n                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n            <\/div>\r\n            <div class=\"pcbg-content\">\r\n                <div class=\"pcbg-content-flex\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-vecina-alerto-al-123-y-desato-el-operativo-que-termino-con-varios-jovenes-capturados-por-secuestro-en-robledo-medellin\/\" title=\"Una vecina alert\u00f3 al 123 y desat\u00f3 el operativo que termin\u00f3 con varios j\u00f3venes capturados por secuestro en Robledo, Medell\u00edn\"><\/a>\r\n                    <div class=\"pcbg-content-inner bgcontent-block\">\r\n                        <a href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-vecina-alerto-al-123-y-desato-el-operativo-que-termino-con-varios-jovenes-capturados-por-secuestro-en-robledo-medellin\/\" title=\"Una vecina alert\u00f3 al 123 y desat\u00f3 el operativo que termin\u00f3 con varios j\u00f3venes capturados por secuestro en Robledo, Medell\u00edn\"\r\n                           class=\"pcbg-bgoverlaytext item-hover\"><\/a>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"pcbg-heading item-hover\">\r\n                                <h3 class=\"pcbg-title\">\r\n                                    <a href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-vecina-alerto-al-123-y-desato-el-operativo-que-termino-con-varios-jovenes-capturados-por-secuestro-en-robledo-medellin\/\">\r\n                                        Una vecina alert\u00f3 al 123 y desat\u00f3 el operativo que termin\u00f3 con varios j\u00f3venes capturados por secuestro en Robledo, Medell\u00edn                                    <\/a>\r\n                                <\/h3>\r\n                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"grid-post-box-meta pcbg-meta item-hover\">\r\n                                <div class=\"pcbg-meta-desc\">\r\n\t\t\t\t\t\t\t\t\t                                        <span class=\"bg-date-author author-italic author vcard\">\r\n\t\t\t\t\t\t\t\t\t\tby <a class=\"url fn n\"\r\n                                                                                                href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a>\r\n\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                        <span class=\"bg-date\"><time class=\"entry-date published\" datetime=\"2026-07-09T11:13:37-05:00\">julio 9, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <\/div>\r\n\t\t\t\t\t\t\t\t                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n<div class=\"penci-bgitem\">\r\n    <div class=\"penci-bgitin\">\r\n        <div class=\"penci-bgmain\">\r\n            <div class=\"pcbg-thumb\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <div class=\"pcbg-thumbin\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/cayeron-los-cazadores-de-cadenas-de-oro-capturan-a-dos-presuntos-atracadores-vinculados-a-cinco-violentos-robos-en-medellin\/\" title=\"\u00a1Cayeron los cazadores de cadenas de oro! Capturan a dos presuntos atracadores vinculados a cinco violentos robos en Medell\u00edn\"><\/a>\r\n\t\t\t\t\t                        <div class=\"penci-image-holder penci-lazy\"                             data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/740628751_1012735958165830_7922623203508311772_n-585x329.jpg\" data_bg_hidpi=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/740628751_1012735958165830_7922623203508311772_n-585x329.jpg\"\r\n                             data-sizes=\"(max-width: 767px) 585px, 585px\">\r\n                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n            <\/div>\r\n            <div class=\"pcbg-content\">\r\n                <div class=\"pcbg-content-flex\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/cayeron-los-cazadores-de-cadenas-de-oro-capturan-a-dos-presuntos-atracadores-vinculados-a-cinco-violentos-robos-en-medellin\/\" title=\"\u00a1Cayeron los cazadores de cadenas de oro! Capturan a dos presuntos atracadores vinculados a cinco violentos robos en Medell\u00edn\"><\/a>\r\n                    <div class=\"pcbg-content-inner bgcontent-block\">\r\n                        <a href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/cayeron-los-cazadores-de-cadenas-de-oro-capturan-a-dos-presuntos-atracadores-vinculados-a-cinco-violentos-robos-en-medellin\/\" title=\"\u00a1Cayeron los cazadores de cadenas de oro! Capturan a dos presuntos atracadores vinculados a cinco violentos robos en Medell\u00edn\"\r\n                           class=\"pcbg-bgoverlaytext item-hover\"><\/a>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"pcbg-heading item-hover\">\r\n                                <h3 class=\"pcbg-title\">\r\n                                    <a href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/cayeron-los-cazadores-de-cadenas-de-oro-capturan-a-dos-presuntos-atracadores-vinculados-a-cinco-violentos-robos-en-medellin\/\">\r\n                                        \u00a1Cayeron los cazadores de cadenas de oro! Capturan a dos presuntos atracadores vinculados a cinco violentos robos en Medell\u00edn                                    <\/a>\r\n                                <\/h3>\r\n                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"grid-post-box-meta pcbg-meta item-hover\">\r\n                                <div class=\"pcbg-meta-desc\">\r\n\t\t\t\t\t\t\t\t\t                                        <span class=\"bg-date-author author-italic author vcard\">\r\n\t\t\t\t\t\t\t\t\t\tby <a class=\"url fn n\"\r\n                                                                                                href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a>\r\n\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                        <span class=\"bg-date\"><time class=\"entry-date published\" datetime=\"2026-07-09T10:38:44-05:00\">julio 9, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <\/div>\r\n\t\t\t\t\t\t\t\t                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n<div class=\"penci-bgitem\">\r\n    <div class=\"penci-bgitin\">\r\n        <div class=\"penci-bgmain\">\r\n            <div class=\"pcbg-thumb\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <div class=\"pcbg-thumbin\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/el-viaje-sin-regreso-la-misteriosa-ruta-que-termino-con-varios-hombres-asesinados-en-distintos-municipios-de-antioquia\/\" title=\"El viaje sin regreso: la misteriosa ruta que termin\u00f3 con varios hombres asesinados en distintos municipios de Antioquia\"><\/a>\r\n\t\t\t\t\t                        <div class=\"penci-image-holder penci-lazy\"                             data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/740601678_975972272103281_2887798897915239700_n-1-585x958.jpg\" data_bg_hidpi=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/740601678_975972272103281_2887798897915239700_n-1-585x958.jpg\"\r\n                             data-sizes=\"(max-width: 767px) 585px, 585px\">\r\n                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n            <\/div>\r\n            <div class=\"pcbg-content\">\r\n                <div class=\"pcbg-content-flex\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/el-viaje-sin-regreso-la-misteriosa-ruta-que-termino-con-varios-hombres-asesinados-en-distintos-municipios-de-antioquia\/\" title=\"El viaje sin regreso: la misteriosa ruta que termin\u00f3 con varios hombres asesinados en distintos municipios de Antioquia\"><\/a>\r\n                    <div class=\"pcbg-content-inner bgcontent-block\">\r\n                        <a href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/el-viaje-sin-regreso-la-misteriosa-ruta-que-termino-con-varios-hombres-asesinados-en-distintos-municipios-de-antioquia\/\" title=\"El viaje sin regreso: la misteriosa ruta que termin\u00f3 con varios hombres asesinados en distintos municipios de Antioquia\"\r\n                           class=\"pcbg-bgoverlaytext item-hover\"><\/a>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"pcbg-heading item-hover\">\r\n                                <h3 class=\"pcbg-title\">\r\n                                    <a href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/el-viaje-sin-regreso-la-misteriosa-ruta-que-termino-con-varios-hombres-asesinados-en-distintos-municipios-de-antioquia\/\">\r\n                                        El viaje sin regreso: la misteriosa ruta que termin\u00f3 con varios hombres asesinados en distintos municipios de Antioquia                                    <\/a>\r\n                                <\/h3>\r\n                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"grid-post-box-meta pcbg-meta item-hover\">\r\n                                <div class=\"pcbg-meta-desc\">\r\n\t\t\t\t\t\t\t\t\t                                        <span class=\"bg-date-author author-italic author vcard\">\r\n\t\t\t\t\t\t\t\t\t\tby <a class=\"url fn n\"\r\n                                                                                                href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a>\r\n\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                        <span class=\"bg-date\"><time class=\"entry-date published\" datetime=\"2026-07-09T10:37:35-05:00\">julio 9, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <\/div>\r\n\t\t\t\t\t\t\t\t                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n<div class=\"penci-bgitem\">\r\n    <div class=\"penci-bgitin\">\r\n        <div class=\"penci-bgmain\">\r\n            <div class=\"pcbg-thumb\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <div class=\"pcbg-thumbin\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-mujer-salio-a-caminar-con-su-suegra-y-fueron-embestidas-por-una-camioneta-la-familia-de-la-joven-que-murio-atropellada-en-la-via-niquia-girardota-busca-al-conductor-que-huyo\/\" title=\"Una mujer sali\u00f3 a caminar con su suegra y fueron embestidas por una camioneta; la Familia de la joven que muri\u00f3 atropellada en la v\u00eda Niqu\u00eda-Girardota busca al conductor que huy\u00f3\u2026\"><\/a>\r\n\t\t\t\t\t                        <div class=\"penci-image-holder penci-lazy\"                             data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/740881013_1011513078407653_5440553282796469660_n-585x732.jpg\" data_bg_hidpi=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/740881013_1011513078407653_5440553282796469660_n-585x732.jpg\"\r\n                             data-sizes=\"(max-width: 767px) 585px, 585px\">\r\n                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n            <\/div>\r\n            <div class=\"pcbg-content\">\r\n                <div class=\"pcbg-content-flex\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-mujer-salio-a-caminar-con-su-suegra-y-fueron-embestidas-por-una-camioneta-la-familia-de-la-joven-que-murio-atropellada-en-la-via-niquia-girardota-busca-al-conductor-que-huyo\/\" title=\"Una mujer sali\u00f3 a caminar con su suegra y fueron embestidas por una camioneta; la Familia de la joven que muri\u00f3 atropellada en la v\u00eda Niqu\u00eda-Girardota busca al conductor que huy\u00f3\u2026\"><\/a>\r\n                    <div class=\"pcbg-content-inner bgcontent-block\">\r\n                        <a href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-mujer-salio-a-caminar-con-su-suegra-y-fueron-embestidas-por-una-camioneta-la-familia-de-la-joven-que-murio-atropellada-en-la-via-niquia-girardota-busca-al-conductor-que-huyo\/\" title=\"Una mujer sali\u00f3 a caminar con su suegra y fueron embestidas por una camioneta; la Familia de la joven que muri\u00f3 atropellada en la v\u00eda Niqu\u00eda-Girardota busca al conductor que huy\u00f3\u2026\"\r\n                           class=\"pcbg-bgoverlaytext item-hover\"><\/a>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"pcbg-heading item-hover\">\r\n                                <h3 class=\"pcbg-title\">\r\n                                    <a href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-mujer-salio-a-caminar-con-su-suegra-y-fueron-embestidas-por-una-camioneta-la-familia-de-la-joven-que-murio-atropellada-en-la-via-niquia-girardota-busca-al-conductor-que-huyo\/\">\r\n                                        Una mujer sali\u00f3 a caminar con su suegra y fueron embestidas por una camioneta; la Familia de la joven que muri\u00f3 atropellada en la v\u00eda Niqu\u00eda-Girardota busca al conductor que huy\u00f3\u2026                                    <\/a>\r\n                                <\/h3>\r\n                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"grid-post-box-meta pcbg-meta item-hover\">\r\n                                <div class=\"pcbg-meta-desc\">\r\n\t\t\t\t\t\t\t\t\t                                        <span class=\"bg-date-author author-italic author vcard\">\r\n\t\t\t\t\t\t\t\t\t\tby <a class=\"url fn n\"\r\n                                                                                                href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a>\r\n\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                        <span class=\"bg-date\"><time class=\"entry-date published\" datetime=\"2026-07-09T10:21:31-05:00\">julio 9, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <\/div>\r\n\t\t\t\t\t\t\t\t                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n<\/div>                <\/div>\r\n\t\t\t\t            <\/div>\r\n        <\/div>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-690acf6 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"690acf6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct  elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f2000a7\" data-id=\"f2000a7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c7c14ab elementor-widget elementor-widget-html\" data-id=\"c7c14ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div style='text-align: center;'><a style='display: inline-block; max-width: 728px;' href='https:\/\/1.envato.market\/YYJ4P' target='_blank'><img src='https:\/\/soledaddemo.pencidesign.net\/wp-content\/uploads\/2021\/08\/banner-home.jpg' width='728' height='90' alt='banner'><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-326f7de elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"326f7de\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct  elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1529704\" data-id=\"1529704\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-420470c elementor-widget elementor-widget-penci-big-grid\" data-id=\"420470c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"penci-big-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"penci-clearfix penci-biggrid-wrapper penci-bgrid-based-post penci-bgrid-style-10 pcbg-ficonpo-top-right pcbg-reiconpo-top-left penci-bgrid-content-on pencibg-imageh-zoom-in pencibg-texth-none pencibg-textani-movetop penci-bgrid-monecol penci-bgrid-msameh textop hide-mdesc\">\r\n\t\t\t        <div class=\"penci-border-arrow penci-homepage-title penci-home-latest-posts style-18 pcalign-center pciconp-right pcicon-right block-title-icon-left\">\r\n            <h3 class=\"inner-arrow\">\r\n                <span>\r\n                    <span>Featured Videos In This Week<\/a>                <\/span>\r\n            <\/h3>\r\n\t\t\t        <\/div>\r\n\t\t            <div class=\"penci-clearfix penci-biggrid penci-bgstyle-10 penci-bgel\">\r\n                <div class=\"penci-biggrid-inner default\">\r\n\t\t\t\t\t<div class=\"penci-big-grid-ajax-data\"><div class=\"penci-clearfix penci-biggrid-data penci-dblock penci-fixh\"><div class=\"penci-bgitem bgitem-1\">\r\n    <div class=\"penci-bgitin\">\r\n        <div class=\"penci-bgmain\">\r\n            <div class=\"pcbg-thumb\">\r\n\t\t\t\t\t\t\t\t                <div class=\"pcbg-thumbin\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/sintio-un-extrano-olor-abrio-el-capo-y-su-carro-termino-envuelto-en-llamas-en-las-palmas-medellin-sin-embargo-varios-conductores-se-bajaron-y-le-facilitaron-el-extintor\/\" title=\"Sinti\u00f3 un extra\u00f1o olor, abri\u00f3 el cap\u00f3 y su carro termin\u00f3 envuelto en llamas en Las Palmas, Medell\u00edn; sin embargo, varios conductores se bajaron y le facilitaron el extintor\"><\/a>\r\n\t\t\t\t\t                        <div class=\"penci-image-holder penci-lazy\"                             data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/742254221_1057317513437214_5211492233948717152_n-585x498.jpg\" data_bg_hidpi=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/742254221_1057317513437214_5211492233948717152_n-585x498.jpg\"\r\n                             data-sizes=\"(max-width: 767px) 585px, 585px\">\r\n                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n            <\/div>\r\n            <div class=\"pcbg-content\">\r\n                <div class=\"pcbg-content-flex\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/sintio-un-extrano-olor-abrio-el-capo-y-su-carro-termino-envuelto-en-llamas-en-las-palmas-medellin-sin-embargo-varios-conductores-se-bajaron-y-le-facilitaron-el-extintor\/\" title=\"Sinti\u00f3 un extra\u00f1o olor, abri\u00f3 el cap\u00f3 y su carro termin\u00f3 envuelto en llamas en Las Palmas, Medell\u00edn; sin embargo, varios conductores se bajaron y le facilitaron el extintor\"><\/a>\r\n                    <div class=\"pcbg-content-inner bgcontent-block\">\r\n                        <a href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/sintio-un-extrano-olor-abrio-el-capo-y-su-carro-termino-envuelto-en-llamas-en-las-palmas-medellin-sin-embargo-varios-conductores-se-bajaron-y-le-facilitaron-el-extintor\/\" title=\"Sinti\u00f3 un extra\u00f1o olor, abri\u00f3 el cap\u00f3 y su carro termin\u00f3 envuelto en llamas en Las Palmas, Medell\u00edn; sin embargo, varios conductores se bajaron y le facilitaron el extintor\"\r\n                           class=\"pcbg-bgoverlaytext active-overlay item-hover\"><\/a>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"pcbg-heading item-hover\">\r\n                                <h3 class=\"pcbg-title\">\r\n                                    <a href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/sintio-un-extrano-olor-abrio-el-capo-y-su-carro-termino-envuelto-en-llamas-en-las-palmas-medellin-sin-embargo-varios-conductores-se-bajaron-y-le-facilitaron-el-extintor\/\">\r\n                                        Sinti\u00f3 un extra\u00f1o olor, abri\u00f3 el cap\u00f3 y su carro termin\u00f3 envuelto en llamas en Las Palmas, Medell\u00edn; sin embargo, varios conductores se bajaron y le facilitaron el extintor                                    <\/a>\r\n                                <\/h3>\r\n                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"grid-post-box-meta pcbg-meta item-hover\">\r\n                                <div class=\"pcbg-meta-desc\">\r\n\t\t\t\t\t\t\t\t\t                                        <span class=\"bg-date-author author-italic author vcard\">\r\n\t\t\t\t\t\t\t\t\t\tby <a class=\"url fn n\"\r\n                                                                                                href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a>\r\n\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                        <span class=\"bg-date\"><time class=\"entry-date published\" datetime=\"2026-07-10T10:45:40-05:00\">julio 10, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <\/div>\r\n\t\t\t\t\t\t\t\t                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n<div class=\"penci-bgitem bgitem-2\">\r\n    <div class=\"penci-bgitin\">\r\n        <div class=\"penci-bgmain\">\r\n            <div class=\"pcbg-thumb\">\r\n\t\t\t\t\t\t\t\t                <div class=\"pcbg-thumbin\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/juez-ordena-a-congresista-yulieth-sanchez-rectificar-senalamientos-contra-dona-gloria-lider-politica-de-bello-antioquia\/\" title=\"Juez ordena a congresista Yulieth S\u00e1nchez rectificar se\u00f1alamientos contra do\u00f1a Gloria, l\u00edder pol\u00edtica de Bello, Antioquia\"><\/a>\r\n\t\t\t\t\t                        <div class=\"penci-image-holder penci-lazy\"                             data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/742129508_1072133355381651_3020601880222902570_n-585x731.jpg\" data_bg_hidpi=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/742129508_1072133355381651_3020601880222902570_n-585x731.jpg\"\r\n                             data-sizes=\"(max-width: 767px) 585px, 585px\">\r\n                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n            <\/div>\r\n            <div class=\"pcbg-content\">\r\n                <div class=\"pcbg-content-flex\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/juez-ordena-a-congresista-yulieth-sanchez-rectificar-senalamientos-contra-dona-gloria-lider-politica-de-bello-antioquia\/\" title=\"Juez ordena a congresista Yulieth S\u00e1nchez rectificar se\u00f1alamientos contra do\u00f1a Gloria, l\u00edder pol\u00edtica de Bello, Antioquia\"><\/a>\r\n                    <div class=\"pcbg-content-inner bgcontent-block\">\r\n                        <a href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/juez-ordena-a-congresista-yulieth-sanchez-rectificar-senalamientos-contra-dona-gloria-lider-politica-de-bello-antioquia\/\" title=\"Juez ordena a congresista Yulieth S\u00e1nchez rectificar se\u00f1alamientos contra do\u00f1a Gloria, l\u00edder pol\u00edtica de Bello, Antioquia\"\r\n                           class=\"pcbg-bgoverlaytext active-overlay item-hover\"><\/a>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"pcbg-heading item-hover\">\r\n                                <h3 class=\"pcbg-title\">\r\n                                    <a href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/juez-ordena-a-congresista-yulieth-sanchez-rectificar-senalamientos-contra-dona-gloria-lider-politica-de-bello-antioquia\/\">\r\n                                        Juez ordena a congresista Yulieth S\u00e1nchez rectificar se\u00f1alamientos contra do\u00f1a Gloria, l\u00edder pol\u00edtica de Bello, Antioquia                                    <\/a>\r\n                                <\/h3>\r\n                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"grid-post-box-meta pcbg-meta item-hover\">\r\n                                <div class=\"pcbg-meta-desc\">\r\n\t\t\t\t\t\t\t\t\t                                        <span class=\"bg-date-author author-italic author vcard\">\r\n\t\t\t\t\t\t\t\t\t\tby <a class=\"url fn n\"\r\n                                                                                                href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a>\r\n\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                        <span class=\"bg-date\"><time class=\"entry-date published\" datetime=\"2026-07-10T10:28:03-05:00\">julio 10, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <\/div>\r\n\t\t\t\t\t\t\t\t                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n<div class=\"penci-bgitem bgitem-3\">\r\n    <div class=\"penci-bgitin\">\r\n        <div class=\"penci-bgmain\">\r\n            <div class=\"pcbg-thumb\">\r\n\t\t\t\t\t\t\t\t                <div class=\"pcbg-thumbin\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-vecina-alerto-al-123-y-desato-el-operativo-que-termino-con-varios-jovenes-capturados-por-secuestro-en-robledo-medellin\/\" title=\"Una vecina alert\u00f3 al 123 y desat\u00f3 el operativo que termin\u00f3 con varios j\u00f3venes capturados por secuestro en Robledo, Medell\u00edn\"><\/a>\r\n\t\t\t\t\t                        <div class=\"penci-image-holder penci-lazy\"                             data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/741196587_1071902635404723_3685621252934489457_n-585x390.jpg\" data_bg_hidpi=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/741196587_1071902635404723_3685621252934489457_n-585x390.jpg\"\r\n                             data-sizes=\"(max-width: 767px) 585px, 585px\">\r\n                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n            <\/div>\r\n            <div class=\"pcbg-content\">\r\n                <div class=\"pcbg-content-flex\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-vecina-alerto-al-123-y-desato-el-operativo-que-termino-con-varios-jovenes-capturados-por-secuestro-en-robledo-medellin\/\" title=\"Una vecina alert\u00f3 al 123 y desat\u00f3 el operativo que termin\u00f3 con varios j\u00f3venes capturados por secuestro en Robledo, Medell\u00edn\"><\/a>\r\n                    <div class=\"pcbg-content-inner bgcontent-block\">\r\n                        <a href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-vecina-alerto-al-123-y-desato-el-operativo-que-termino-con-varios-jovenes-capturados-por-secuestro-en-robledo-medellin\/\" title=\"Una vecina alert\u00f3 al 123 y desat\u00f3 el operativo que termin\u00f3 con varios j\u00f3venes capturados por secuestro en Robledo, Medell\u00edn\"\r\n                           class=\"pcbg-bgoverlaytext active-overlay item-hover\"><\/a>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"pcbg-heading item-hover\">\r\n                                <h3 class=\"pcbg-title\">\r\n                                    <a href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-vecina-alerto-al-123-y-desato-el-operativo-que-termino-con-varios-jovenes-capturados-por-secuestro-en-robledo-medellin\/\">\r\n                                        Una vecina alert\u00f3 al 123 y desat\u00f3 el operativo que termin\u00f3 con varios j\u00f3venes capturados por secuestro en Robledo, Medell\u00edn                                    <\/a>\r\n                                <\/h3>\r\n                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"grid-post-box-meta pcbg-meta item-hover\">\r\n                                <div class=\"pcbg-meta-desc\">\r\n\t\t\t\t\t\t\t\t\t                                        <span class=\"bg-date-author author-italic author vcard\">\r\n\t\t\t\t\t\t\t\t\t\tby <a class=\"url fn n\"\r\n                                                                                                href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a>\r\n\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                        <span class=\"bg-date\"><time class=\"entry-date published\" datetime=\"2026-07-09T11:13:37-05:00\">julio 9, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <\/div>\r\n\t\t\t\t\t\t\t\t                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n<div class=\"penci-bgitem pcbg-big-item bgitem-4\">\r\n    <div class=\"penci-bgitin\">\r\n        <div class=\"penci-bgmain\">\r\n            <div class=\"pcbg-thumb\">\r\n\t\t\t\t\t\t\t\t                <div class=\"pcbg-thumbin\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/cayeron-los-cazadores-de-cadenas-de-oro-capturan-a-dos-presuntos-atracadores-vinculados-a-cinco-violentos-robos-en-medellin\/\" title=\"\u00a1Cayeron los cazadores de cadenas de oro! Capturan a dos presuntos atracadores vinculados a cinco violentos robos en Medell\u00edn\"><\/a>\r\n\t\t\t\t\t                        <div class=\"penci-image-holder penci-lazy\"                             data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/740628751_1012735958165830_7922623203508311772_n.jpg\" data_bg_hidpi=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/740628751_1012735958165830_7922623203508311772_n-585x329.jpg\"\r\n                             data-sizes=\"(max-width: 767px) 585px, 1170px\">\r\n                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n            <\/div>\r\n            <div class=\"pcbg-content\">\r\n                <div class=\"pcbg-content-flex\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/cayeron-los-cazadores-de-cadenas-de-oro-capturan-a-dos-presuntos-atracadores-vinculados-a-cinco-violentos-robos-en-medellin\/\" title=\"\u00a1Cayeron los cazadores de cadenas de oro! Capturan a dos presuntos atracadores vinculados a cinco violentos robos en Medell\u00edn\"><\/a>\r\n                    <div class=\"pcbg-content-inner bgcontent-block\">\r\n                        <a href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/cayeron-los-cazadores-de-cadenas-de-oro-capturan-a-dos-presuntos-atracadores-vinculados-a-cinco-violentos-robos-en-medellin\/\" title=\"\u00a1Cayeron los cazadores de cadenas de oro! Capturan a dos presuntos atracadores vinculados a cinco violentos robos en Medell\u00edn\"\r\n                           class=\"pcbg-bgoverlaytext active-overlay item-hover\"><\/a>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"pcbg-heading item-hover\">\r\n                                <h3 class=\"pcbg-title\">\r\n                                    <a href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/cayeron-los-cazadores-de-cadenas-de-oro-capturan-a-dos-presuntos-atracadores-vinculados-a-cinco-violentos-robos-en-medellin\/\">\r\n                                        \u00a1Cayeron los cazadores de cadenas de oro! Capturan a dos presuntos atracadores vinculados a cinco violentos robos en Medell\u00edn                                    <\/a>\r\n                                <\/h3>\r\n                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"grid-post-box-meta pcbg-meta item-hover\">\r\n                                <div class=\"pcbg-meta-desc\">\r\n\t\t\t\t\t\t\t\t\t                                        <span class=\"bg-date-author author-italic author vcard\">\r\n\t\t\t\t\t\t\t\t\t\tby <a class=\"url fn n\"\r\n                                                                                                href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a>\r\n\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                        <span class=\"bg-date\"><time class=\"entry-date published\" datetime=\"2026-07-09T10:38:44-05:00\">julio 9, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <\/div>\r\n\t\t\t\t\t\t\t\t                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n<div class=\"penci-bgitem pcbg-big-item bgitem-0\">\r\n    <div class=\"penci-bgitin\">\r\n        <div class=\"penci-bgmain\">\r\n            <div class=\"pcbg-thumb\">\r\n\t\t\t\t\t\t\t\t                <div class=\"pcbg-thumbin\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/el-viaje-sin-regreso-la-misteriosa-ruta-que-termino-con-varios-hombres-asesinados-en-distintos-municipios-de-antioquia\/\" title=\"El viaje sin regreso: la misteriosa ruta que termin\u00f3 con varios hombres asesinados en distintos municipios de Antioquia\"><\/a>\r\n\t\t\t\t\t                        <div class=\"penci-image-holder penci-lazy\"                             data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/740601678_975972272103281_2887798897915239700_n-1-1170x1915.jpg\" data_bg_hidpi=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/740601678_975972272103281_2887798897915239700_n-1-585x958.jpg\"\r\n                             data-sizes=\"(max-width: 767px) 585px, 1170px\">\r\n                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n            <\/div>\r\n            <div class=\"pcbg-content\">\r\n                <div class=\"pcbg-content-flex\">\r\n                    <a class=\"pcbg-bgoverlay\"\r\n                       href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/el-viaje-sin-regreso-la-misteriosa-ruta-que-termino-con-varios-hombres-asesinados-en-distintos-municipios-de-antioquia\/\" title=\"El viaje sin regreso: la misteriosa ruta que termin\u00f3 con varios hombres asesinados en distintos municipios de Antioquia\"><\/a>\r\n                    <div class=\"pcbg-content-inner bgcontent-block\">\r\n                        <a href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/el-viaje-sin-regreso-la-misteriosa-ruta-que-termino-con-varios-hombres-asesinados-en-distintos-municipios-de-antioquia\/\" title=\"El viaje sin regreso: la misteriosa ruta que termin\u00f3 con varios hombres asesinados en distintos municipios de Antioquia\"\r\n                           class=\"pcbg-bgoverlaytext active-overlay item-hover\"><\/a>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"pcbg-heading item-hover\">\r\n                                <h3 class=\"pcbg-title\">\r\n                                    <a href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/el-viaje-sin-regreso-la-misteriosa-ruta-que-termino-con-varios-hombres-asesinados-en-distintos-municipios-de-antioquia\/\">\r\n                                        El viaje sin regreso: la misteriosa ruta que termin\u00f3 con varios hombres asesinados en distintos municipios de Antioquia                                    <\/a>\r\n                                <\/h3>\r\n                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                            <div class=\"grid-post-box-meta pcbg-meta item-hover\">\r\n                                <div class=\"pcbg-meta-desc\">\r\n\t\t\t\t\t\t\t\t\t                                        <span class=\"bg-date-author author-italic author vcard\">\r\n\t\t\t\t\t\t\t\t\t\tby <a class=\"url fn n\"\r\n                                                                                                href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a>\r\n\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                        <span class=\"bg-date\"><time class=\"entry-date published\" datetime=\"2026-07-09T10:37:35-05:00\">julio 9, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <\/div>\r\n\t\t\t\t\t\t\t\t                            <\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n<\/div><\/div>                <\/div>\r\n\t\t\t\t            <\/div>\r\n        <\/div>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"penci-section penci-disSticky penci-structure-22 elementor-section elementor-top-section elementor-element elementor-element-50aa112 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"50aa112\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"penci-ercol-33 penci-ercol-order-1 penci-sticky-sb penci-sidebarSC elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c2a42aa\" data-id=\"c2a42aa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35177eb elementor-widget elementor-widget-penci-recent-posts\" data-id=\"35177eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;rp_rows_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]}}\" data-widget_type=\"penci-recent-posts.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"penci-block-vc penci_recent-posts-sc\">\r\n\t\t\t        <div class=\"penci-border-arrow penci-homepage-title penci-home-latest-posts style-15 pcalign-center pciconp-right pcicon-right block-title-icon-left\">\r\n            <h3 class=\"inner-arrow\">\r\n                <span>\r\n                    <a href=\"https:\/\/soledaddemo.pencidesign.net\/category\/life-style\/culture\/\">Culture<\/a>                <\/span>\r\n            <\/h3>\r\n\t\t\t        <\/div>\r\n\t\t            <div class=\"penci-block_content\">\r\n                <ul id=\"penci-latestwg-9042\"\r\n                    class=\"side-newsfeed penci-feed-2columns penci-2columns-feed\">\r\n\t\t\t\t\t                        <li class=\"penci-feed\">\r\n\t\t\t\t\t\t\t                            <div class=\"side-item\">\r\n\t\t\t\t\t\t\t\t                                    <div class=\"side-image\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                            <a class=\"penci-image-holder penci-lazy small-fix-size\" rel=\"bookmark\"\r\n                                               data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/742254221_1057317513437214_5211492233948717152_n-263x175.jpg\"\r\n                                               href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/sintio-un-extrano-olor-abrio-el-capo-y-su-carro-termino-envuelto-en-llamas-en-las-palmas-medellin-sin-embargo-varios-conductores-se-bajaron-y-le-facilitaron-el-extintor\/\"\r\n                                               title=\"Sinti\u00f3 un extra\u00f1o olor, abri\u00f3 el cap\u00f3 y su carro termin\u00f3 envuelto en llamas en Las Palmas, Medell\u00edn; sin embargo, varios conductores se bajaron y le facilitaron el extintor\"><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t                                    <\/div>\r\n\t\t\t\t\t\t\t\t                                <div class=\"side-item-text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n                                    <h4 class=\"side-title-post\">\r\n                                        <a href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/sintio-un-extrano-olor-abrio-el-capo-y-su-carro-termino-envuelto-en-llamas-en-las-palmas-medellin-sin-embargo-varios-conductores-se-bajaron-y-le-facilitaron-el-extintor\/\" rel=\"bookmark\" title=\"Sinti\u00f3 un extra\u00f1o olor, abri\u00f3 el cap\u00f3 y su carro termin\u00f3 envuelto en llamas en Las Palmas, Medell\u00edn; sin embargo, varios conductores se bajaron y le facilitaron el extintor\">\r\n\t\t\t\t\t\t\t\t\t\t\tSinti\u00f3 un extra\u00f1o olor, abri\u00f3 el cap\u00f3 y su carro termin\u00f3 envuelto en llamas en Las Palmas, Medell\u00edn; sin embargo, varios conductores se bajaron y le facilitaron el extintor                                        <\/a>\r\n                                    <\/h4>\r\n\t\t\t\t\t\t\t\t\t                                        <div class=\"grid-post-box-meta penci-side-item-meta pcsnmt-below\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                                <span class=\"side-item-meta side-wdate\"><time class=\"entry-date published\" datetime=\"2026-07-10T10:45:40-05:00\">julio 10, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                        <\/div>\r\n\t\t\t\t\t\t\t\t\t                                <\/div>\r\n                            <\/div>\r\n                        <\/li>\r\n\t\t\t\t\t\t                        <li class=\"penci-feed\">\r\n\t\t\t\t\t\t\t                            <div class=\"side-item\">\r\n\t\t\t\t\t\t\t\t                                    <div class=\"side-image\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                            <a class=\"penci-image-holder penci-lazy small-fix-size\" rel=\"bookmark\"\r\n                                               data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/742129508_1072133355381651_3020601880222902570_n-263x175.jpg\"\r\n                                               href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/juez-ordena-a-congresista-yulieth-sanchez-rectificar-senalamientos-contra-dona-gloria-lider-politica-de-bello-antioquia\/\"\r\n                                               title=\"Juez ordena a congresista Yulieth S\u00e1nchez rectificar se\u00f1alamientos contra do\u00f1a Gloria, l\u00edder pol\u00edtica de Bello, Antioquia\"><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t                                    <\/div>\r\n\t\t\t\t\t\t\t\t                                <div class=\"side-item-text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n                                    <h4 class=\"side-title-post\">\r\n                                        <a href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/juez-ordena-a-congresista-yulieth-sanchez-rectificar-senalamientos-contra-dona-gloria-lider-politica-de-bello-antioquia\/\" rel=\"bookmark\" title=\"Juez ordena a congresista Yulieth S\u00e1nchez rectificar se\u00f1alamientos contra do\u00f1a Gloria, l\u00edder pol\u00edtica de Bello, Antioquia\">\r\n\t\t\t\t\t\t\t\t\t\t\tJuez ordena a congresista Yulieth S\u00e1nchez rectificar se\u00f1alamientos contra do\u00f1a Gloria, l\u00edder pol\u00edtica de Bello, Antioquia                                        <\/a>\r\n                                    <\/h4>\r\n\t\t\t\t\t\t\t\t\t                                        <div class=\"grid-post-box-meta penci-side-item-meta pcsnmt-below\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                                <span class=\"side-item-meta side-wdate\"><time class=\"entry-date published\" datetime=\"2026-07-10T10:28:03-05:00\">julio 10, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                        <\/div>\r\n\t\t\t\t\t\t\t\t\t                                <\/div>\r\n                            <\/div>\r\n                        <\/li>\r\n\t\t\t\t\t\t                        <li class=\"penci-feed\">\r\n\t\t\t\t\t\t\t                            <div class=\"side-item\">\r\n\t\t\t\t\t\t\t\t                                    <div class=\"side-image\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                            <a class=\"penci-image-holder penci-lazy small-fix-size\" rel=\"bookmark\"\r\n                                               data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/741196587_1071902635404723_3685621252934489457_n-263x175.jpg\"\r\n                                               href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-vecina-alerto-al-123-y-desato-el-operativo-que-termino-con-varios-jovenes-capturados-por-secuestro-en-robledo-medellin\/\"\r\n                                               title=\"Una vecina alert\u00f3 al 123 y desat\u00f3 el operativo que termin\u00f3 con varios j\u00f3venes capturados por secuestro en Robledo, Medell\u00edn\"><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t                                    <\/div>\r\n\t\t\t\t\t\t\t\t                                <div class=\"side-item-text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n                                    <h4 class=\"side-title-post\">\r\n                                        <a href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-vecina-alerto-al-123-y-desato-el-operativo-que-termino-con-varios-jovenes-capturados-por-secuestro-en-robledo-medellin\/\" rel=\"bookmark\" title=\"Una vecina alert\u00f3 al 123 y desat\u00f3 el operativo que termin\u00f3 con varios j\u00f3venes capturados por secuestro en Robledo, Medell\u00edn\">\r\n\t\t\t\t\t\t\t\t\t\t\tUna vecina alert\u00f3 al 123 y desat\u00f3 el operativo que termin\u00f3 con varios j\u00f3venes capturados por secuestro en Robledo, Medell\u00edn                                        <\/a>\r\n                                    <\/h4>\r\n\t\t\t\t\t\t\t\t\t                                        <div class=\"grid-post-box-meta penci-side-item-meta pcsnmt-below\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                                <span class=\"side-item-meta side-wdate\"><time class=\"entry-date published\" datetime=\"2026-07-09T11:13:37-05:00\">julio 9, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                        <\/div>\r\n\t\t\t\t\t\t\t\t\t                                <\/div>\r\n                            <\/div>\r\n                        <\/li>\r\n\t\t\t\t\t\t                        <li class=\"penci-feed\">\r\n\t\t\t\t\t\t\t                            <div class=\"side-item\">\r\n\t\t\t\t\t\t\t\t                                    <div class=\"side-image\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                            <a class=\"penci-image-holder penci-lazy small-fix-size\" rel=\"bookmark\"\r\n                                               data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/740628751_1012735958165830_7922623203508311772_n-263x175.jpg\"\r\n                                               href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/cayeron-los-cazadores-de-cadenas-de-oro-capturan-a-dos-presuntos-atracadores-vinculados-a-cinco-violentos-robos-en-medellin\/\"\r\n                                               title=\"\u00a1Cayeron los cazadores de cadenas de oro! Capturan a dos presuntos atracadores vinculados a cinco violentos robos en Medell\u00edn\"><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t                                    <\/div>\r\n\t\t\t\t\t\t\t\t                                <div class=\"side-item-text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n                                    <h4 class=\"side-title-post\">\r\n                                        <a href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/cayeron-los-cazadores-de-cadenas-de-oro-capturan-a-dos-presuntos-atracadores-vinculados-a-cinco-violentos-robos-en-medellin\/\" rel=\"bookmark\" title=\"\u00a1Cayeron los cazadores de cadenas de oro! Capturan a dos presuntos atracadores vinculados a cinco violentos robos en Medell\u00edn\">\r\n\t\t\t\t\t\t\t\t\t\t\t\u00a1Cayeron los cazadores de cadenas de oro! Capturan a dos presuntos atracadores vinculados a cinco violentos robos en Medell\u00edn                                        <\/a>\r\n                                    <\/h4>\r\n\t\t\t\t\t\t\t\t\t                                        <div class=\"grid-post-box-meta penci-side-item-meta pcsnmt-below\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                                <span class=\"side-item-meta side-wdate\"><time class=\"entry-date published\" datetime=\"2026-07-09T10:38:44-05:00\">julio 9, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                        <\/div>\r\n\t\t\t\t\t\t\t\t\t                                <\/div>\r\n                            <\/div>\r\n                        <\/li>\r\n\t\t\t\t\t\t                        <li class=\"penci-feed\">\r\n\t\t\t\t\t\t\t                            <div class=\"side-item\">\r\n\t\t\t\t\t\t\t\t                                    <div class=\"side-image\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                            <a class=\"penci-image-holder penci-lazy small-fix-size\" rel=\"bookmark\"\r\n                                               data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/740601678_975972272103281_2887798897915239700_n-1-263x175.jpg\"\r\n                                               href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/el-viaje-sin-regreso-la-misteriosa-ruta-que-termino-con-varios-hombres-asesinados-en-distintos-municipios-de-antioquia\/\"\r\n                                               title=\"El viaje sin regreso: la misteriosa ruta que termin\u00f3 con varios hombres asesinados en distintos municipios de Antioquia\"><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t                                    <\/div>\r\n\t\t\t\t\t\t\t\t                                <div class=\"side-item-text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n                                    <h4 class=\"side-title-post\">\r\n                                        <a href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/el-viaje-sin-regreso-la-misteriosa-ruta-que-termino-con-varios-hombres-asesinados-en-distintos-municipios-de-antioquia\/\" rel=\"bookmark\" title=\"El viaje sin regreso: la misteriosa ruta que termin\u00f3 con varios hombres asesinados en distintos municipios de Antioquia\">\r\n\t\t\t\t\t\t\t\t\t\t\tEl viaje sin regreso: la misteriosa ruta que termin\u00f3 con varios hombres asesinados en distintos municipios de Antioquia                                        <\/a>\r\n                                    <\/h4>\r\n\t\t\t\t\t\t\t\t\t                                        <div class=\"grid-post-box-meta penci-side-item-meta pcsnmt-below\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                                <span class=\"side-item-meta side-wdate\"><time class=\"entry-date published\" datetime=\"2026-07-09T10:37:35-05:00\">julio 9, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                        <\/div>\r\n\t\t\t\t\t\t\t\t\t                                <\/div>\r\n                            <\/div>\r\n                        <\/li>\r\n\t\t\t\t\t\t                        <li class=\"penci-feed\">\r\n\t\t\t\t\t\t\t                            <div class=\"side-item\">\r\n\t\t\t\t\t\t\t\t                                    <div class=\"side-image\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                            <a class=\"penci-image-holder penci-lazy small-fix-size\" rel=\"bookmark\"\r\n                                               data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/740881013_1011513078407653_5440553282796469660_n-263x175.jpg\"\r\n                                               href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-mujer-salio-a-caminar-con-su-suegra-y-fueron-embestidas-por-una-camioneta-la-familia-de-la-joven-que-murio-atropellada-en-la-via-niquia-girardota-busca-al-conductor-que-huyo\/\"\r\n                                               title=\"Una mujer sali\u00f3 a caminar con su suegra y fueron embestidas por una camioneta; la Familia de la joven que muri\u00f3 atropellada en la v\u00eda Niqu\u00eda-Girardota busca al conductor que huy\u00f3\u2026\"><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t                                    <\/div>\r\n\t\t\t\t\t\t\t\t                                <div class=\"side-item-text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n                                    <h4 class=\"side-title-post\">\r\n                                        <a href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-mujer-salio-a-caminar-con-su-suegra-y-fueron-embestidas-por-una-camioneta-la-familia-de-la-joven-que-murio-atropellada-en-la-via-niquia-girardota-busca-al-conductor-que-huyo\/\" rel=\"bookmark\" title=\"Una mujer sali\u00f3 a caminar con su suegra y fueron embestidas por una camioneta; la Familia de la joven que muri\u00f3 atropellada en la v\u00eda Niqu\u00eda-Girardota busca al conductor que huy\u00f3\u2026\">\r\n\t\t\t\t\t\t\t\t\t\t\tUna mujer sali\u00f3 a caminar con su suegra y fueron embestidas por una camioneta; la Familia de la joven que muri\u00f3 atropellada en la v\u00eda Niqu\u00eda-Girardota busca al conductor que huy\u00f3\u2026                                        <\/a>\r\n                                    <\/h4>\r\n\t\t\t\t\t\t\t\t\t                                        <div class=\"grid-post-box-meta penci-side-item-meta pcsnmt-below\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                                <span class=\"side-item-meta side-wdate\"><time class=\"entry-date published\" datetime=\"2026-07-09T10:21:31-05:00\">julio 9, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                        <\/div>\r\n\t\t\t\t\t\t\t\t\t                                <\/div>\r\n                            <\/div>\r\n                        <\/li>\r\n\t\t\t\t\t\t                <\/ul>\r\n\t\t\t\t            <\/div>\r\n        <\/div>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"penci-ercol-66 penci-ercol-order-2 penci-sticky-ct  elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-3ff691d\" data-id=\"3ff691d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab4f9b8 elementor-widget elementor-widget-penci-featured-cat\" data-id=\"ab4f9b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"penci-featured-cat.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div id=\"pencifeatured_cat_55258\" class=\"penci-featured-cat-sc\">\r\n\t\t\t\t                    <section class=\"home-featured-cat mag-cat-style-10\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t                            <div class=\"penci-border-arrow penci-homepage-title penci-magazine-title style-13 pcalign-left pciconp-right pcicon-right\">\r\n                                <h3 class=\"inner-arrow\">\r\n                                    <span>\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/soledaddemo.pencidesign.net\/category\/life-style\/style\/\">Latest in Style<\/a>                                    <\/span>\r\n                                <\/h3>\r\n\t\t\t\t\t\t\t\t                            <\/div>\r\n\t\t\t\t\t\t                        <div class=\"home-featured-cat-wrapper\">\r\n                            <div class=\"home-featured-cat-content pwf-id-default style-10\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n<div class=\"mag-post-box hentry first-post\">\r\n    <div class=\"magcat-thumb\">\r\n\t\t\t\t            <a class=\"penci-image-holder penci-lazy\"\r\n               data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/742254221_1057317513437214_5211492233948717152_n-585x390.jpg\"\r\n               href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/sintio-un-extrano-olor-abrio-el-capo-y-su-carro-termino-envuelto-en-llamas-en-las-palmas-medellin-sin-embargo-varios-conductores-se-bajaron-y-le-facilitaron-el-extintor\/\" title=\"Sinti\u00f3 un extra\u00f1o olor, abri\u00f3 el cap\u00f3 y su carro termin\u00f3 envuelto en llamas en Las Palmas, Medell\u00edn; sin embargo, varios conductores se bajaron y le facilitaron el extintor\">\r\n            <\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t    <\/div>\r\n    <div class=\"magcat-detail\">\r\n\t\t        <div class=\"mag-header\">            <h3 class=\"magcat-titlte entry-title\"><a\r\n                        href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/sintio-un-extrano-olor-abrio-el-capo-y-su-carro-termino-envuelto-en-llamas-en-las-palmas-medellin-sin-embargo-varios-conductores-se-bajaron-y-le-facilitaron-el-extintor\/\">Sinti\u00f3 un extra\u00f1o olor, abri\u00f3 el cap\u00f3 y su carro termin\u00f3 envuelto en llamas en Las Palmas, Medell\u00edn; sin embargo, varios conductores se bajaron y le facilitaron el extintor<\/a>\r\n            <\/h3>\r\n\t\t\t                <div class=\"grid-post-box-meta mag-meta\">\r\n\t\t\t\t\t                        <span class=\"featc-author author-italic author vcard\">by <a\r\n                                    class=\"url fn n\"\r\n                                    href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\r\n\t\t\t\t\t\t\t\t\t\t                        <span class=\"featc-date\"><time class=\"entry-date published\" datetime=\"2026-07-10T10:45:40-05:00\">julio 10, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <\/div>\r\n\t\t\t\t\t\t<\/div>\t\t            <div class=\"mag-excerpt entry-content\">\r\n\t\t\t\t<p>Prensapaisa.com La ma\u00f1ana de este viernes comenz\u00f3 con largas filas de veh\u00edculos sobre la avenida Las Palmas, una de las principales v\u00edas de ingreso a &#8230;<\/p>\n            <\/div>\r\n\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">by <a class=\"url fn n\" href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2026-07-10T10:45:40-05:00\">julio 10, 2026<\/time>\t\t<\/div>\n\t\t    <\/div>\r\n<\/div>\r\n\r\n<div class=\"mag-post-box hentry first-post\">\r\n    <div class=\"magcat-thumb\">\r\n\t\t\t\t            <a class=\"penci-image-holder penci-lazy\"\r\n               data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/742129508_1072133355381651_3020601880222902570_n-585x390.jpg\"\r\n               href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/juez-ordena-a-congresista-yulieth-sanchez-rectificar-senalamientos-contra-dona-gloria-lider-politica-de-bello-antioquia\/\" title=\"Juez ordena a congresista Yulieth S\u00e1nchez rectificar se\u00f1alamientos contra do\u00f1a Gloria, l\u00edder pol\u00edtica de Bello, Antioquia\">\r\n            <\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t    <\/div>\r\n    <div class=\"magcat-detail\">\r\n\t\t        <div class=\"mag-header\">            <h3 class=\"magcat-titlte entry-title\"><a\r\n                        href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/juez-ordena-a-congresista-yulieth-sanchez-rectificar-senalamientos-contra-dona-gloria-lider-politica-de-bello-antioquia\/\">Juez ordena a congresista Yulieth S\u00e1nchez rectificar se\u00f1alamientos contra do\u00f1a Gloria, l\u00edder pol\u00edtica de Bello, Antioquia<\/a>\r\n            <\/h3>\r\n\t\t\t                <div class=\"grid-post-box-meta mag-meta\">\r\n\t\t\t\t\t                        <span class=\"featc-author author-italic author vcard\">by <a\r\n                                    class=\"url fn n\"\r\n                                    href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\r\n\t\t\t\t\t\t\t\t\t\t                        <span class=\"featc-date\"><time class=\"entry-date published\" datetime=\"2026-07-10T10:28:03-05:00\">julio 10, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <\/div>\r\n\t\t\t\t\t\t<\/div>\t\t            <div class=\"mag-excerpt entry-content\">\r\n\t\t\t\t<p>Prensapaisa.com Una controversia pol\u00edtica que comenz\u00f3 durante los escrutinios de las elecciones legislativas termin\u00f3 en los estrados judiciales. Un juez orden\u00f3 a la representante a &#8230;<\/p>\n            <\/div>\r\n\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">by <a class=\"url fn n\" href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2026-07-10T10:28:03-05:00\">julio 10, 2026<\/time>\t\t<\/div>\n\t\t    <\/div>\r\n<\/div>\r\n\r\n<div class=\"mag-post-box hentry\">\r\n    <div class=\"magcat-thumb\">\r\n\t\t\t\t            <a class=\"penci-image-holder penci-lazy small-fix-size\"\r\n               data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/741196587_1071902635404723_3685621252934489457_n-585x390.jpg\"\r\n               href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-vecina-alerto-al-123-y-desato-el-operativo-que-termino-con-varios-jovenes-capturados-por-secuestro-en-robledo-medellin\/\" title=\"Una vecina alert\u00f3 al 123 y desat\u00f3 el operativo que termin\u00f3 con varios j\u00f3venes capturados por secuestro en Robledo, Medell\u00edn\">\r\n            <\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t    <\/div>\r\n    <div class=\"magcat-detail\">\r\n\t\t            <h3 class=\"magcat-titlte entry-title\"><a\r\n                        href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-vecina-alerto-al-123-y-desato-el-operativo-que-termino-con-varios-jovenes-capturados-por-secuestro-en-robledo-medellin\/\">Una vecina alert\u00f3 al 123 y desat\u00f3 el operativo que termin\u00f3 con varios j\u00f3venes capturados por secuestro en Robledo, Medell\u00edn<\/a>\r\n            <\/h3>\r\n\t\t\t                <div class=\"grid-post-box-meta mag-meta\">\r\n\t\t\t\t\t\t\t\t\t\t                        <span class=\"featc-date\"><time class=\"entry-date published\" datetime=\"2026-07-09T11:13:37-05:00\">julio 9, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">by <a class=\"url fn n\" href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2026-07-09T11:13:37-05:00\">julio 9, 2026<\/time>\t\t<\/div>\n\t\t    <\/div>\r\n<\/div>\r\n\r\n<div class=\"mag-post-box hentry\">\r\n    <div class=\"magcat-thumb\">\r\n\t\t\t\t            <a class=\"penci-image-holder penci-lazy small-fix-size\"\r\n               data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/740628751_1012735958165830_7922623203508311772_n-585x390.jpg\"\r\n               href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/cayeron-los-cazadores-de-cadenas-de-oro-capturan-a-dos-presuntos-atracadores-vinculados-a-cinco-violentos-robos-en-medellin\/\" title=\"\u00a1Cayeron los cazadores de cadenas de oro! Capturan a dos presuntos atracadores vinculados a cinco violentos robos en Medell\u00edn\">\r\n            <\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t    <\/div>\r\n    <div class=\"magcat-detail\">\r\n\t\t            <h3 class=\"magcat-titlte entry-title\"><a\r\n                        href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/cayeron-los-cazadores-de-cadenas-de-oro-capturan-a-dos-presuntos-atracadores-vinculados-a-cinco-violentos-robos-en-medellin\/\">\u00a1Cayeron los cazadores de cadenas de oro! Capturan a dos presuntos atracadores vinculados a cinco violentos robos en Medell\u00edn<\/a>\r\n            <\/h3>\r\n\t\t\t                <div class=\"grid-post-box-meta mag-meta\">\r\n\t\t\t\t\t\t\t\t\t\t                        <span class=\"featc-date\"><time class=\"entry-date published\" datetime=\"2026-07-09T10:38:44-05:00\">julio 9, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">by <a class=\"url fn n\" href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2026-07-09T10:38:44-05:00\">julio 9, 2026<\/time>\t\t<\/div>\n\t\t    <\/div>\r\n<\/div>\r\n\r\n<div class=\"mag-post-box hentry\">\r\n    <div class=\"magcat-thumb\">\r\n\t\t\t\t            <a class=\"penci-image-holder penci-lazy small-fix-size\"\r\n               data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/740601678_975972272103281_2887798897915239700_n-1-585x390.jpg\"\r\n               href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/el-viaje-sin-regreso-la-misteriosa-ruta-que-termino-con-varios-hombres-asesinados-en-distintos-municipios-de-antioquia\/\" title=\"El viaje sin regreso: la misteriosa ruta que termin\u00f3 con varios hombres asesinados en distintos municipios de Antioquia\">\r\n            <\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t    <\/div>\r\n    <div class=\"magcat-detail\">\r\n\t\t            <h3 class=\"magcat-titlte entry-title\"><a\r\n                        href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/el-viaje-sin-regreso-la-misteriosa-ruta-que-termino-con-varios-hombres-asesinados-en-distintos-municipios-de-antioquia\/\">El viaje sin regreso: la misteriosa ruta que termin\u00f3 con varios hombres asesinados en distintos municipios de Antioquia<\/a>\r\n            <\/h3>\r\n\t\t\t                <div class=\"grid-post-box-meta mag-meta\">\r\n\t\t\t\t\t\t\t\t\t\t                        <span class=\"featc-date\"><time class=\"entry-date published\" datetime=\"2026-07-09T10:37:35-05:00\">julio 9, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">by <a class=\"url fn n\" href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2026-07-09T10:37:35-05:00\">julio 9, 2026<\/time>\t\t<\/div>\n\t\t    <\/div>\r\n<\/div>\r\n\r\n<div class=\"mag-post-box hentry\">\r\n    <div class=\"magcat-thumb\">\r\n\t\t\t\t            <a class=\"penci-image-holder penci-lazy small-fix-size\"\r\n               data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/740881013_1011513078407653_5440553282796469660_n-585x390.jpg\"\r\n               href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-mujer-salio-a-caminar-con-su-suegra-y-fueron-embestidas-por-una-camioneta-la-familia-de-la-joven-que-murio-atropellada-en-la-via-niquia-girardota-busca-al-conductor-que-huyo\/\" title=\"Una mujer sali\u00f3 a caminar con su suegra y fueron embestidas por una camioneta; la Familia de la joven que muri\u00f3 atropellada en la v\u00eda Niqu\u00eda-Girardota busca al conductor que huy\u00f3\u2026\">\r\n            <\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t    <\/div>\r\n    <div class=\"magcat-detail\">\r\n\t\t            <h3 class=\"magcat-titlte entry-title\"><a\r\n                        href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-mujer-salio-a-caminar-con-su-suegra-y-fueron-embestidas-por-una-camioneta-la-familia-de-la-joven-que-murio-atropellada-en-la-via-niquia-girardota-busca-al-conductor-que-huyo\/\">Una mujer sali\u00f3 a caminar con su suegra y fueron embestidas por una camioneta; la Familia de la joven que muri\u00f3 atropellada en la v\u00eda Niqu\u00eda-Girardota busca al conductor que huy\u00f3\u2026<\/a>\r\n            <\/h3>\r\n\t\t\t                <div class=\"grid-post-box-meta mag-meta\">\r\n\t\t\t\t\t\t\t\t\t\t                        <span class=\"featc-date\"><time class=\"entry-date published\" datetime=\"2026-07-09T10:21:31-05:00\">julio 9, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">by <a class=\"url fn n\" href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2026-07-09T10:21:31-05:00\">julio 9, 2026<\/time>\t\t<\/div>\n\t\t    <\/div>\r\n<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                            <\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\r\n                        <\/div>\r\n\r\n\t\t\t\t\t\t                <\/section>\r\n\t\t\t\r\n            <\/div><!-- penci-featured-cat-sc -->\r\n\t\t\t            <style>\r\n                            <\/style>\r\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-f766f3e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"f766f3e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct  elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-26e545c\" data-id=\"26e545c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-364857c elementor-widget elementor-widget-html\" data-id=\"364857c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div style='text-align: center;'><a style='display: inline-block; max-width: 728px;' href='https:\/\/1.envato.market\/YYJ4P' target='_blank'><img src='https:\/\/soledaddemo.pencidesign.net\/wp-content\/uploads\/2021\/08\/banner-home.jpg' width='728' height='90' alt='banner'><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"penci-section penci-enSticky penci-structure-22 elementor-section elementor-top-section elementor-element elementor-element-3c308e7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3c308e7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"penci-ercol-66 penci-ercol-order-1 penci-sticky-ct  elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-402ac69\" data-id=\"402ac69\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ee679f0 elementor-widget elementor-widget-penci-latest-posts\" data-id=\"ee679f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"penci-latest-posts.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t                <div id=\"pencilatest_posts_1252\" class=\"penci-latest-posts-sc penci-latest-posts-list penci-latest-posts-el penci-el-mixed-s1 penci-std-continue-center penci-std-excerpt-center penci-grid-excerpt-left\">\r\n\t\t\t\t\t\t\t\t\t\t\t                        <div class=\"penci-border-arrow penci-homepage-title penci-home-latest-posts style-13 pcalign-center pciconp-right pcicon-right\">\r\n                            <h3 class=\"inner-arrow\">\r\n                                <span>\r\n\t\t\t\t\t\t\t\tLatest Posts                                <\/span>\r\n                            <\/h3>\r\n\t\t\t\t\t\t\t                        <\/div>\r\n\t\t\t\t\t                    <div class=\"penci-wrapper-posts-ajax\">\r\n\r\n                        <div class=\"penci-wrapper-posts-content pwid-default\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <ul class=\"penci-wrapper-data penci-grid penci-shortcode-render\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t    <li class=\"list-post penci-item-listp\">\r\n        <article id=\"post-16876\" class=\"item hentry\">\r\n\t\t\t                <div class=\"thumbnail\">\r\n\t\t\t\t\t\r\n\t\t\t\t\t                        <a class=\"penci-image-holder penci-lazy\"                           data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/742254221_1057317513437214_5211492233948717152_n-585x390.jpg\"\r\n                           href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/sintio-un-extrano-olor-abrio-el-capo-y-su-carro-termino-envuelto-en-llamas-en-las-palmas-medellin-sin-embargo-varios-conductores-se-bajaron-y-le-facilitaron-el-extintor\/\"\r\n                           title=\"Sinti\u00f3 un extra\u00f1o olor, abri\u00f3 el cap\u00f3 y su carro termin\u00f3 envuelto en llamas en Las Palmas, Medell\u00edn; sin embargo, varios conductores se bajaron y le facilitaron el extintor\">\r\n                        <\/a>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <\/div>\r\n\t\t\t\r\n            <div class=\"content-list-right content-list-center\">\r\n                <div class=\"header-list-style\">\r\n\t\t\t\t\t                        <span class=\"cat\"><a class=\"penci-cat-name penci-cat-45\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/movilidad\/accidentes\/\"  rel=\"category tag\">Accidentes<\/a><a class=\"penci-cat-name penci-cat-44\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/movilidad\/\"  rel=\"category tag\">Movilidad<\/a><a class=\"penci-cat-name penci-cat-16\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/municipios\/\"  rel=\"category tag\">Municipios<\/a><a class=\"penci-cat-name penci-cat-1\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/noticias\/\"  rel=\"category tag\">Noticias<\/a><a class=\"penci-cat-name penci-cat-47\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/\"  rel=\"category tag\">Orden Publico<\/a><a class=\"penci-cat-name penci-cat-46\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/redes-sociales\/\"  rel=\"category tag\">Redes Sociales<\/a><\/span>\r\n\t\t\t\t\t\r\n                    <h2 class=\"penci-entry-title entry-title grid-title\"><a\r\n                                href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/sintio-un-extrano-olor-abrio-el-capo-y-su-carro-termino-envuelto-en-llamas-en-las-palmas-medellin-sin-embargo-varios-conductores-se-bajaron-y-le-facilitaron-el-extintor\/\">Sinti\u00f3 un extra\u00f1o olor, abri\u00f3 el cap\u00f3 y su carro termin\u00f3 envuelto en llamas en Las Palmas, Medell\u00edn; sin embargo, varios conductores se bajaron y le facilitaron el extintor<\/a>\r\n                    <\/h2>\r\n\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">by <a class=\"url fn n\" href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2026-07-10T10:45:40-05:00\">julio 10, 2026<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                        <div class=\"grid-post-box-meta\">\r\n\t\t\t\t\t\t\t                                <span class=\"otherl-date-author author-italic author vcard\">by <a\r\n                                            class=\"url fn n\"\r\n                                            href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2026-07-10T10:45:40-05:00\">julio 10, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n\r\n\t\t\t\t                    <div class=\"item-content entry-content\">\r\n\t\t\t\t\t\t<p>Prensapaisa.com La ma\u00f1ana de este viernes comenz\u00f3 con largas filas de veh\u00edculos sobre la avenida Las Palmas, una de las principales v\u00edas de ingreso a &#8230;<\/p>\n                    <\/div>\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t            <\/div>\r\n\r\n        <\/article>\r\n    <\/li>\r\n    <li class=\"list-post penci-item-listp\">\r\n        <article id=\"post-16866\" class=\"item hentry\">\r\n\t\t\t                <div class=\"thumbnail\">\r\n\t\t\t\t\t\r\n\t\t\t\t\t                        <a class=\"penci-image-holder penci-lazy\"                           data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/742129508_1072133355381651_3020601880222902570_n-585x390.jpg\"\r\n                           href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/juez-ordena-a-congresista-yulieth-sanchez-rectificar-senalamientos-contra-dona-gloria-lider-politica-de-bello-antioquia\/\"\r\n                           title=\"Juez ordena a congresista Yulieth S\u00e1nchez rectificar se\u00f1alamientos contra do\u00f1a Gloria, l\u00edder pol\u00edtica de Bello, Antioquia\">\r\n                        <\/a>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <\/div>\r\n\t\t\t\r\n            <div class=\"content-list-right content-list-center\">\r\n                <div class=\"header-list-style\">\r\n\t\t\t\t\t                        <span class=\"cat\"><a class=\"penci-cat-name penci-cat-49\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/capturas\/\"  rel=\"category tag\">Capturas<\/a><a class=\"penci-cat-name penci-cat-50\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/denuncias\/\"  rel=\"category tag\">Denuncias<\/a><a class=\"penci-cat-name penci-cat-48\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/hurtos\/\"  rel=\"category tag\">Hurtos<\/a><a class=\"penci-cat-name penci-cat-16\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/municipios\/\"  rel=\"category tag\">Municipios<\/a><a class=\"penci-cat-name penci-cat-1\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/noticias\/\"  rel=\"category tag\">Noticias<\/a><a class=\"penci-cat-name penci-cat-47\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/\"  rel=\"category tag\">Orden Publico<\/a><a class=\"penci-cat-name penci-cat-46\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/redes-sociales\/\"  rel=\"category tag\">Redes Sociales<\/a><\/span>\r\n\t\t\t\t\t\r\n                    <h2 class=\"penci-entry-title entry-title grid-title\"><a\r\n                                href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/10\/juez-ordena-a-congresista-yulieth-sanchez-rectificar-senalamientos-contra-dona-gloria-lider-politica-de-bello-antioquia\/\">Juez ordena a congresista Yulieth S\u00e1nchez rectificar se\u00f1alamientos contra do\u00f1a Gloria, l\u00edder pol\u00edtica de Bello, Antioquia<\/a>\r\n                    <\/h2>\r\n\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">by <a class=\"url fn n\" href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2026-07-10T10:28:03-05:00\">julio 10, 2026<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                        <div class=\"grid-post-box-meta\">\r\n\t\t\t\t\t\t\t                                <span class=\"otherl-date-author author-italic author vcard\">by <a\r\n                                            class=\"url fn n\"\r\n                                            href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2026-07-10T10:28:03-05:00\">julio 10, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n\r\n\t\t\t\t                    <div class=\"item-content entry-content\">\r\n\t\t\t\t\t\t<p>Prensapaisa.com Una controversia pol\u00edtica que comenz\u00f3 durante los escrutinios de las elecciones legislativas termin\u00f3 en los estrados judiciales. Un juez orden\u00f3 a la representante a &#8230;<\/p>\n                    <\/div>\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t            <\/div>\r\n\r\n        <\/article>\r\n    <\/li>\r\n    <li class=\"list-post penci-item-listp\">\r\n        <article id=\"post-16861\" class=\"item hentry\">\r\n\t\t\t                <div class=\"thumbnail\">\r\n\t\t\t\t\t\r\n\t\t\t\t\t                        <a class=\"penci-image-holder penci-lazy\"                           data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/741196587_1071902635404723_3685621252934489457_n-585x390.jpg\"\r\n                           href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-vecina-alerto-al-123-y-desato-el-operativo-que-termino-con-varios-jovenes-capturados-por-secuestro-en-robledo-medellin\/\"\r\n                           title=\"Una vecina alert\u00f3 al 123 y desat\u00f3 el operativo que termin\u00f3 con varios j\u00f3venes capturados por secuestro en Robledo, Medell\u00edn\">\r\n                        <\/a>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <\/div>\r\n\t\t\t\r\n            <div class=\"content-list-right content-list-center\">\r\n                <div class=\"header-list-style\">\r\n\t\t\t\t\t                        <span class=\"cat\"><a class=\"penci-cat-name penci-cat-49\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/capturas\/\"  rel=\"category tag\">Capturas<\/a><a class=\"penci-cat-name penci-cat-50\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/denuncias\/\"  rel=\"category tag\">Denuncias<\/a><a class=\"penci-cat-name penci-cat-48\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/hurtos\/\"  rel=\"category tag\">Hurtos<\/a><a class=\"penci-cat-name penci-cat-16\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/municipios\/\"  rel=\"category tag\">Municipios<\/a><a class=\"penci-cat-name penci-cat-1\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/noticias\/\"  rel=\"category tag\">Noticias<\/a><a class=\"penci-cat-name penci-cat-47\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/\"  rel=\"category tag\">Orden Publico<\/a><a class=\"penci-cat-name penci-cat-46\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/redes-sociales\/\"  rel=\"category tag\">Redes Sociales<\/a><\/span>\r\n\t\t\t\t\t\r\n                    <h2 class=\"penci-entry-title entry-title grid-title\"><a\r\n                                href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-vecina-alerto-al-123-y-desato-el-operativo-que-termino-con-varios-jovenes-capturados-por-secuestro-en-robledo-medellin\/\">Una vecina alert\u00f3 al 123 y desat\u00f3 el operativo que termin\u00f3 con varios j\u00f3venes capturados por secuestro en Robledo, Medell\u00edn<\/a>\r\n                    <\/h2>\r\n\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">by <a class=\"url fn n\" href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2026-07-09T11:13:37-05:00\">julio 9, 2026<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                        <div class=\"grid-post-box-meta\">\r\n\t\t\t\t\t\t\t                                <span class=\"otherl-date-author author-italic author vcard\">by <a\r\n                                            class=\"url fn n\"\r\n                                            href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2026-07-09T11:13:37-05:00\">julio 9, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n\r\n\t\t\t\t                    <div class=\"item-content entry-content\">\r\n\t\t\t\t\t\t<p>Prensapaisa.com En Robledo, Comuna 7, los techos suelen servir para tender ropa, conversar con los vecinos o contemplar el atardecer sobre las monta\u00f1as de Medell\u00edn. &#8230;<\/p>\n                    <\/div>\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t            <\/div>\r\n\r\n        <\/article>\r\n    <\/li>\r\n    <li class=\"list-post penci-item-listp\">\r\n        <article id=\"post-16858\" class=\"item hentry\">\r\n\t\t\t                <div class=\"thumbnail\">\r\n\t\t\t\t\t\r\n\t\t\t\t\t                        <a class=\"penci-image-holder penci-lazy\"                           data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/740628751_1012735958165830_7922623203508311772_n-585x390.jpg\"\r\n                           href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/cayeron-los-cazadores-de-cadenas-de-oro-capturan-a-dos-presuntos-atracadores-vinculados-a-cinco-violentos-robos-en-medellin\/\"\r\n                           title=\"\u00a1Cayeron los cazadores de cadenas de oro! Capturan a dos presuntos atracadores vinculados a cinco violentos robos en Medell\u00edn\">\r\n                        <\/a>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <\/div>\r\n\t\t\t\r\n            <div class=\"content-list-right content-list-center\">\r\n                <div class=\"header-list-style\">\r\n\t\t\t\t\t                        <span class=\"cat\"><a class=\"penci-cat-name penci-cat-49\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/capturas\/\"  rel=\"category tag\">Capturas<\/a><a class=\"penci-cat-name penci-cat-50\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/denuncias\/\"  rel=\"category tag\">Denuncias<\/a><a class=\"penci-cat-name penci-cat-48\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/hurtos\/\"  rel=\"category tag\">Hurtos<\/a><a class=\"penci-cat-name penci-cat-16\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/municipios\/\"  rel=\"category tag\">Municipios<\/a><a class=\"penci-cat-name penci-cat-1\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/noticias\/\"  rel=\"category tag\">Noticias<\/a><a class=\"penci-cat-name penci-cat-47\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/\"  rel=\"category tag\">Orden Publico<\/a><a class=\"penci-cat-name penci-cat-46\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/redes-sociales\/\"  rel=\"category tag\">Redes Sociales<\/a><\/span>\r\n\t\t\t\t\t\r\n                    <h2 class=\"penci-entry-title entry-title grid-title\"><a\r\n                                href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/cayeron-los-cazadores-de-cadenas-de-oro-capturan-a-dos-presuntos-atracadores-vinculados-a-cinco-violentos-robos-en-medellin\/\">\u00a1Cayeron los cazadores de cadenas de oro! Capturan a dos presuntos atracadores vinculados a cinco violentos robos en Medell\u00edn<\/a>\r\n                    <\/h2>\r\n\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">by <a class=\"url fn n\" href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2026-07-09T10:38:44-05:00\">julio 9, 2026<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                        <div class=\"grid-post-box-meta\">\r\n\t\t\t\t\t\t\t                                <span class=\"otherl-date-author author-italic author vcard\">by <a\r\n                                            class=\"url fn n\"\r\n                                            href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2026-07-09T10:38:44-05:00\">julio 9, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n\r\n\t\t\t\t                    <div class=\"item-content entry-content\">\r\n\t\t\t\t\t\t<p>Prensapaisa.com Antes de salir a atacar, al parecer estudiaban a sus v\u00edctimas. Bastaba ver una cadena de oro, un reloj costoso o una persona desprevenida &#8230;<\/p>\n                    <\/div>\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t            <\/div>\r\n\r\n        <\/article>\r\n    <\/li>\r\n    <li class=\"list-post penci-item-listp\">\r\n        <article id=\"post-16851\" class=\"item hentry\">\r\n\t\t\t                <div class=\"thumbnail\">\r\n\t\t\t\t\t\r\n\t\t\t\t\t                        <a class=\"penci-image-holder penci-lazy\"                           data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/740601678_975972272103281_2887798897915239700_n-1-585x390.jpg\"\r\n                           href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/el-viaje-sin-regreso-la-misteriosa-ruta-que-termino-con-varios-hombres-asesinados-en-distintos-municipios-de-antioquia\/\"\r\n                           title=\"El viaje sin regreso: la misteriosa ruta que termin\u00f3 con varios hombres asesinados en distintos municipios de Antioquia\">\r\n                        <\/a>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <\/div>\r\n\t\t\t\r\n            <div class=\"content-list-right content-list-center\">\r\n                <div class=\"header-list-style\">\r\n\t\t\t\t\t                        <span class=\"cat\"><a class=\"penci-cat-name penci-cat-49\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/capturas\/\"  rel=\"category tag\">Capturas<\/a><a class=\"penci-cat-name penci-cat-50\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/denuncias\/\"  rel=\"category tag\">Denuncias<\/a><a class=\"penci-cat-name penci-cat-48\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/hurtos\/\"  rel=\"category tag\">Hurtos<\/a><a class=\"penci-cat-name penci-cat-16\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/municipios\/\"  rel=\"category tag\">Municipios<\/a><a class=\"penci-cat-name penci-cat-1\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/noticias\/\"  rel=\"category tag\">Noticias<\/a><a class=\"penci-cat-name penci-cat-47\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/\"  rel=\"category tag\">Orden Publico<\/a><a class=\"penci-cat-name penci-cat-46\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/redes-sociales\/\"  rel=\"category tag\">Redes Sociales<\/a><\/span>\r\n\t\t\t\t\t\r\n                    <h2 class=\"penci-entry-title entry-title grid-title\"><a\r\n                                href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/el-viaje-sin-regreso-la-misteriosa-ruta-que-termino-con-varios-hombres-asesinados-en-distintos-municipios-de-antioquia\/\">El viaje sin regreso: la misteriosa ruta que termin\u00f3 con varios hombres asesinados en distintos municipios de Antioquia<\/a>\r\n                    <\/h2>\r\n\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">by <a class=\"url fn n\" href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2026-07-09T10:37:35-05:00\">julio 9, 2026<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                        <div class=\"grid-post-box-meta\">\r\n\t\t\t\t\t\t\t                                <span class=\"otherl-date-author author-italic author vcard\">by <a\r\n                                            class=\"url fn n\"\r\n                                            href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2026-07-09T10:37:35-05:00\">julio 9, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n\r\n\t\t\t\t                    <div class=\"item-content entry-content\">\r\n\t\t\t\t\t\t<p>Prensapaisa.com Hay historias que comienzan como cualquier otra salida entre conocidos y terminan convirti\u00e9ndose en un rompecabezas para las autoridades. Esta es una de ellas. &#8230;<\/p>\n                    <\/div>\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t            <\/div>\r\n\r\n        <\/article>\r\n    <\/li>\r\n    <li class=\"list-post penci-item-listp\">\r\n        <article id=\"post-16840\" class=\"item hentry\">\r\n\t\t\t                <div class=\"thumbnail\">\r\n\t\t\t\t\t\r\n\t\t\t\t\t                        <a class=\"penci-image-holder penci-lazy\"                           data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/740881013_1011513078407653_5440553282796469660_n-585x390.jpg\"\r\n                           href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-mujer-salio-a-caminar-con-su-suegra-y-fueron-embestidas-por-una-camioneta-la-familia-de-la-joven-que-murio-atropellada-en-la-via-niquia-girardota-busca-al-conductor-que-huyo\/\"\r\n                           title=\"Una mujer sali\u00f3 a caminar con su suegra y fueron embestidas por una camioneta; la Familia de la joven que muri\u00f3 atropellada en la v\u00eda Niqu\u00eda-Girardota busca al conductor que huy\u00f3\u2026\">\r\n                        <\/a>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <\/div>\r\n\t\t\t\r\n            <div class=\"content-list-right content-list-center\">\r\n                <div class=\"header-list-style\">\r\n\t\t\t\t\t                        <span class=\"cat\"><a class=\"penci-cat-name penci-cat-45\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/movilidad\/accidentes\/\"  rel=\"category tag\">Accidentes<\/a><a class=\"penci-cat-name penci-cat-50\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/denuncias\/\"  rel=\"category tag\">Denuncias<\/a><a class=\"penci-cat-name penci-cat-43\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/fallecidos\/\"  rel=\"category tag\">Fallecidos<\/a><a class=\"penci-cat-name penci-cat-44\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/movilidad\/\"  rel=\"category tag\">Movilidad<\/a><a class=\"penci-cat-name penci-cat-16\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/municipios\/\"  rel=\"category tag\">Municipios<\/a><a class=\"penci-cat-name penci-cat-1\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/noticias\/\"  rel=\"category tag\">Noticias<\/a><a class=\"penci-cat-name penci-cat-47\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/\"  rel=\"category tag\">Orden Publico<\/a><a class=\"penci-cat-name penci-cat-46\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/redes-sociales\/\"  rel=\"category tag\">Redes Sociales<\/a><\/span>\r\n\t\t\t\t\t\r\n                    <h2 class=\"penci-entry-title entry-title grid-title\"><a\r\n                                href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/una-mujer-salio-a-caminar-con-su-suegra-y-fueron-embestidas-por-una-camioneta-la-familia-de-la-joven-que-murio-atropellada-en-la-via-niquia-girardota-busca-al-conductor-que-huyo\/\">Una mujer sali\u00f3 a caminar con su suegra y fueron embestidas por una camioneta; la Familia de la joven que muri\u00f3 atropellada en la v\u00eda Niqu\u00eda-Girardota busca al conductor que huy\u00f3\u2026<\/a>\r\n                    <\/h2>\r\n\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">by <a class=\"url fn n\" href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2026-07-09T10:21:31-05:00\">julio 9, 2026<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                        <div class=\"grid-post-box-meta\">\r\n\t\t\t\t\t\t\t                                <span class=\"otherl-date-author author-italic author vcard\">by <a\r\n                                            class=\"url fn n\"\r\n                                            href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2026-07-09T10:21:31-05:00\">julio 9, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n\r\n\t\t\t\t                    <div class=\"item-content entry-content\">\r\n\t\t\t\t\t\t<p>Prensapaisa.com La muerte de Geraldin Vanegas tiene hoy a una familia sumida en el dolor y pidiendo ayuda para esclarecer lo ocurrido. La joven falleci\u00f3 &#8230;<\/p>\n                    <\/div>\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t            <\/div>\r\n\r\n        <\/article>\r\n    <\/li>\r\n    <li class=\"list-post penci-item-listp\">\r\n        <article id=\"post-16837\" class=\"item hentry\">\r\n\t\t\t                <div class=\"thumbnail\">\r\n\t\t\t\t\t\r\n\t\t\t\t\t                        <a class=\"penci-image-holder penci-lazy\"                           data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/740052309_2263742807732861_3568277186871209413_n-585x390.jpg\"\r\n                           href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/megaoperativo-golpeo-una-de-las-estructuras-senaladas-de-inundar-de-drogas-las-calles-de-envigado\/\"\r\n                           title=\"Megaoperativo golpe\u00f3 una de las estructuras se\u00f1aladas de inundar de drogas las calles de Envigado\">\r\n                        <\/a>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <\/div>\r\n\t\t\t\r\n            <div class=\"content-list-right content-list-center\">\r\n                <div class=\"header-list-style\">\r\n\t\t\t\t\t                        <span class=\"cat\"><a class=\"penci-cat-name penci-cat-49\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/capturas\/\"  rel=\"category tag\">Capturas<\/a><a class=\"penci-cat-name penci-cat-50\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/denuncias\/\"  rel=\"category tag\">Denuncias<\/a><a class=\"penci-cat-name penci-cat-48\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/hurtos\/\"  rel=\"category tag\">Hurtos<\/a><a class=\"penci-cat-name penci-cat-16\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/municipios\/\"  rel=\"category tag\">Municipios<\/a><a class=\"penci-cat-name penci-cat-1\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/noticias\/\"  rel=\"category tag\">Noticias<\/a><a class=\"penci-cat-name penci-cat-47\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/\"  rel=\"category tag\">Orden Publico<\/a><a class=\"penci-cat-name penci-cat-46\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/redes-sociales\/\"  rel=\"category tag\">Redes Sociales<\/a><\/span>\r\n\t\t\t\t\t\r\n                    <h2 class=\"penci-entry-title entry-title grid-title\"><a\r\n                                href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/megaoperativo-golpeo-una-de-las-estructuras-senaladas-de-inundar-de-drogas-las-calles-de-envigado\/\">Megaoperativo golpe\u00f3 una de las estructuras se\u00f1aladas de inundar de drogas las calles de Envigado<\/a>\r\n                    <\/h2>\r\n\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">by <a class=\"url fn n\" href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2026-07-09T10:16:48-05:00\">julio 9, 2026<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                        <div class=\"grid-post-box-meta\">\r\n\t\t\t\t\t\t\t                                <span class=\"otherl-date-author author-italic author vcard\">by <a\r\n                                            class=\"url fn n\"\r\n                                            href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2026-07-09T10:16:48-05:00\">julio 9, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n\r\n\t\t\t\t                    <div class=\"item-content entry-content\">\r\n\t\t\t\t\t\t<p>Prensapaisa.com Durante diez meses, investigadores de la Polic\u00eda Nacional siguieron cada movimiento de una organizaci\u00f3n que, seg\u00fan las autoridades, hab\u00eda convertido varios sectores de Envigado &#8230;<\/p>\n                    <\/div>\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t            <\/div>\r\n\r\n        <\/article>\r\n    <\/li>\r\n    <li class=\"list-post penci-item-listp\">\r\n        <article id=\"post-16830\" class=\"item hentry\">\r\n\t\t\t                <div class=\"thumbnail\">\r\n\t\t\t\t\t\r\n\t\t\t\t\t                        <a class=\"penci-image-holder penci-lazy\"                           data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/07\/742011440_2296078977933479_7457297837941194987_n-585x390.jpg\"\r\n                           href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/un-paisa-ofrece-una-jugosa-recompensa-para-quien-le-informe-donde-esta-su-vehiculo-hurtado\/\"\r\n                           title=\"Un paisa ofrece una jugosa recompensa para quien le informe d\u00f3nde est\u00e1 su veh\u00edculo hurtado\">\r\n                        <\/a>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <\/div>\r\n\t\t\t\r\n            <div class=\"content-list-right content-list-center\">\r\n                <div class=\"header-list-style\">\r\n\t\t\t\t\t                        <span class=\"cat\"><a class=\"penci-cat-name penci-cat-49\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/capturas\/\"  rel=\"category tag\">Capturas<\/a><a class=\"penci-cat-name penci-cat-50\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/denuncias\/\"  rel=\"category tag\">Denuncias<\/a><a class=\"penci-cat-name penci-cat-48\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/hurtos\/\"  rel=\"category tag\">Hurtos<\/a><a class=\"penci-cat-name penci-cat-16\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/municipios\/\"  rel=\"category tag\">Municipios<\/a><a class=\"penci-cat-name penci-cat-1\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/noticias\/\"  rel=\"category tag\">Noticias<\/a><a class=\"penci-cat-name penci-cat-47\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/\"  rel=\"category tag\">Orden Publico<\/a><a class=\"penci-cat-name penci-cat-46\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/redes-sociales\/\"  rel=\"category tag\">Redes Sociales<\/a><\/span>\r\n\t\t\t\t\t\r\n                    <h2 class=\"penci-entry-title entry-title grid-title\"><a\r\n                                href=\"https:\/\/prensapaisa.com\/index.php\/2026\/07\/09\/un-paisa-ofrece-una-jugosa-recompensa-para-quien-le-informe-donde-esta-su-vehiculo-hurtado\/\">Un paisa ofrece una jugosa recompensa para quien le informe d\u00f3nde est\u00e1 su veh\u00edculo hurtado<\/a>\r\n                    <\/h2>\r\n\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">by <a class=\"url fn n\" href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2026-07-09T10:15:43-05:00\">julio 9, 2026<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                        <div class=\"grid-post-box-meta\">\r\n\t\t\t\t\t\t\t                                <span class=\"otherl-date-author author-italic author vcard\">by <a\r\n                                            class=\"url fn n\"\r\n                                            href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2026-07-09T10:15:43-05:00\">julio 9, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n\r\n\t\t\t\t                    <div class=\"item-content entry-content\">\r\n\t\t\t\t\t\t<p>Prensapaisa.com El d\u00eda lunes festivo 29 de junio, aproximadamente a las 6:00 p. m., fue hurtada una Kia Sportage, placas IST-131, en el sector de &#8230;<\/p>\n                    <\/div>\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t            <\/div>\r\n\r\n        <\/article>\r\n    <\/li>\r\n    <li class=\"list-post penci-item-listp\">\r\n        <article id=\"post-16824\" class=\"item hentry\">\r\n\t\t\t                <div class=\"thumbnail\">\r\n\t\t\t\t\t\r\n\t\t\t\t\t                        <a class=\"penci-image-holder penci-lazy\"                           data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/06\/Captura-de-pantalla-2026-06-24-231125.jpg\"\r\n                           href=\"https:\/\/prensapaisa.com\/index.php\/2026\/06\/24\/golpe-a-la-delincuencia-robo-de-motocicletas-se-desploma-en-villa-hermosa-medellin\/\"\r\n                           title=\"Golpe a la delincuencia: robo de motocicletas se desploma en Villa Hermosa, Medell\u00edn\">\r\n                        <\/a>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <\/div>\r\n\t\t\t\r\n            <div class=\"content-list-right content-list-center\">\r\n                <div class=\"header-list-style\">\r\n\t\t\t\t\t                        <span class=\"cat\"><a class=\"penci-cat-name penci-cat-49\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/capturas\/\"  rel=\"category tag\">Capturas<\/a><a class=\"penci-cat-name penci-cat-50\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/denuncias\/\"  rel=\"category tag\">Denuncias<\/a><a class=\"penci-cat-name penci-cat-48\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/hurtos\/\"  rel=\"category tag\">Hurtos<\/a><a class=\"penci-cat-name penci-cat-16\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/municipios\/\"  rel=\"category tag\">Municipios<\/a><a class=\"penci-cat-name penci-cat-1\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/noticias\/\"  rel=\"category tag\">Noticias<\/a><a class=\"penci-cat-name penci-cat-47\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/\"  rel=\"category tag\">Orden Publico<\/a><a class=\"penci-cat-name penci-cat-46\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/redes-sociales\/\"  rel=\"category tag\">Redes Sociales<\/a><\/span>\r\n\t\t\t\t\t\r\n                    <h2 class=\"penci-entry-title entry-title grid-title\"><a\r\n                                href=\"https:\/\/prensapaisa.com\/index.php\/2026\/06\/24\/golpe-a-la-delincuencia-robo-de-motocicletas-se-desploma-en-villa-hermosa-medellin\/\">Golpe a la delincuencia: robo de motocicletas se desploma en Villa Hermosa, Medell\u00edn<\/a>\r\n                    <\/h2>\r\n\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">by <a class=\"url fn n\" href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2026-06-24T23:15:23-05:00\">junio 24, 2026<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                        <div class=\"grid-post-box-meta\">\r\n\t\t\t\t\t\t\t                                <span class=\"otherl-date-author author-italic author vcard\">by <a\r\n                                            class=\"url fn n\"\r\n                                            href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2026-06-24T23:15:23-05:00\">junio 24, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n\r\n\t\t\t\t                    <div class=\"item-content entry-content\">\r\n\t\t\t\t\t\t<p>Prensapaisa.com En Villa Hermosa, Medell\u00edn, hay algo que poco a poco se vuelve m\u00e1s frecuente entre los vecinos: escuchar menos historias de robos y m\u00e1s &#8230;<\/p>\n                    <\/div>\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t            <\/div>\r\n\r\n        <\/article>\r\n    <\/li>\r\n    <li class=\"list-post penci-item-listp\">\r\n        <article id=\"post-16821\" class=\"item hentry\">\r\n\t\t\t                <div class=\"thumbnail\">\r\n\t\t\t\t\t\r\n\t\t\t\t\t                        <a class=\"penci-image-holder penci-lazy\"                           data-bgset=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2026\/06\/Captura-de-pantalla-2026-06-24-230825.jpg\"\r\n                           href=\"https:\/\/prensapaisa.com\/index.php\/2026\/06\/24\/entre-cambuches-basuras-y-andenes-ocupados-asi-siguen-recuperando-el-centro-de-medellin\/\"\r\n                           title=\"Entre cambuches, basuras y andenes ocupados: as\u00ed siguen recuperando el centro de Medell\u00edn\">\r\n                        <\/a>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                <\/div>\r\n\t\t\t\r\n            <div class=\"content-list-right content-list-center\">\r\n                <div class=\"header-list-style\">\r\n\t\t\t\t\t                        <span class=\"cat\"><a class=\"penci-cat-name penci-cat-50\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/denuncias\/\"  rel=\"category tag\">Denuncias<\/a><a class=\"penci-cat-name penci-cat-44\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/movilidad\/\"  rel=\"category tag\">Movilidad<\/a><a class=\"penci-cat-name penci-cat-16\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/municipios\/\"  rel=\"category tag\">Municipios<\/a><a class=\"penci-cat-name penci-cat-1\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/noticias\/\"  rel=\"category tag\">Noticias<\/a><a class=\"penci-cat-name penci-cat-47\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/orden-publico\/\"  rel=\"category tag\">Orden Publico<\/a><a class=\"penci-cat-name penci-cat-46\" href=\"https:\/\/prensapaisa.com\/index.php\/category\/redes-sociales\/\"  rel=\"category tag\">Redes Sociales<\/a><\/span>\r\n\t\t\t\t\t\r\n                    <h2 class=\"penci-entry-title entry-title grid-title\"><a\r\n                                href=\"https:\/\/prensapaisa.com\/index.php\/2026\/06\/24\/entre-cambuches-basuras-y-andenes-ocupados-asi-siguen-recuperando-el-centro-de-medellin\/\">Entre cambuches, basuras y andenes ocupados: as\u00ed siguen recuperando el centro de Medell\u00edn<\/a>\r\n                    <\/h2>\r\n\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">by <a class=\"url fn n\" href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2026-06-24T23:09:46-05:00\">junio 24, 2026<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                        <div class=\"grid-post-box-meta\">\r\n\t\t\t\t\t\t\t                                <span class=\"otherl-date-author author-italic author vcard\">by <a\r\n                                            class=\"url fn n\"\r\n                                            href=\"https:\/\/prensapaisa.com\/index.php\/author\/prensapaisagmail-com\/\">noticias@prensapaisa.com<\/a><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2026-06-24T23:09:46-05:00\">junio 24, 2026<\/time><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                        <\/div>\r\n\t\t\t\t\t                <\/div>\r\n\r\n\t\t\t\t                    <div class=\"item-content entry-content\">\r\n\t\t\t\t\t\t<p>Prensapaisa.com Mientras miles de personas caminan a diario por las calles de La Candelaria para trabajar, estudiar o hacer diligencias, las autoridades contin\u00faan adelantando operativos &#8230;<\/p>\n                    <\/div>\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t            <\/div>\r\n\r\n        <\/article>\r\n    <\/li>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"penci-pagination align-left\"><ul class='page-numbers'>\n\t<li><span aria-current=\"page\" class=\"page-numbers current\">1<\/span><\/li>\n\t<li><a class=\"page-numbers\" href=\"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/pages\/3330\/page\/2\/\">2<\/a><\/li>\n\t<li><a class=\"page-numbers\" href=\"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/pages\/3330\/page\/3\/\">3<\/a><\/li>\n\t<li><span class=\"page-numbers dots\">&hellip;<\/span><\/li>\n\t<li><a class=\"page-numbers\" href=\"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/pages\/3330\/page\/265\/\">265<\/a><\/li>\n\t<li><a class=\"next page-numbers\" href=\"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/pages\/3330\/page\/2\/\"><i class=\"penci-faicon fa fa-angle-right\" ><\/i><\/a><\/li>\n<\/ul>\n<\/div>\t\t\t\t\t\t\t                        <\/div>\r\n\r\n\t\t\t\t\t\t                    <\/div>\r\n                <\/div>\r\n\t\t\t            <style>\r\n                                                                                                                                                                            <\/style>\r\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"penci-ercol-33 penci-ercol-order-2 penci-sticky-sb penci-sidebarSC elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c012f29\" data-id=\"c012f29\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f8fd52 elementor-widget elementor-widget-penci-sidebar\" data-id=\"6f8fd52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"penci-sidebar.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n        <div id=\"sidebar\"\r\n             class=\"penci-sidebar-content penci-sidebar-content-vc style-1 pcalign-center  pciconp-right pcicon-right\">\r\n            <div class=\"theiaStickySidebar\">\r\n\t\t\t\t\t\t\t<aside id=\"penci_videoplaylist_widget-1\" class=\"widget penci_videoplaylist_widget\">\t\t\t<h3 class=\"widget-title penci-border-arrow\"><span class=\"inner-arrow\">Trending  Tech Videos<\/span><\/h3>            <div class=\"penci-block-vc penci-video_playlist pencisc-column-1\">\r\n                <div class=\"penci-block_content\">\r\n\t\t\t\t\t<strong>Youtube Api key<\/strong> is empty. Please go to Customize > General > Extra Options > YouTube API Key and enter an api key \ud83d\ude42                <\/div>\r\n            <\/div>\r\n\t\t\t<\/aside><aside id=\"custom_html-2\" class=\"widget_text widget widget_custom_html\"><div class=\"textwidget custom-html-widget\"><\/div><\/aside>            <\/div>\r\n        <\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>News Highlight 42 Foods You Need To Eat Before You Die | The Ultimate List Fixing A Toxic Work Culture: Guarding Against The &#8216;Dark Triad&#8217; 5 Must-Visit Little Saigons In&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-fullwidth.php","meta":{"footnotes":""},"class_list":["post-3330","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Home With One Sidebar - PRENSA PAISA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prensapaisa.com\/index.php\/home-with-one-sidebar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home With One Sidebar - PRENSA PAISA\" \/>\n<meta property=\"og:description\" content=\"News Highlight 42 Foods You Need To Eat Before You Die | The Ultimate List Fixing A Toxic Work Culture: Guarding Against The &#8216;Dark Triad&#8217; 5 Must-Visit Little Saigons In&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prensapaisa.com\/index.php\/home-with-one-sidebar\/\" \/>\n<meta property=\"og:site_name\" content=\"PRENSA PAISA\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-04T19:52:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prensapaisa.com\/wp-content\/uploads\/2021\/08\/banner-home.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/home-with-one-sidebar\\\/\",\"url\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/home-with-one-sidebar\\\/\",\"name\":\"Home With One Sidebar - PRENSA PAISA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/home-with-one-sidebar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/home-with-one-sidebar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prensapaisa.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/banner-home.jpg\",\"datePublished\":\"2021-09-30T04:25:56+00:00\",\"dateModified\":\"2022-06-04T19:52:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/home-with-one-sidebar\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/home-with-one-sidebar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/home-with-one-sidebar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/prensapaisa.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/banner-home.jpg\",\"contentUrl\":\"https:\\\/\\\/prensapaisa.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/banner-home.jpg\",\"width\":1456,\"height\":180},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/index.php\\\/home-with-one-sidebar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/prensapaisa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home With One Sidebar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#website\",\"url\":\"https:\\\/\\\/prensapaisa.com\\\/\",\"name\":\"PRENSA PAISA\",\"description\":\"Prensa Paisa la Original | Noticias de Medell\u00edn, Antioquia\",\"publisher\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prensapaisa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#organization\",\"name\":\"PRENSA PAISA\",\"url\":\"https:\\\/\\\/prensapaisa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/prensapaisa.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/cropped-cropped-prensa.png\",\"contentUrl\":\"https:\\\/\\\/prensapaisa.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/cropped-cropped-prensa.png\",\"width\":784,\"height\":524,\"caption\":\"PRENSA PAISA\"},\"image\":{\"@id\":\"https:\\\/\\\/prensapaisa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Home With One Sidebar - PRENSA PAISA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prensapaisa.com\/index.php\/home-with-one-sidebar\/","og_locale":"es_ES","og_type":"article","og_title":"Home With One Sidebar - PRENSA PAISA","og_description":"News Highlight 42 Foods You Need To Eat Before You Die | The Ultimate List Fixing A Toxic Work Culture: Guarding Against The &#8216;Dark Triad&#8217; 5 Must-Visit Little Saigons In&hellip;","og_url":"https:\/\/prensapaisa.com\/index.php\/home-with-one-sidebar\/","og_site_name":"PRENSA PAISA","article_modified_time":"2022-06-04T19:52:00+00:00","og_image":[{"url":"https:\/\/prensapaisa.com\/wp-content\/uploads\/2021\/08\/banner-home.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/prensapaisa.com\/index.php\/home-with-one-sidebar\/","url":"https:\/\/prensapaisa.com\/index.php\/home-with-one-sidebar\/","name":"Home With One Sidebar - PRENSA PAISA","isPartOf":{"@id":"https:\/\/prensapaisa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prensapaisa.com\/index.php\/home-with-one-sidebar\/#primaryimage"},"image":{"@id":"https:\/\/prensapaisa.com\/index.php\/home-with-one-sidebar\/#primaryimage"},"thumbnailUrl":"https:\/\/prensapaisa.com\/wp-content\/uploads\/2021\/08\/banner-home.jpg","datePublished":"2021-09-30T04:25:56+00:00","dateModified":"2022-06-04T19:52:00+00:00","breadcrumb":{"@id":"https:\/\/prensapaisa.com\/index.php\/home-with-one-sidebar\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prensapaisa.com\/index.php\/home-with-one-sidebar\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/prensapaisa.com\/index.php\/home-with-one-sidebar\/#primaryimage","url":"https:\/\/prensapaisa.com\/wp-content\/uploads\/2021\/08\/banner-home.jpg","contentUrl":"https:\/\/prensapaisa.com\/wp-content\/uploads\/2021\/08\/banner-home.jpg","width":1456,"height":180},{"@type":"BreadcrumbList","@id":"https:\/\/prensapaisa.com\/index.php\/home-with-one-sidebar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/prensapaisa.com\/"},{"@type":"ListItem","position":2,"name":"Home With One Sidebar"}]},{"@type":"WebSite","@id":"https:\/\/prensapaisa.com\/#website","url":"https:\/\/prensapaisa.com\/","name":"PRENSA PAISA","description":"Prensa Paisa la Original | Noticias de Medell\u00edn, Antioquia","publisher":{"@id":"https:\/\/prensapaisa.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prensapaisa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/prensapaisa.com\/#organization","name":"PRENSA PAISA","url":"https:\/\/prensapaisa.com\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/prensapaisa.com\/#\/schema\/logo\/image\/","url":"https:\/\/prensapaisa.com\/wp-content\/uploads\/2022\/05\/cropped-cropped-prensa.png","contentUrl":"https:\/\/prensapaisa.com\/wp-content\/uploads\/2022\/05\/cropped-cropped-prensa.png","width":784,"height":524,"caption":"PRENSA PAISA"},"image":{"@id":"https:\/\/prensapaisa.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/pages\/3330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/comments?post=3330"}],"version-history":[{"count":1,"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/pages\/3330\/revisions"}],"predecessor-version":[{"id":3386,"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/pages\/3330\/revisions\/3386"}],"wp:attachment":[{"href":"https:\/\/prensapaisa.com\/index.php\/wp-json\/wp\/v2\/media?parent=3330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}